{"id":7634,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/tag\/aerea\/","name":"a\u00e9rea","slug":"aerea","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags\/7634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts?tags=7634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}