{"id":6969,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/tag\/ex-namorada\/","name":"ex-namorada","slug":"ex-namorada","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags\/6969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts?tags=6969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}