{"id":5640,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/tag\/129-ate-r-5\/","name":"129 at\u00e9 R$ 5","slug":"129-ate-r-5","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags\/5640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts?tags=5640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}