{"id":5044,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/tag\/ernesto-araujo-e-ricardo-salles-usam-despreparo-de-bolsonaro-para-enrola-lo\/","name":"Ernesto Ara\u00fajo e Ricardo Salles usam despreparo de Bolsonaro para enrol\u00e1-lo","slug":"ernesto-araujo-e-ricardo-salles-usam-despreparo-de-bolsonaro-para-enrola-lo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags\/5044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts?tags=5044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}