{"id":29668,"date":"2024-01-26T09:10:46","date_gmt":"2024-01-26T12:10:46","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/?p=29668"},"modified":"2024-01-26T15:30:00","modified_gmt":"2024-01-26T18:30:00","slug":"ipca-15-previa-da-inflacao-avanca-031-em-janeiro-puxada-por-alimentos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/ipca-15-previa-da-inflacao-avanca-031-em-janeiro-puxada-por-alimentos\/","title":{"rendered":"IPCA-15: Pr\u00e9via da infla\u00e7\u00e3o avan\u00e7a 0,31%, em janeiro, puxada por alimentos"},"content":{"rendered":"<p>ROSANA HESSEL<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">O \u00cdndice de Pre\u00e7os ao Consumidor Amplo 15 (IPCA-15), conhecido como pr\u00e9via da infla\u00e7\u00e3o oficial, registrou alta de 0,31%, em janeiro, conforme dados do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) divulgados nesta sexta-feira (26\/1).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>O dado ficou abaixo das estimativas do mercado (em torno de 0,50%) e desacelerou em rela\u00e7\u00e3o \u00e0 taxa de 0,40% de dezembro, ficando 0,09 ponto percentual a menos.\u00a0 Nos 12 meses encerrados em janeiro a varia\u00e7\u00e3o do IPCA-15 foi de 4,47%, tamb\u00e9m abaixo dos 4,72% contabilizados no mesmo per\u00edodo imediatamente anterior.\u00a0 Em 2023, o indicador registrou alta de 0,55% no primeiro m\u00eas do ano.<\/p>\n<p>&nbsp;<\/p>\n<p>Apesar da desacelera\u00e7\u00e3o do IPCA-15, de acordo com os dados do IBGE, sete dos nove grupos de produtos e servi\u00e7os pesquisados\u00a0 registraram alta em janeiro. A maior varia\u00e7\u00e3o veio do grupo Alimenta\u00e7\u00e3o e bebidas, de 1,53%, que teve um impacto maior do que a varia\u00e7\u00e3o do indicador, de 0,32 ponto percentual. J\u00e1 o grupo de transportes, registrou queda de 1,13% e contribuiu para um impacto negativo de 0,24 ponto percentual, ajudando na desacelera\u00e7\u00e3o do indicador de carestia no m\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Conforme os dados do IBGE, o custo da alimenta\u00e7\u00e3o no domic\u00edlio subiu <\/span>2,04%, <span style=\"font-weight: 400\">em janeiro, com destaque para o aumento da batata-inglesa (de 25,95%), do tomate (de 11,19%), do arroz (de 5,85%), das frutas (de 5,45%) e das carnes (de 0,94%). J\u00e1 a <\/span>alimenta\u00e7\u00e3o fora do domic\u00edlio<span style=\"font-weight: 400\">\u00a0desacelerou em rela\u00e7\u00e3o ao m\u00eas de dezembro (0,53%) e registrou alta de 0,24%.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Na avalia\u00e7\u00e3o do economista e consultor Andr\u00e9 Perfeito, o IPCA-15 de janeiro surpreendeu e veio &#8220;bem abaixo&#8221; das estimativas dos economistas.\u00a0 &#8220;O resultado foi fortemente influenciado pela queda do grupo transportes, que recuou 1,13%, puxado por recuo de pre\u00e7os de passagens a\u00e9reas e combust\u00edveis. No entanto, o grupo alimenta\u00e7\u00e3o apresentou alta expressiva saindo de 0,54% em dezembro para 1,53% agora&#8221;, destacou.<\/p>\n<p>&nbsp;<\/p>\n<p>Contudo, ressaltou que, apesar da surpresa benigna, o dado da infla\u00e7\u00e3o &#8220;inspira certo cuidado uma vez que no caso de transportes as quedas tendem a ser limitadas at\u00e9 pela defasagem atual da gasolina em rela\u00e7\u00e3o aos pre\u00e7os internacionais&#8221;. &#8220;Ademais, a alta de alimentos pode refrear a sensa\u00e7\u00e3o mais benigna da infla\u00e7\u00e3o mais baixa&#8221;, completou Perfeito.<\/p>\n<p>&nbsp;<\/p>\n<p>O analista lembrou que os dados do IPCA-15\u00a0sugerem cautela no aspecto qualitativo para a reuni\u00e3o do Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom) do Banco Central, que ser\u00e1 realizada na pr\u00f3xima semana.\u00a0 &#8220;A dispers\u00e3o dos pre\u00e7os aumentou e uma medida bastante usada pelo Copom para antecipar a infla\u00e7\u00e3o, os servi\u00e7os subjacentes, teve piora&#8221;, alertou. Segundo ele, os servi\u00e7os tendem a pressionar o IPCA, &#8220;devido \u00e0 recupera\u00e7\u00e3o do rendimento m\u00e9dio real habitual na esteira do desemprego em queda&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSANA HESSEL &nbsp; O \u00cdndice de Pre\u00e7os ao Consumidor Amplo 15 (IPCA-15), conhecido como pr\u00e9via da infla\u00e7\u00e3o oficial, registrou alta de 0,31%, em janeiro, conforme dados do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) divulgados nesta sexta-feira (26\/1). &nbsp; O dado ficou abaixo das estimativas do mercado (em torno de 0,50%) e desacelerou em rela\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":15703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[600],"tags":[211,391,1916,7270,5573],"class_list":["post-29668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-carestia","tag-ibge","tag-ipca-15","tag-janeiro-de-2024","tag-previa-da-inflacao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/29668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/comments?post=29668"}],"version-history":[{"count":17,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/29668\/revisions"}],"predecessor-version":[{"id":29691,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/29668\/revisions\/29691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media\/15703"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media?parent=29668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/categories?post=29668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags?post=29668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}