{"id":28395,"date":"2023-07-03T18:47:56","date_gmt":"2023-07-03T21:47:56","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/?p=28395"},"modified":"2023-07-06T12:04:02","modified_gmt":"2023-07-06T15:04:02","slug":"a-real-de-portugal-ha-45-mil-vagas-no-setor-de-turismo-e-empresas-preferem-brasileiros","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/a-real-de-portugal-ha-45-mil-vagas-no-setor-de-turismo-e-empresas-preferem-brasileiros\/","title":{"rendered":"A real de Portugal: h\u00e1 45 mil vagas no setor de turismo e empresas preferem brasileiros"},"content":{"rendered":"<h2>O ver\u00e3o come\u00e7ou com tudo em Portugal, com sol escaldante e um n\u00famero recorde de turistas. Mas os empres\u00e1rios do setor, mais precisamente os de hot\u00e9is e restaurantes, est\u00e3o desesperados porque n\u00e3o h\u00e1 m\u00e3o de obra dispon\u00edvel para preencher todas as vagas abertas.<\/h2>\n<p>&nbsp;<\/p>\n<p>H\u00e1, segundo o levantamento mais recente, publicado pelo <em>Di\u00e1rio de Not\u00edcias<\/em>, 45 mil postos vagos de Norte a Sul de Portugal. A escassez de trabalhadores \u00e9 tamanha, que v\u00e1rias empresas, como a rede de hot\u00e9is Vila Gal\u00e9, est\u00e3o pagando acima do sal\u00e1rio m\u00ednimo de 760 euros (R$ 4,1 mil), oferecendo seguro sa\u00fade e oportunidade de empregados e familiares se hospedarem nos estabelecimentos para desfrutar de alguns dias de descanso.<\/p>\n<p>&nbsp;<\/p>\n<p>A falta de m\u00e3o de obra no setor de turismo de Portugal tornou-se um problema cr\u00f4nico e vem se agudizando desde 2019, antes, portanto, da pandemia do novo coronav\u00edrus. Os portugueses mais jovens n\u00e3o querem trabalhar no ramo, porque se consideram qualificados demais para os trabalhos oferecidos. A op\u00e7\u00e3o tem sido os imigrantes que chegam de v\u00e1rias partes do mundo.<\/p>\n<p>&nbsp;<\/p>\n<p>A prefer\u00eancia dos empres\u00e1rios \u00e9 por brasileiros, por falarem a mesma l\u00edngua e serem mais flex\u00edveis para se encaixar nas vagas dispon\u00edveis. As empresas esperavam, inclusive, que as facilidades dadas pelo governo portugu\u00eas para a concess\u00e3o de autoriza\u00e7\u00e3o de resid\u00eancia a cidad\u00e3os da Comunidade dos Pa\u00edses de L\u00edngua Portuguesa \/CPLP) fossem incrementar a oferta de trabalhadores, mas n\u00e3o \u00e9 o que se v\u00ea.<\/p>\n<p>&nbsp;<\/p>\n<p>Mais de 120 mil pessoas conseguiram obter o direito de morar legalmente em Portugal desde 13 de mar\u00e7o, quando entrou no ar o sistema on-line para a obten\u00e7\u00e3o de autoriza\u00e7\u00e3o de resid\u00eancia. Desse total, cerca de 100 mil s\u00e3o brasileiros. O problema \u00e9 que eles j\u00e1 estavam em Portugal e, na maioria das vezes, empregados.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9 importante ressaltar, ainda, que, mesmo com os b\u00f4nus pagos pelas empresas para preencher as vagas dispon\u00edveis, os sal\u00e1rios n\u00e3o conseguem fazer frente \u00e0 carestia em Portugal. Dependendo das regi\u00f5es de Lisboa e do Porto, as duas maiores cidades do pa\u00eds, o aluguel de um quarto custa entre 700\u00a0 e 800 euros (R$ 3,9 mil e R$ 4,3 mil). As despesas b\u00e1sicas incluem alimenta\u00e7\u00e3o e transporte.<\/p>\n<p>&nbsp;<\/p>\n<p>Portanto, \u00e9 importante que os interessados em se mudar para Portugal para tentar uma vaga no mercado de trabalho pensem muito bem antes de tomar qualquer decis\u00e3o. Foi-se o tempo em que o pa\u00eds europeu oferecia uma \u00f3tima qualidade de vida a um custo baixo. Nem os portugueses est\u00e3o dando conta de arcar com os fortes aumentos de pre\u00e7os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ver\u00e3o come\u00e7ou com tudo em Portugal, com sol escaldante e um n\u00famero recorde de turistas. Mas os empres\u00e1rios do setor, mais precisamente os de hot\u00e9is e restaurantes, est\u00e3o desesperados porque n\u00e3o h\u00e1 m\u00e3o de obra dispon\u00edvel para preencher todas as vagas abertas. &nbsp; H\u00e1, segundo o levantamento mais recente, publicado pelo Di\u00e1rio de Not\u00edcias, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":26130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[600],"tags":[4252,6717,2003,6528,2400,1109,467,14,4835,6716,4253,122,3599],"class_list":["post-28395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-autorizacao","tag-baixos","tag-brasileiros","tag-cplp","tag-empregos","tag-empresas","tag-governo","tag-inflacao","tag-portugal","tag-preferem","tag-residencia","tag-salarios","tag-turismo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/28395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/comments?post=28395"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/28395\/revisions"}],"predecessor-version":[{"id":28425,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/posts\/28395\/revisions\/28425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media\/26130"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/media?parent=28395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/categories?post=28395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/vicente\/wp-json\/wp\/v2\/tags?post=28395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}