{"id":2237,"date":"2022-06-17T06:45:37","date_gmt":"2022-06-17T09:45:37","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/?p=2237"},"modified":"2022-06-17T10:11:16","modified_gmt":"2022-06-17T13:11:16","slug":"caetano-veloso-e-o-grande-encontro-sao-os-destaques-do-fim-de-semana","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/caetano-veloso-e-o-grande-encontro-sao-os-destaques-do-fim-de-semana\/","title":{"rendered":"Caetano Veloso e O Grande Encontro s\u00e3o os destaques do fim de semana"},"content":{"rendered":"<p>A diversidade musical volta a dar o tom na programa\u00e7\u00e3o de shows neste fim de semana em Bras\u00edlia, que tem como destaques <em>Meu coco<\/em>, de Caetano Veloso, e <em>O Grande Encontro<\/em>, com Elba Ramalho, Alceu Valen\u00e7a e Geraldo Azevedo, al\u00e9m da banda pernambucana Eddie. Veja o roteiro que traz o blog <em>Trilha Sonora<\/em>, que se hospeda no <strong>Correio Braziliense<\/strong>.<\/p>\n<p><strong>Arraial Dona Junina &#8212;<\/strong>\u00a0Alceu Valen\u00e7a e Geraldo Azevedo ser\u00e3o as principais atra\u00e7\u00f5es da festa junina que ocorre hoje (17), a partir das 16h, na Ascade (Setor de Clubes Sul). Eles trazem de volta a Bras\u00edlia <em>O Grande Encontro*<\/em>, espet\u00e1culo que est\u00e1 em cartaz h\u00e1 mais de 20 anos. Haver\u00e1 apresenta\u00e7\u00e3o tamb\u00e9m do grupo Rastap\u00e9 e da banda do bloco Eduardo e M\u00f4nica. Ingressos a partir de R$ 80.<\/p>\n<p>*A cantora Elba Ramalho, que iria participar do show, teve a presen\u00e7a cancelada ap\u00f3s testar positivo para a covid-19. A informa\u00e7\u00e3o foi divulgada em comunicado oficial do evento nas redes sociais.<\/p>\n<figure id=\"attachment_2123\" aria-describedby=\"caption-attachment-2123\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2123\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/04\/Sr.-GonzalesBailedeMascaras3-Foto-PaulaCarrubba-230x153.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2123\" class=\"wp-caption-text\">Paula Carrubba\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Era do R\u00e1dio &#8212;<\/strong> No show que faz hoje (17), \u00e0s 20h, na \u00e1rea externa do Clube do Choro (Eixo Monumental), Sr. Gonzales Serenata Orquestra resgata sucessos de cantores e cantoras da era de ouro do r\u00e1dio. O grupo \u00e9 formado por Andr\u00e9 Gonzales (voz), Gustavo Dreher (teclados), Fernando Jatob\u00e1 (guitarra) e Esdras Nogueira (sopro). O couvert art\u00edstico \u00e9 de R$ 25.<\/p>\n<figure id=\"attachment_2246\" aria-describedby=\"caption-attachment-2246\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2246\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1.jpg\" alt=\"\" width=\"1200\" height=\"638\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-300x160.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-768x408.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-1024x544.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-800x425.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-550x292.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/cats-1-230x122.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-2246\" class=\"wp-caption-text\">C\u00e1ssia Portugal. Cr\u00e9dito: TV Globo\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Mulheres que encantam &#8212;<\/strong> C\u00e1ssia Portugal, que participou da edi\u00e7\u00e3o deste ano do programa <em>The Voice Mais,<\/em> se apresenta hoje (17), \u00e0s 20h, no Fazendola Cozinha Bar (311 Norte, Bloco D), pelo projeto <em>Mulheres que encantam<\/em>. A cantora vai interpretar cl\u00e1ssicos do cancioneiro rom\u00e2ntico brasileiro. O couvert art\u00edstico \u00e9 de R$ 10. Reserva de mesa pelo telefone 98154-078.<\/p>\n<figure id=\"attachment_2247\" aria-describedby=\"caption-attachment-2247\" style=\"width: 756px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2247\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Alex.jpg\" alt=\"\" width=\"756\" height=\"405\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Alex.jpg 756w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Alex-300x161.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Alex-550x295.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Alex-230x123.jpg 230w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/><figcaption id=\"caption-attachment-2247\" class=\"wp-caption-text\">Alex Silva. Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<p><strong>Homenagem a Benjor &#8212;<\/strong> Alex Silva e sua banda revisitam a obra de Jorge Benjor em show hoje (17h), \u00e0s 19h30, no Green Coffee Lounge (203 Norte, Bloco C).O couve art\u00edstico \u00e9 de R$ 20.<\/p>\n<p><strong>Arrai\u00e1 do Man\u00e9 &#8212;<\/strong> O conglomerado de restaurantesno Man\u00e9, pr\u00f3ximo ao Est\u00e1dio Man\u00e9 Garrincha, promove o primeiro Arrai\u00e1 do Man\u00e9, a partir das 16h. Hoje (17) se apresentam o grupo Forr\u00f3 da Massa e a Fam\u00edlia Firula, e amanh\u00e3 (18) o Trio Cavanha. Acesso gratuito.<\/p>\n<figure id=\"attachment_2245\" aria-describedby=\"caption-attachment-2245\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2245\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Myriam-Greco.jpg\" alt=\"\" width=\"720\" height=\"480\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Myriam-Greco.jpg 720w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Myriam-Greco-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Myriam-Greco-550x367.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Myriam-Greco-230x153.jpg 230w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-2245\" class=\"wp-caption-text\">Myriam Greco. Cr\u00e9dito: Conjunto Nacional\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>M\u00fasica em conjunto &#8212;<\/strong> O Jardim Urbano no terceiro piso do Conjunto Nacional recebe hoje (17), \u00e0s 17h, a cantora Myrian Greco, int\u00e9rprete de cl\u00e1ssicos da obra de compositores da MPB. J\u00e1 amanh\u00e3 (18), \u00e0s 12h \u00e9 a vez do Caf\u00e9 Samba Tr\u00eas, liderado pelo cantor e compositor carioca, radicado em Ceil\u00e2ndia, Marcelo Caf\u00e9, que toca sambas de mestres. Acesso gratuito.<\/p>\n<figure id=\"attachment_2244\" aria-describedby=\"caption-attachment-2244\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2244\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz.jpg 1600w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-1024x682.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-1440x959.jpg 1440w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-800x533.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/007_@jpsofranz-230x153.jpg 230w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-2244\" class=\"wp-caption-text\">Caetano Veloso. Cr\u00e9dito: jpsofranz\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Meu Coco &#8212;<\/strong> Em turn\u00ea pelo pa\u00eds com o show <em>Meu coco<\/em>, Caetano Veloso chega amanh\u00e3 (18) a Bras\u00edlia para apresenta\u00e7\u00e3o o audit\u00f3rio master do Centro de Conven\u00e7\u00f5es Ulysses Guimar\u00e3es. Acompanhado por banda, o tropicalista mostra m\u00fasicas do \u00e1lbum hom\u00f4nimo, lan\u00e7ado no final de 2021 e cl\u00e1ssicos de sua obra, a partir \u00e0s 22h.Os ingressos est\u00e3o esgotados.<\/p>\n<figure id=\"attachment_2240\" aria-describedby=\"caption-attachment-2240\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2240\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/CrisPereira6-Foto-ThaisMalon-230x153.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2240\" class=\"wp-caption-text\">Cris Pereira. Cr\u00e9dito: Tha\u00eds Mallon\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Samba de bambas &#8212;<\/strong> A cantora Cris Pereira \u00e9 destaque de amanh\u00e3 (18), ao meio dia, na feijoada do Caf\u00e9 Musical, na \u00e1rea externa do Clube do Choro (Eixo Monumental). Ela vai levar aos espectadores cl\u00e1ssicos dos bambas do samba. O couvert art\u00edstico \u00e9 de R$15 e o da feijoada R$ 44,90.<\/p>\n<p><strong>Belo Dia &#8212;<\/strong> O sambista Belo e a funkeira Ludmilla agitam o <em>Belo Dia<\/em>, evento que ocupa a Prainha da Asbac (Setor de Clubes Sul), amanh\u00e3 (18), com in\u00edcio \u00e0s 16h. H\u00e1 a participa\u00e7\u00e3o dos DJs Matheus Fonseca, Rafa Rios e Daniel Futuro. Ingressos a partir de R$ 130.<\/p>\n<figure id=\"attachment_2242\" aria-describedby=\"caption-attachment-2242\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2242\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod.jpg\" alt=\"\" width=\"800\" height=\"527\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod-300x198.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod-768x506.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod-550x362.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/p\u00e9-de-cerraod-230x152.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2242\" class=\"wp-caption-text\">P\u00e9 de Cerrado. Cr\u00e9dito: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Festival Cerratense &#8212;<\/strong> Shows de Ana Ximenes, Cris Pereira, grupo P\u00e9 de Cerrado e das bandas Tribaw\u00ea, Nenhuma Ilha e Negra Eve est\u00e3o na programa\u00e7\u00e3o do Festival Cerratense amanh\u00e3 (18), \u00e0s 19h, na Pra\u00e7a S\u00e3o Sebasti\u00e3o, em Planaltina. Acesso gratuito.<\/p>\n<figure id=\"attachment_2241\" aria-describedby=\"caption-attachment-2241\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2241\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Eddie-Foto-Clara-Gouveia-2-230x153.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2241\" class=\"wp-caption-text\">Eddie. Cr\u00e9dito: Clara Gouveia\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Ati\u00e7a &#8212;<\/strong> Pioneira do mangue beat, a Banda Eddie faz show amanh\u00e3 (18), \u00e0s 22h, no Chic\u00e3o do Conic (Setor de Divers\u00f5es Sul), para lan\u00e7ar o \u00e1lbum Ati\u00e7a. O ingresso custa R$ 5 e + R$ 5 de taxa.<\/p>\n<figure id=\"attachment_2238\" aria-describedby=\"caption-attachment-2238\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2238\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/2022.05.20-7-na-roda-fotos-Tha\u00eds-Mallon-6-230x153.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2238\" class=\"wp-caption-text\">7 na Roda. Cr\u00e9dito: Tha\u00eds Mallon\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Samba Ta A\u00ed &#8212;<\/strong> Idealizado pelo grupo 7 na Roda, o projeto Samba T\u00e1 A\u00ed, que vai circular pelo Distrito Federal, estreia domingo (19), \u00e0s 16h, na Pra\u00e7a da Igrejinha, na Vila Planalto. Na homenagem a J\u00fanior do Cavaco se apresentam Marcelo Sena e Lucinha Cust. Acesso gratuito.<\/p>\n<figure id=\"attachment_2239\" aria-describedby=\"caption-attachment-2239\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2239\" src=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1-300x200.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1-768x512.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1-550x366.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-content\/uploads\/sites\/39\/2022\/06\/Rooftop-Sante-Lago-credito-Davi-Fernandes-1-230x153.jpg 230w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2239\" class=\"wp-caption-text\">Cr\u00e9dito: Davi Fernandes\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Sant\u00e9 Sol &amp; Som &#8212;<\/strong> Show de O Bando abre o projeto Sant\u00e9 Sol &amp; Som no domingo (19), \u00e0s 16h, no restaurante Sant\u00e9, na Orla da Ponte JK. O repert\u00f3rio do grupo traz MPB, pop, rock e reggae.O couvert art\u00edstico \u00e9 de R$ 25.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diversidade musical volta a dar o tom na programa\u00e7\u00e3o de shows neste fim de semana em Bras\u00edlia, que tem como destaques Meu coco, de Caetano Veloso, e O Grande Encontro, com Elba Ramalho, Alceu Valen\u00e7a e Geraldo Azevedo, al\u00e9m da banda pernambucana Eddie. Veja o roteiro que traz o blog Trilha Sonora, que se hospeda no Correio Braziliense. Arraial [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113],"tags":[26,58,256,235,257,285],"class_list":["post-2237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materia","tag-brasilia","tag-caetano-veloso","tag-eventos","tag-festa-junina","tag-fim-de-semana","tag-o-grande-encontro"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/posts\/2237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/comments?post=2237"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/posts\/2237\/revisions"}],"predecessor-version":[{"id":2251,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/posts\/2237\/revisions\/2251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/media\/2243"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/media?parent=2237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/categories?post=2237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/trilhasonora\/wp-json\/wp\/v2\/tags?post=2237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}