{"id":7327,"date":"2017-11-08T10:54:32","date_gmt":"2017-11-08T12:54:32","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=7327"},"modified":"2017-11-08T10:54:32","modified_gmt":"2017-11-08T12:54:32","slug":"reforma-trabalhista-configuracao-de-salario-muda-com-nova-lei","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/reforma-trabalhista-configuracao-de-salario-muda-com-nova-lei\/","title":{"rendered":"Reforma trabalhista &#8211; Configura\u00e7\u00e3o de sal\u00e1rio muda com a nova lei"},"content":{"rendered":"<p><em>Pr\u00eamios poder\u00e3o ficar de fora da remunera\u00e7\u00e3o e, com isso, n\u00e3o incidir\u00e3o encargos trabalhistas e previdenci\u00e1rios sobre o valor. Se por um lado pode estimular pagamentos extras por produtividade, causar\u00e1 perda de arrecada\u00e7\u00e3o ao governo<\/em><\/p>\n<p><strong>ALESSANDRA AZEVEDO<\/strong><\/p>\n<p>As novas regras trabalhistas, que come\u00e7am a valer no s\u00e1bado, n\u00e3o mudam apenas os tipos de contratos estabelecidos entre os empregados e as empresas. Entre os mais de 100 pontos da Consolida\u00e7\u00e3o das Leis do Trabalho (CLT) alterados pela Lei n\u00ba 13.467, sancionada em julho pelo presidente Michel Temer, est\u00e1 a possibilidade de uma nova configura\u00e7\u00e3o dos sal\u00e1rios. Alguns valores que atualmente fazem parte obrigatoriamente da remunera\u00e7\u00e3o, sobre a qual incidem encargos trabalhistas e previdenci\u00e1rios, agora poder\u00e3o ser pagos \u00e0 parte nos novos contratos.<\/p>\n<p>Os pr\u00eamios s\u00e3o o principal exemplo disso. Hoje, uma empresa pode recompensar os funcion\u00e1rios por bom desempenho, mas o valor entrar\u00e1 na conta do sal\u00e1rio. Ou seja, al\u00e9m de descontos para o Fundo de Garantia por Tempo de Servi\u00e7o (FGTS), faz parte do c\u00e1lculo do 13\u00ba sal\u00e1rio, das f\u00e9rias e de todos os outros direitos trabalhistas. A partir de s\u00e1bado, entretanto, a empresa poder\u00e1 ceder pr\u00eamios sem que, sobre o valor, sejam descontados quaisquer tipos de impostos.<\/p>\n<p>A nova configura\u00e7\u00e3o gera duas principais consequ\u00eancias que precisam ser analisadas com cuidado, na avalia\u00e7\u00e3o de especialistas. Uma delas, que \u00e9 o objetivo do legislador, \u00e9 a maior disposi\u00e7\u00e3o dos empres\u00e1rios de premiar os funcion\u00e1rios, j\u00e1 que os b\u00f4nus n\u00e3o ser\u00e3o acompanhados de mais custos. \u201cSe for usado da forma correta, pode ser algo bastante interessante para flexibilizar a remunera\u00e7\u00e3o. \u00c9 mais atraente para os empres\u00e1rios\u201d, afirmou o advogado trabalhista Antonio Carlos Aguiar, s\u00f3cio do Peixoto &amp; Cury Advogados.<\/p>\n<p>Estimular os empregadores a conceder pr\u00eamios \u00e9 o principal objetivo da ressalva inclu\u00edda no texto. \u201cAtualmente, h\u00e1 muito temor em dar esse tipo de parcela e a pessoa entrar na Justi\u00e7a depois e conseguir incorpor\u00e1-la para todos os fins. Esse dispositivo veio para dar seguran\u00e7a ao empregador que quiser dar um b\u00f4nus\u201d, explicou o advogado Lucas Sousa Santos, especialista em direito trabalhista do Mendon\u00e7a e Sousa Advogados.<\/p>\n<p>A outra consequ\u00eancia, menos positiva, \u00e9 que as empresas poder\u00e3o passar a contratar funcion\u00e1rios com sal\u00e1rios menores, mas com pr\u00eamios garantidos. Por exemplo, em vez de um trabalhador que ganhe R$ 5 mil de sal\u00e1rio, o empres\u00e1rio poder\u00e1 pagar R$ 2 mil e garantir o resto como pr\u00eamio, sem que incida nenhum tipo de imposto. \u201cTrocando em mi\u00fados, a empresa oferece um sal\u00e1rio de R$ 2 mil, mas pr\u00eamio de R$ 4 mil, de forma que, no fim das contas, ele ganha R$ 1 mil a mais do que antes. Passa a ideia de que \u00e9 melhor para o empregado\u201d, explica advogado Fabio Chong, s\u00f3cio da \u00e1rea trabalhista do L.O. Baptista Advogados. O problema \u00e9 que, na hora de receber o FGTS ou o 13\u00ba sal\u00e1rio, a base de c\u00e1lculo ser\u00e1 os R$ 2 mil registrados em carteira, o que pode diminuir bastante a renda final do trabalhador.<\/p>\n<p><strong>Redu\u00e7\u00e3o salarial<\/strong><\/p>\n<p>Aguiar, da Peixoto &amp; Cury, ressalta que n\u00e3o existe a possibilidade de redu\u00e7\u00e3o de sal\u00e1rios. A configura\u00e7\u00e3o valer\u00e1 para os novos funcion\u00e1rios contratados, mas os patr\u00f5es n\u00e3o poder\u00e3o diminuir o sal\u00e1rio de um contratado, mesmo que reponha na forma de pr\u00eamio. \u201cSe fizer isso, o trabalhador pode entrar na Justi\u00e7a e estar\u00e1 com a causa ganha. Nem acordo com sindicato pode ser feito para diminuir os direitos do trabalhador. Tudo o que for feito para burlar ou fraudar a lei ser\u00e1 automaticamente nulo de direito\u201d observou o advogado.<\/p>\n<p>Mas as novas possibilidades de remunera\u00e7\u00e3o podem fazer com que a disposi\u00e7\u00e3o dos empregadores em conceder aumentos salariais fique menor. \u201cAgora, o patr\u00e3o pode se negar a dar aumento, mas sugerir que, se o funcion\u00e1rio conseguir melhorar o desempenho, ganhar\u00e1 pr\u00eamios\u201d, explicou Aguiar.<\/p>\n<p><strong>Previd\u00eancia<\/strong><\/p>\n<p>Diante do rombo previdenci\u00e1rio de quase R$ 150 bilh\u00f5es no ano passado, o fato de que a arrecada\u00e7\u00e3o poder\u00e1 diminuir com esse tipo de iniciativa preocupa at\u00e9 integrantes do governo federal. Depois de um per\u00edodo de experi\u00eancia, \u00e9 poss\u00edvel que esse dispositivo seja revisto pelo Pal\u00e1cio do Planalto. Dificilmente, avaliam especialistas, ser\u00e1 avaliado de novo pelos parlamentares, que se constituem, em boa parte, de empres\u00e1rios beneficiados pela nova forma de remunerar seus funcion\u00e1rios. \u201cO risco disso \u00e9 que o governo vai deixar de receber a contribui\u00e7\u00e3o para Instituto Nacional do Seguro Social (INSS). N\u00e3o se sabe se ele vai abrir m\u00e3o disso. A fiscaliza\u00e7\u00e3o do INSS vai pegar pesado\u201d, acredita Aguiar.<\/p>\n<p>O diretor de Rela\u00e7\u00f5es Institucionais da CBPI Produtividade Institucional, Emerson Casali, tamb\u00e9m acredita que esse ponto ainda ser\u00e1 testado, por ser um dos grandes impasses da reforma trabalhista. \u201cN\u00e3o \u00e9 uma quest\u00e3o pacificada, sobre a qual o advogado vai dizer realmente como funciona. H\u00e1 opini\u00f5es muito inconclusivas. Depender\u00e1 muito do bom senso e do tempo para ver como fica\u201d, avaliou.<\/p>\n<p><b>Pagamento de gorjetas gera d\u00favidas<\/b><\/p>\n<p>Embora o texto da lei n\u00e3o insira explicitamente as gorjetas como parte desses pr\u00eamios, muitas empresas entenderam que sim, e passaram a desconsiderar a lei das gorjetas, aprovada este ano, que obriga a contabilizar esses valores nos c\u00e1lculos de remunera\u00e7\u00e3o do empregado.<\/p>\n<p>O advogado Lucas Sousa Santos, especialista em direito trabalhista do Mendon\u00e7a e Sousa Advogados, esclareceu que esse tipo de pagamento n\u00e3o entra na lista dos valores que podem ser livres de impostos, apesar de a lei ter sido pouco clara quanto ao ponto. &#8220;O entendimento majorit\u00e1rio \u00e9 de que a lei das gorjetas se mant\u00e9m. Para n\u00e3o ser inclu\u00eddo na conta do sal\u00e1rio, o valor precisa decorrer de desempenho fora do ordin\u00e1rio. Gorjeta est\u00e1 dentro do esperado, n\u00e3o \u00e9 nenhum tipo de premia\u00e7\u00e3o por desempenho\u201d, explicou.<\/p>\n<p>A mesma regra vale, segundo ele, para comiss\u00f5es recebidas por funcion\u00e1rios de lojas, de acordo com o volume das vendas. O advogado lembrou que a reforma trabalhista inseriu no texto, al\u00e9m da possibilidade de pagamentos sem encargos, o conceito de pr\u00eamio. \u201cCriaram um par\u00e1grafo para explicar o que pode ser considerado pr\u00eamio. \u00c9 uma parcela paga por vontade do empregador, como contrapresta\u00e7\u00e3o por algum resultado at\u00edpico, como meta batida, por exemplo\u201d, explicou. (<b>AA<\/b>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00eamios poder\u00e3o ficar de fora da remunera\u00e7\u00e3o e, com isso, n\u00e3o incidir\u00e3o encargos trabalhistas e previdenci\u00e1rios sobre o valor. Se por um lado pode estimular pagamentos extras por produtividade, causar\u00e1 perda de arrecada\u00e7\u00e3o ao governo ALESSANDRA AZEVEDO As novas regras trabalhistas, que come\u00e7am a valer no s\u00e1bado, n\u00e3o mudam apenas os tipos de contratos estabelecidos entre os empregados e as [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[2414,946,2272,9659,1948,5034,2381,2032,685,98,2770,102,9660,2474,4570,7148,4553,711,1620,643,2157],"class_list":["post-7327","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-13o-salario","tag-arrecadacao","tag-clt","tag-configuracao","tag-descontados","tag-encargos","tag-extras","tag-ferias","tag-fgts","tag-governo","tag-impostos","tag-lei","tag-lei-13-467","tag-michel-temer","tag-pagamentos","tag-premios","tag-previdenciarios","tag-reforma","tag-remuneracao","tag-salario","tag-trabalhista"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=7327"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7327\/revisions"}],"predecessor-version":[{"id":7328,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7327\/revisions\/7328"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=7327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=7327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=7327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}