{"id":7050,"date":"2017-10-19T12:13:18","date_gmt":"2017-10-19T14:13:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=7050"},"modified":"2017-10-19T12:13:18","modified_gmt":"2017-10-19T14:13:18","slug":"comparativo-entre-ingressos-por-concurso-e-aposentadorias-demonstra-reducao-de-servidores-em-2017","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/comparativo-entre-ingressos-por-concurso-e-aposentadorias-demonstra-reducao-de-servidores-em-2017\/","title":{"rendered":"Comparativo entre ingressos por concurso e aposentadorias demonstra redu\u00e7\u00e3o de servidores em 2017"},"content":{"rendered":"<p><span style=\"font-family: Arial,sans-serif\"><span style=\"font-size: large\"><span style=\"font-size: medium\"><em>Os dados foram extra\u00eddos do Painel Estat\u00edstico de Pessoal (PEP) e revelam que houve diminui\u00e7\u00e3o de 4.292 funcion\u00e1rios somente esse ano<br \/>\n<\/em><\/span><\/span><\/span><\/p>\n<p class=\"m_3885050477490568823western\"><span style=\"font-family: Arial,sans-serif\">Levantamento, com base no\u00a0<span style=\"font-family: Arial,sans-serif\"> <a href=\"https:\/\/www.pep.planejamento.gov.br\/\" target=\"_blank\"> Painel Estat\u00edstico de Pessoal (PEP)\u200b<\/a>,<\/span> demonstra uma redu\u00e7\u00e3o na quantidade de servidores na compara\u00e7\u00e3o entre os ingressos por concurso p\u00fablico e as aposentadorias no servi\u00e7o p\u00fablico em 2017, informou o <span style=\"font-family: Arial,sans-serif\">do Minist\u00e9rio do Planejamento, Desenvolvimento e Gest\u00e3o (MP)<\/span>. Os dados revelam uma diminui\u00e7\u00e3o de 4.292 servidores na an\u00e1lise do per\u00edodo entre janeiro a setembro deste ano. <\/span><\/p>\n<p class=\"m_3885050477490568823western\">\u201c<span style=\"font-family: Arial,sans-serif\">Esta informa\u00e7\u00e3o demonstra o esfor\u00e7o do governo em modernizar a gest\u00e3o com o uso intensivo de tecnologia, al\u00e9m do controle de despesas de pessoal\u201d, afirma Augusto Chiba, secret\u00e1rio de Gest\u00e3o de Pessoas do MP. Entre janeiro e setembro de 2017, ingressaram no servi\u00e7o p\u00fablico 14.934 pessoas. Nestes meses, se aposentaram 19.226 servidores.<\/span><\/p>\n<p class=\"m_3885050477490568823western\"><span style=\"font-family: Arial,sans-serif\"><\/p>\n<p><img decoding=\"async\" class=\"CToWUd a6T\" title=\"20171017_grafico_pep.png\" src=\"https:\/\/mail.google.com\/mail\/u\/0\/?ui=2&amp;ik=161b52c0c4&amp;view=fimg&amp;th=15f34d63ca04e4c3&amp;attid=0.1&amp;disp=emb&amp;attbid=ANGjdJ9ZaCO00YFRpgeRxl9960qzZ1kCP7XpYnhKtexybiXAbA9PpvYBF9VeJ_9crOfH_NhPPxs-T0W8FsiDD56FjCAohAeJzGGm0OeoDmc5f4Va5lSOYR0XyM5AW2E&amp;sz=s0-l75-ft&amp;ats=1508421253018&amp;rm=15f34d63ca04e4c3&amp;zw&amp;atsh=1\" alt=\"\" \/>\u200b<br \/>\n<\/span><\/p>\n<p class=\"m_3885050477490568823western\"><span style=\"font-family: Arial,sans-serif\">Os dados divulgados no PEP s\u00e3o atualizados mensalmente pela Secretaria de Gest\u00e3o de Pessoas (SGP). Segundo as informa\u00e7\u00f5es de setembro de 2017, trabalham no Executivo Federal 634.904 pessoas, com uma despesa total de R$ 7,9 bilh\u00f5es. Estes n\u00fameros englobam os servidores civis ativos.<\/p>\n<p>O PEP foi lan\u00e7ado em junho deste ano com o objetivo de ampliar a transpar\u00eancia ativa e simplificar o acesso \u00e0s informa\u00e7\u00f5es estat\u00edsticas da gest\u00e3o de pessoas do governo federal. O sistema permite ao usu\u00e1rio, ainda, o cruzamento de dados e diferentes an\u00e1lises. O painel concentra informa\u00e7\u00f5es sobre despesas, servidores, remunera\u00e7\u00e3o, concursos, cargos e fun\u00e7\u00f5es e aposentadorias. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os dados foram extra\u00eddos do Painel Estat\u00edstico de Pessoal (PEP) e revelam que houve diminui\u00e7\u00e3o de 4.292 funcion\u00e1rios somente esse ano Levantamento, com base no\u00a0 Painel Estat\u00edstico de Pessoal (PEP)\u200b, demonstra uma redu\u00e7\u00e3o na quantidade de servidores na compara\u00e7\u00e3o entre os ingressos por concurso p\u00fablico e as aposentadorias no servi\u00e7o p\u00fablico em 2017, informou o do Minist\u00e9rio do Planejamento, Desenvolvimento [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[2055,865,9369,207,235,6176,315,98,2914,141,7395,6728,1153,325,58,4504],"class_list":["post-7050","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-aposentadorias","tag-ativos","tag-comparativo","tag-controle","tag-despesas","tag-esforco","tag-gestao","tag-governo","tag-ingressos","tag-ministerio-do-planejamento","tag-modernizar","tag-pep","tag-pessoal","tag-reducao","tag-servidores","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=7050"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7050\/revisions"}],"predecessor-version":[{"id":7051,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/7050\/revisions\/7051"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=7050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=7050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=7050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}