{"id":6360,"date":"2017-08-15T14:20:20","date_gmt":"2017-08-15T17:20:20","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=6360"},"modified":"2017-08-15T14:20:20","modified_gmt":"2017-08-15T17:20:20","slug":"geap-retificacao-de-imposto-de-renda","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/geap-retificacao-de-imposto-de-renda\/","title":{"rendered":"Geap &#8211; retifica\u00e7\u00e3o de Imposto de Renda"},"content":{"rendered":"<p><em>A Geap Autogest\u00e3o, maior operadora de plano de sa\u00fade dos servidores, informou reenviou ao fisco os arquivos da DMED. Quem teve a Declara\u00e7\u00e3o de Imposto de Renda retida na malha fina, por discord\u00e2ncia dos dados sobre valores de desconto, deve verificar que continua com a pend\u00eancia na Receita Federal<\/em><\/p>\n<p>Veja a nota:<\/p>\n<p>&#8220;A Geap motivada por in\u00fameras solicita\u00e7\u00f5es de seus benefici\u00e1rios, a fim de esclarecimentos acerca da tratativa para retificar o imposto de renda, devido \u00e0 declara\u00e7\u00e3o ter ficado presa na malha fina, informa que foi retransmitido \u00e0 Receita Federal do Brasil (RFB), o arquivo da Declara\u00e7\u00e3o de Servi\u00e7os M\u00e9dicos (DMED), compondo todos os valores pagos para a Geap, separados por CPF, no exerc\u00edcio de 2016.<\/p>\n<p>Sendo assim, com o intuito de dirimir as d\u00favidas de seus benefici\u00e1rios e demonstrar \u00e0 Receita Federal o que realmente foi descontado\/cobrado do benefici\u00e1rio, \u00e9 que a Geap decidiu enviar novamente esse arquivo da DMED com as informa\u00e7\u00f5es de todos os valores pagos, sejam eles por meio da folha de pagamento ou por t\u00edtulo banc\u00e1rio.<\/p>\n<p>Portanto, orientamos aos benefici\u00e1rios que estiverem na malha fina, verificar se com o reenvio do novo arquivo pela Geap, a pend\u00eancia foi retirada pela Receita Federal do Brasil. Caso n\u00e3o tenha ocorrido, a retifica\u00e7\u00e3o dever\u00e1 ser feita de acordo com o <strong>\u201cComprovante de pagamento para efeito de declara\u00e7\u00e3o de imposto de renda\u201d<\/strong>, disponibilizado pela Geap.<\/p>\n<p>Alertamos, tamb\u00e9m, aos benefici\u00e1rios que receberam reembolso integral de despesas m\u00e9dicas, n\u00e3o dever\u00e3o lan\u00e7ar as informa\u00e7\u00f5es no imposto de renda.<\/p>\n<p>O comprovante citado acima est\u00e1 dispon\u00edvel nos seguintes canais:<\/p>\n<ul>\n<li>Site da Geap: <a href=\"http:\/\/www.geap.com.br\/\">http:\/\/www.geap.com.br\/<\/a><\/li>\n<li>Central de atendimento: 0800 728 8300<\/li>\n<li>Balc\u00e3o de atendimento das Ger\u00eancias Estaduais&#8221;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A Geap Autogest\u00e3o, maior operadora de plano de sa\u00fade dos servidores, informou reenviou ao fisco os arquivos da DMED. Quem teve a Declara\u00e7\u00e3o de Imposto de Renda retida na malha fina, por discord\u00e2ncia dos dados sobre valores de desconto, deve verificar que continua com a pend\u00eancia na Receita Federal Veja a nota: &#8220;A Geap motivada por in\u00fameras solicita\u00e7\u00f5es de seus [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[980,956,167,1274,3690,235,5645,8232,8234,8231,355,1036,4585,3073,5429,294,5186,8233,2965,1808],"class_list":["post-6360","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-beneficiarios","tag-cobranca","tag-dados","tag-declaracao","tag-desconto","tag-despesas","tag-discordancia","tag-dmed","tag-fina","tag-geapa","tag-imposto-de-renda","tag-integral","tag-malha","tag-medica","tag-pendencia","tag-receita-federal","tag-reembolso","tag-retida","tag-retificacao","tag-valores"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/6360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=6360"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/6360\/revisions"}],"predecessor-version":[{"id":6361,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/6360\/revisions\/6361"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=6360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=6360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=6360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}