{"id":4428,"date":"2017-02-23T17:20:45","date_gmt":"2017-02-23T20:20:45","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=4428"},"modified":"2017-02-23T17:20:45","modified_gmt":"2017-02-23T20:20:45","slug":"empresas-do-simples-podem-ser-liberadas-de-multa-de-10-sobre-fgts","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/empresas-do-simples-podem-ser-liberadas-de-multa-de-10-sobre-fgts\/","title":{"rendered":"Empresas do Simples podem ser liberadas de multa de 10% sobre FGTS"},"content":{"rendered":"<p><em>Decis\u00e3o recente da 20\u00aa Vara Federal do Distrito Federal abre precedente para que empresas do regime sejam liberadas do tributo. Projeto de Lei enviado ao Congresso prev\u00ea redu\u00e7\u00e3o gradativa da multa para todas as empresas<\/em><\/p>\n<p>Decis\u00e3o judicial recente da 20\u00aa Vara Federal do Distrito Federal abre precedente para que empresas de todo o pa\u00eds enquadradas no Simples Nacional sejam liberadas da multa extra de 10% do Fundo de Garantia por Tempo de Servi\u00e7o (FGTS) em caso de demiss\u00e3o sem justa causa. Na avalia\u00e7\u00e3o da Federa\u00e7\u00e3o Nacional das Empresas de Servi\u00e7os Cont\u00e1beis e das Empresas de Assessoramento, Per\u00edcias, Informa\u00e7\u00f5es e Pesquisas (Fenacon), a legisla\u00e7\u00e3o dessas empresas \u00e9 diferenciada e a tributa\u00e7\u00e3o n\u00e3o est\u00e1 prevista para o regime. Foi nesta an\u00e1lise que o juiz Renato Coelho Borelli se baseou para liberar o pagamento. Al\u00e9m disso, na an\u00e1lise da Fenacon, a decis\u00e3o, que \u00e9 particular, s\u00f3 refor\u00e7a a import\u00e2ncia da aprova\u00e7\u00e3o do projeto de lei de redu\u00e7\u00e3o gradual da multa extra, enviado pelo governo ao Congresso Nacional na \u00faltima semana.<\/p>\n<p>\u201cA decis\u00e3o judicial gera efeito apenas entre as partes envolvidas na a\u00e7\u00e3o mas pode criar um precedente para outras que se encontram na mesma situa\u00e7\u00e3o\u201d, destaca o diretor pol\u00edtico-parlamentar da Fenacon, Valdir Pietrobon, que estimula o ingresso de a\u00e7\u00f5es judiciais por parte das empresas do Simples enquanto a extin\u00e7\u00e3o n\u00e3o ocorre por meio de lei.<\/p>\n<p><strong>Redu\u00e7\u00e3o gradual<\/strong><\/p>\n<p>Para incentivar o aumento da competitividade e a retomada do crescimento, o governo enviou proposta ao Congresso Nacional que extingue, de forma gradual, a multa de 10% para demiss\u00f5es sem justa causa. O projeto de lei complementar (PLP 340\/2017) prev\u00ea a retirada de 1% ao ano, entre 2018 e 2027, at\u00e9 que o tributo deixe de existir. Considerando as verbas rescis\u00f3rias, como os saldos de sal\u00e1rios e f\u00e9rias, o 13\u00ba proporcional e ainda os 40% sobre o valor total do fundo devido ao trabalhador, custa caro demitir um funcion\u00e1rio sem justa causa no Brasil.<\/p>\n<p>A proposta de extin\u00e7\u00e3o gradativa da multa contribui para redu\u00e7\u00e3o de custos para as empresas e, consequente, estimula sua sobreviv\u00eancia e crescimento, especialmente em tempos de crise. \u201cSe levarmos em conta s\u00f3 o FGTS de um funcion\u00e1rio com saldo de R$ 10 mil, al\u00e9m de depositar os R$ 4 mil devidos ao trabalhador, o empres\u00e1rio ter\u00e1 de pagar mais R$ 1 mil para o governo\u201d, explica o presidente da Fenacon, Mario Elmir Berti. \u201cEm uma \u00e9poca de crise como a que estamos vivendo, o valor gasto com a multa extra impede o empres\u00e1rio de fazer um novo investimento ou at\u00e9 mesmo uma nova contrata\u00e7\u00e3o\u201d, ressaltou.<\/p>\n<p>O assunto n\u00e3o \u00e9 novo e j\u00e1 foi discutido na C\u00e2mara e no Senado em 2013, mas sofreu veto presidencial. \u201cEsperamos que agora o projeto seja aprovado e contribua para o desenvolvimento das empresas brasileiras. Embora ele seja considerado um avan\u00e7o devido a crise econ\u00f4mica que o pa\u00eds atravessa e por uma recupera\u00e7\u00e3o mais r\u00e1pidas das empresas, a Fenacon ir\u00e1 sugerir que a retirada da multa seja de 5% no primeiro ano e de 1% nos seguintes, finalizando em seis anos \u201d, destaca Pietrobon.<\/p>\n<p>Os trabalhadores n\u00e3o ser\u00e3o afetados pela mudan\u00e7a, conforme destaca Berti. \u201cO percentual que deve ser extinto era devido ao governo, a parcela paga ao funcion\u00e1rio no momento da rescis\u00e3o sem justa causa n\u00e3o ser\u00e1 alterado pelo projeto\u201d, ressaltou.<\/p>\n<p><strong>Hist\u00f3rico<\/strong><\/p>\n<p>A multa de 10% sobre o saldo do FGTS foi institu\u00edda em 2001, por meio da Lei Complementar n\u00ba110, e tinha como objetivo promover a atualiza\u00e7\u00e3o monet\u00e1ria das contas vinculadas que sofreram expurgo pelos Planos Ver\u00e3o e Collor. No entanto, desde agosto de 2012, segundo o texto da proposta, os valores arrecadados s\u00e3o superiores aos necess\u00e1rios, por isso o governo prop\u00f4s a extin\u00e7\u00e3o gradual. O projeto de Lei Complementar foi encaminhado \u00e0 C\u00e2mara dos Deputados em 17 de fevereiro e depois de passar pelas comiss\u00f5es e pelo plen\u00e1rio da casa, ser\u00e1 encaminhado para aprecia\u00e7\u00e3o do Senado.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><strong>Sobre o Sistema Fenacon Sescap\/Sescon<\/strong><\/p>\n<p>O Sistema Fenacon Sescap\/Sescon (Federa\u00e7\u00e3o Nacional das Empresas de Servi\u00e7os Cont\u00e1beis e das Empresas de Assessoramento, Per\u00edcias, Informa\u00e7\u00f5es e Pesquisas) congrega 37 sindicatos, distribu\u00eddos nos 26 estados e no Distrito Federal, que representam mais de 400 mil empresas dessas \u00e1reas. A entidade tem se consolidado como leg\u00edtima lideran\u00e7a na representa\u00e7\u00e3o do setor de servi\u00e7os, atuando diretamente no combate \u00e0 alta carga tribut\u00e1ria e na diminui\u00e7\u00e3o da burocracia, al\u00e9m de lutar por pol\u00edticas p\u00fablicas que garantam mais desenvolvimento \u00e0s empresas brasileiras, sobretudo as micro e pequenas. Mais informa\u00e7\u00f5es: <a href=\"http:\/\/www.fenacon.org.br\" target=\"_blank\">www.fenacon.org.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o recente da 20\u00aa Vara Federal do Distrito Federal abre precedente para que empresas do regime sejam liberadas do tributo. Projeto de Lei enviado ao Congresso prev\u00ea redu\u00e7\u00e3o gradativa da multa para todas as empresas Decis\u00e3o judicial recente da 20\u00aa Vara Federal do Distrito Federal abre precedente para que empresas de todo o pa\u00eds enquadradas no Simples Nacional sejam liberadas [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[100,1017,390,2114,2348,599,685,2236,5137,405,101,477,5001],"class_list":["post-4428","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-congresso","tag-demissao","tag-empresas","tag-extincao","tag-extra","tag-fenacon","tag-fgts","tag-justica-federal","tag-liberadas","tag-multa","tag-projeto","tag-simples","tag-tributo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=4428"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4428\/revisions"}],"predecessor-version":[{"id":4429,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4428\/revisions\/4429"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=4428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=4428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=4428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}