{"id":4120,"date":"2017-01-25T15:21:29","date_gmt":"2017-01-25T17:21:29","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=4120"},"modified":"2017-01-25T15:21:29","modified_gmt":"2017-01-25T17:21:29","slug":"atuacao-irregular-em-operacoes-no-mercado-forex","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/atuacao-irregular-em-operacoes-no-mercado-forex\/","title":{"rendered":"Atua\u00e7\u00e3o irregular em opera\u00e7\u00f5es no mercado Forex"},"content":{"rendered":"<p>AlAlerta ao mercado<\/p>\n<p>A Superintend\u00eancia de Rela\u00e7\u00f5es com o Mercado e Intermedi\u00e1rios (SMI) da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM) alerta que a empresa TF Trading Ltd. n\u00e3o est\u00e1 autorizada pela Autarquia a captar clientes residentes no Brasil para realiza\u00e7\u00e3o de opera\u00e7\u00f5es no mercado Forex.<\/p>\n<p>De acordo com o Ato Declarat\u00f3rio CVM 15.464, a empresa n\u00e3o integra o sistema de distribui\u00e7\u00e3o previsto no art. 15 da Lei 6.385\/76.<\/p>\n<p>No entanto, foi detectada poss\u00edvel capta\u00e7\u00e3o de clientes atrav\u00e9s do site institucional (https:\/\/www.turboforex.com\/pt). Diante disso, a \u00e1rea t\u00e9cnica da CVM determinou a imediata suspens\u00e3o de veicula\u00e7\u00e3o de qualquer oferta p\u00fablica de oportunidades de investimento no mercado Forex, de forma direta ou indireta, inclusive por meio da p\u00e1gina na Internet acima citada.<\/p>\n<p>Caso n\u00e3o cumpra a determina\u00e7\u00e3o, a TF Trading Ltd. ficar\u00e1 sujeita \u00e0 aplica\u00e7\u00e3o de multa cominat\u00f3ria di\u00e1ria individual no valor de R$ 1.000,00, sem preju\u00edzo da responsabilidade pelas infra\u00e7\u00f5es cometidas antes da publica\u00e7\u00e3o do referido Ato Declarat\u00f3rio, com a imposi\u00e7\u00e3o das penalidades cab\u00edveis, nos termos do art. 11 da Lei 6.385.<\/p>\n<p>Lembre-se!<\/p>\n<p>Caso seja investidor ou receba proposta de investimento por parte da empresa mencionada, entre em contato com a CVM atrav\u00e9s do Servi\u00e7o de Atendimento ao Cidad\u00e3o (SAC), preferencialmente fornecendo detalhes da oferta e a identifica\u00e7\u00e3o das pessoas envolvidas, a fim de que seja poss\u00edvel a pronta atua\u00e7\u00e3o da Autarquia no caso.<\/p>\n<p>Mais informa\u00e7\u00f5es<\/p>\n<p>A SMI destaca que as opera\u00e7\u00f5es realizadas no mercado Forex envolvem negocia\u00e7\u00f5es com pares de moedas estrangeiras, revelando a exist\u00eancia de instrumentos financeiros por meio dos quais s\u00e3o transacionadas taxas de c\u00e2mbio. Trata-se assim de contratos derivativos, cuja oferta p\u00fablica no Brasil deve ser autorizada pela CVM, nos termos da Lei 6.385\/76.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AlAlerta ao mercado A Superintend\u00eancia de Rela\u00e7\u00f5es com o Mercado e Intermedi\u00e1rios (SMI) da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM) alerta que a empresa TF Trading Ltd. n\u00e3o est\u00e1 autorizada pela Autarquia a captar clientes residentes no Brasil para realiza\u00e7\u00e3o de opera\u00e7\u00f5es no mercado Forex. De acordo com o Ato Declarat\u00f3rio CVM 15.464, a empresa n\u00e3o integra o sistema de distribui\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[],"class_list":["post-4120","post","type-post","status-publish","format-standard","hentry","category-servidor"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=4120"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4120\/revisions"}],"predecessor-version":[{"id":4121,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/4120\/revisions\/4121"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=4120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=4120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=4120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}