{"id":3489,"date":"2016-11-10T12:57:17","date_gmt":"2016-11-10T14:57:17","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=3489"},"modified":"2016-11-10T12:57:17","modified_gmt":"2016-11-10T14:57:17","slug":"pec-do-teto-avanca-no-senado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/pec-do-teto-avanca-no-senado\/","title":{"rendered":"PEC do teto avan\u00e7a no Senado"},"content":{"rendered":"<p><em>Proposta que limita gastos p\u00fablicos por 20 anos passa na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e vai a vota\u00e7\u00e3o no plen\u00e1rio da Casa. Expectativa do governo \u00e9 que ela seja aprovada em dezembro e comece a vigorar em janeiro de 2017. Relator da mat\u00e9ria, Eun\u00edcio Oliveira (PMDB-CE) manteve os recursos para o Fies e o Fundeb fora da restri\u00e7\u00e3o<\/em><\/p>\n<p><strong>ANTONIO TEM\u00d3TEO<\/strong><\/p>\n<p>O governo conseguiu mais uma vit\u00f3ria ao aprovar na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ), do Senado, a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) n\u00ba 55, de 2016, que limita o crescimento dos gastos p\u00fablicos. Dos integrantes do colegiado, 19 votaram favoravelmente ao texto do relator, senador Eun\u00edcio Oliveira (PMDB-CE), e apenas sete se posicionaram de maneira contr\u00e1ria. O texto segue agora para o plen\u00e1rio da Casa, que come\u00e7ar\u00e1 as discuss\u00f5es sobre o tema em 17 de novembro.<\/p>\n<p>Conforme calend\u00e1rio definido pelo presidente do Senado, Renan Calheiros (PMDB-AL), a mat\u00e9ria deve ser apreciada em 1\u00ba turno em 29 de novembro e em 2\u00ba turno em 13 de dezembro. O relator rejeitou 59 emendas e tr\u00eas votos em separado, dos senadores Randolfe Rodrigues (Rede-AP), Roberto Requi\u00e3o (PMDB-PR) e Vanessa Grazziotin (PCdoB-AM). Al\u00e9m disso, o colegiado n\u00e3o acatou emenda da senadora Gleisi Hoffmann (PR-PR), que previa um referendo popular sobre o tema.<\/p>\n<p>Eun\u00edcio Oliveira afirmou que programas essenciais, como vincula\u00e7\u00f5es ao Fundo de Financiamento Estudantil (Fies) e ao Fundo de Manuten\u00e7\u00e3o e Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (Fundeb) est\u00e3o exclu\u00eddos do teto. \u201cO Senado n\u00e3o deve adiar o in\u00edcio do novo regime fiscal. A PEC n\u00e3o pro\u00edbe aumento de gastos em nenhuma \u00e1rea, apenas requer que eles estejam submetidos a um limite. Se for necess\u00e1rio expandir despesas com seguran\u00e7a e ci\u00eancia e tecnologia, por exemplo, ou em qualquer outra \u00e1rea, o Congresso ser\u00e1 soberano ao faz\u00ea-lo\u201d, afirmou o senador.<\/p>\n<p>A reda\u00e7\u00e3o aprovada pela comiss\u00e3o prev\u00ea como limite para o aumento dos gastos p\u00fablicos, em cada exerc\u00edcio, a infla\u00e7\u00e3o acumulada em 12 meses at\u00e9 junho do ano anterior. Para 2017, ser\u00e1 utilizada a taxa de 7,2%, prevista na proposta or\u00e7ament\u00e1ria. O prazo de vig\u00eancia da PEC ser\u00e1 de 20 anos, com possibilidade de altera\u00e7\u00e3o a partir do d\u00e9cimo ano.<\/p>\n<p>A sess\u00e3o que discutiu o texto chegou a ser interrompida para que manifestantes contr\u00e1rios ao tema fossem retirados do plen\u00e1rio. A oposi\u00e7\u00e3o usou de diversos requerimentos para tentar protelar a vota\u00e7\u00e3o, mas, apesar das manobras, o texto foi aprovado excluindo os gastos com sa\u00fade da regra do teto at\u00e9 2018. Al\u00e9m disso, para 2017, foi aumentado de 13,2% para 15% da receita corrente l\u00edquida (RCL) o percentual m\u00ednimo que o governo precisa destinar a essa \u00e1rea.<\/p>\n<p>O relator destacou que as despesas com sa\u00fade e educa\u00e7\u00e3o continuar\u00e3o respeitando o m\u00ednimo constitucional em 2017 e, a partir de 2018, passar\u00e3o a ser corrigidas pela infla\u00e7\u00e3o. \u201cNo caso da sa\u00fade, os disp\u00eandios ficar\u00e3o em R$ 112 bilh\u00f5es no pr\u00f3ximo ano, acima dos R$ 95 bilh\u00f5es de 2016\u201d, disse<\/p>\n<p><strong>Penalidades<\/strong><\/p>\n<p>Se houver descumprimento do limite em determinado ano, no exerc\u00edcio seguinte os \u00f3rg\u00e3os respons\u00e1veis sofrer\u00e3o san\u00e7\u00f5es. Uma delas veda qualquer medida que \u201cimplique reajuste de despesa obrigat\u00f3ria acima da varia\u00e7\u00e3o da infla\u00e7\u00e3o. O reajuste do sal\u00e1rio m\u00ednimo pela infla\u00e7\u00e3o est\u00e1 assegurado, mas h\u00e1 veda\u00e7\u00f5es para aumentos superiores em caso de descumprimento do teto pelos Poderes. Em caso de viola\u00e7\u00e3o do limite, os servidores ter\u00e3o os sal\u00e1rios congelados, sem direito \u00e0 reposi\u00e7\u00e3o inflacion\u00e1ria hoje garantida pela Constitui\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proposta que limita gastos p\u00fablicos por 20 anos passa na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e vai a vota\u00e7\u00e3o no plen\u00e1rio da Casa. Expectativa do governo \u00e9 que ela seja aprovada em dezembro e comece a vigorar em janeiro de 2017. Relator da mat\u00e9ria, Eun\u00edcio Oliveira (PMDB-CE) manteve os recursos para o Fies e o Fundeb fora da restri\u00e7\u00e3o ANTONIO [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[2187,2094,1169,2156,4175,4237,2776,696,642],"class_list":["post-3489","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-ccj","tag-descumprimento","tag-gastos","tag-pec","tag-pec-55","tag-penalidades","tag-plenario","tag-senado","tag-teto"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"predecessor-version":[{"id":3490,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3489\/revisions\/3490"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}