{"id":3068,"date":"2016-10-05T14:01:18","date_gmt":"2016-10-05T17:01:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=3068"},"modified":"2016-10-05T14:01:18","modified_gmt":"2016-10-05T17:01:18","slug":"cirurgia-para-mudar-sexo-no-registro-civil-nao-e-necessaria-diz-corregedor","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/cirurgia-para-mudar-sexo-no-registro-civil-nao-e-necessaria-diz-corregedor\/","title":{"rendered":"Cirurgia para mudar sexo no registro civil n\u00e3o \u00e9 necess\u00e1ria, diz corregedor"},"content":{"rendered":"<p>O corregedor nacional de Justi\u00e7a, ministro Jo\u00e3o Ot\u00e1vio de Noronha, entende que n\u00e3o \u00e9 exigida cirurgia de mudan\u00e7a de sexo para alterar o nome no registro civil, como j\u00e1 decidiu o CNJ em julgamentos passados. A afirma\u00e7\u00e3o foi feita em decis\u00e3o desta ter\u00e7a-feira (4\/10)\u00a0ao pedido liminar\u00a0da\u00a0Defensoria P\u00fablica da Uni\u00e3o\u00a0que\u00a0afirma que magistrados e cart\u00f3rios est\u00e3o condicionando a retifica\u00e7\u00e3o do registro civil \u00e0 cirurgia de redesigna\u00e7\u00e3o sexual.<\/p>\n<p>Desta forma, o corregedor nacional determinou que as corregedorias dos Tribunais de Justi\u00e7a dos estados e do Distrito Federal e os cart\u00f3rios t\u00eam at\u00e9 15 dias para informarem expressamente se a n\u00e3o exig\u00eancia da cirurgia j\u00e1 foi objeto de regulamenta\u00e7\u00e3o, bem como se est\u00e1 havendo problemas quanto a isso, como alega a Defensoria P\u00fablica da Uni\u00e3o.<\/p>\n<p>Na mesma liminar, o ministro Noronha reafirmou que todos os cidad\u00e3os t\u00eam direito de pleitear mudan\u00e7a nas informa\u00e7\u00f5es pessoais do registro de nascimento, mas desde que percorram o mesmo caminho jur\u00eddico. O corregedor negou pedido formulado pela Defensoria P\u00fablica da Uni\u00e3o para que o CNJ emita orienta\u00e7\u00e3o a todos os cart\u00f3rios do pa\u00eds a fim de que fa\u00e7am a mudan\u00e7a de nome e sexo de pessoas trans, travestis e transexuais nos registros civis sem decis\u00e3o judicial.<\/p>\n<p>O corregedor nacional de Justi\u00e7a fundamentou a decis\u00e3o nos princ\u00edpios da isonomia e da seguran\u00e7a jur\u00eddica. \u201cO sistema registral adota como princ\u00edpios b\u00e1sicos a seguran\u00e7a jur\u00eddica como norte para evitar quaisquer tipos de condutas que busquem poss\u00edvel isen\u00e7\u00e3o de responsabilidade civil ou penal\u201d, ressaltou o ministro Noronha na liminar.<\/p>\n<p><strong>Testemunhas<\/strong> &#8211; A decis\u00e3o destaca que a Lei de Registros P\u00fablicos, no artigo 40, j\u00e1 prev\u00ea que qualquer cidad\u00e3o brasileiro pode alterar, retirar ou acrescentar\u00a0informa\u00e7\u00f5es, desde que com peti\u00e7\u00e3o fundamentada com documentos e indica\u00e7\u00e3o de testemunhas. O procedimento judicial sum\u00e1rio prev\u00ea que a decis\u00e3o seja proferida em 5 dias, se n\u00e3o houver impugna\u00e7\u00e3o, ap\u00f3s o Minist\u00e9rio P\u00fablico se pronunciar.<\/p>\n<p>Ap\u00f3s o envio das informa\u00e7\u00f5es solicitadas pelo corregedor nacional, a mat\u00e9ria ser\u00e1 analisada\u00a0e, posteriormente,\u00a0levada \u00e0 aprecia\u00e7\u00e3o do plen\u00e1rio do CNJ.<\/p>\n<p><em>Corregedoria Nacional de Justi\u00e7a<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O corregedor nacional de Justi\u00e7a, ministro Jo\u00e3o Ot\u00e1vio de Noronha, entende que n\u00e3o \u00e9 exigida cirurgia de mudan\u00e7a de sexo para alterar o nome no registro civil, como j\u00e1 decidiu o CNJ em julgamentos passados. A afirma\u00e7\u00e3o foi feita em decis\u00e3o desta ter\u00e7a-feira (4\/10)\u00a0ao pedido liminar\u00a0da\u00a0Defensoria P\u00fablica da Uni\u00e3o\u00a0que\u00a0afirma que magistrados e cart\u00f3rios est\u00e3o condicionando a retifica\u00e7\u00e3o do registro civil [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[3765,3761,1319,254,3764,3763,2789,617,2902,2625,3762,3766,3768,3767],"class_list":["post-3068","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-alterar","tag-cirurgia","tag-civil","tag-cnj","tag-corregedor","tag-desnecessaria","tag-dpu","tag-liminar","tag-mudar","tag-registro","tag-sexo","tag-trans","tag-transexuais","tag-travestis"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=3068"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3068\/revisions"}],"predecessor-version":[{"id":3069,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/3068\/revisions\/3069"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=3068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=3068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=3068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}