{"id":2758,"date":"2016-08-23T16:01:12","date_gmt":"2016-08-23T19:01:12","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=2758"},"modified":"2016-08-23T16:01:12","modified_gmt":"2016-08-23T19:01:12","slug":"caiado-apresenta-questao-de-ordem-para-invalidar-sessao-da-cae","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/caiado-apresenta-questao-de-ordem-para-invalidar-sessao-da-cae\/","title":{"rendered":"Caiado apresenta quest\u00e3o de ordem para invalidar sess\u00e3o da CAE"},"content":{"rendered":"<p>O l\u00edder do Democratas no Senado, Ronaldo Caiado (GO), vai entrar com quest\u00e3o de ordem para anular a vota\u00e7\u00e3o do PLC 32\/2016, que reajusta os sal\u00e1rios dos defensores p\u00fablicos, quando j\u00e1 havia sido iniciada a ordem do dia no Congresso Nacional. Essa a\u00e7\u00e3o n\u00e3o \u00e9 permitida pelo regimento interno das duas Casas. Durante sess\u00e3o do Congresso, o presidente do Senado anunciou que todas as vota\u00e7\u00f5es durante a reuni\u00e3o do parlamento seriam anuladas. Ao longo da reuni\u00e3o da CAE, Caiado foi contr\u00e1rio a mais reajustes de servidores enquanto o pa\u00eds n\u00e3o recuperar a economia e reduzir o desemprego. Ele questionou a incoer\u00eancia de senadores petistas que criticam pagamento de juros, mas defendem o crescimento das despesas da Uni\u00e3o com esses reajustes.<\/p>\n<p>\u201cN\u00e3o podemos nos deixar levar para um lado populista na discuss\u00e3o de reajustes de servidores p\u00fablicos. Fizeram uma vota\u00e7\u00e3o sorrateira, irregular na Comiss\u00e3o de Assuntos Econ\u00f4micos de aumento de sal\u00e1rio dos defensores p\u00fablicos quando j\u00e1 havia sido iniciada ordem do dia na sess\u00e3o do Congresso Nacional, o que n\u00e3o \u00e9 permitido pelo regimento interno. Impressiona a incoer\u00eancia do PT em apoiar e querer pressa na vota\u00e7\u00e3o. Eles criticam pagamento de juros, mas como o governo com or\u00e7amento deficit\u00e1rio vai arcar com esse aumento sem contrair empr\u00e9stimos?\u201d, argumentou o parlamentar antes do encerramento da sess\u00e3o da CAE.<\/p>\n<p>O l\u00edder defendeu que a popula\u00e7\u00e3o, incluindo servidores p\u00fablicos, devem dar sua cota de sacrif\u00edcio pela recupera\u00e7\u00e3o do pa\u00eds. \u201c\u00c9 hora de escolhermos se vamos seguir com esse modelo implantado por Lula e Dilma nos \u00faltimos 13 anos que deixou o pa\u00eds no caos, com desemprego, infla\u00e7\u00e3o e o pior momento da sa\u00fade j\u00e1 visto ou se todos v\u00e3o dar sua cota de sacrif\u00edcio pela recupera\u00e7\u00e3o do Brasil. Minha posi\u00e7\u00e3o n\u00e3o \u00e9 contr\u00e1ria aos defensores p\u00fablicos, mas o de dar prioridade aos desempregados e aos pacientes que est\u00e3o morrendo a espera de atendimento no SUS. Depois de arrumarmos essa bagun\u00e7a que o PT deixou, vamos ter a sensibilidade de retomar esse projeto que trata de quem tem estabilidade\u201d, disse.<\/p>\n<p>Caiado criticou tanto senadores pr\u00f3-Dilma como os que sustentam o governo Temer por defender projetos que comprometem o ajuste fiscal e o resgate do emprego de 12 milh\u00f5es de brasileiros. \u201cQuestiono a postura dos senadores da ex-base de presidente Dilma, mas tamb\u00e9m do governo de Michel Temer. Vimos o pr\u00f3prio presidente e sua equipe defender ajuste fiscal e os senadores de sua base est\u00e3o com posi\u00e7\u00e3o diferente. Estamos votando a favor de um projeto de milh\u00f5es de pessoas que foram as ruas\u201d, encerrou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O l\u00edder do Democratas no Senado, Ronaldo Caiado (GO), vai entrar com quest\u00e3o de ordem para anular a vota\u00e7\u00e3o do PLC 32\/2016, que reajusta os sal\u00e1rios dos defensores p\u00fablicos, quando j\u00e1 havia sido iniciada a ordem do dia no Congresso Nacional. Essa a\u00e7\u00e3o n\u00e3o \u00e9 permitida pelo regimento interno das duas Casas. Durante sess\u00e3o do Congresso, o presidente do Senado [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[3156,2780,2708,100,2807,3430,1945,2744,24,3429,63,30,696,2227],"class_list":["post-2758","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-apresenta","tag-cae","tag-caiado","tag-congresso","tag-defensores","tag-invalidar","tag-ordem","tag-plc-322016","tag-publicos","tag-questao","tag-reajuste","tag-salarios","tag-senado","tag-sessao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=2758"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2758\/revisions"}],"predecessor-version":[{"id":2759,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2758\/revisions\/2759"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=2758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=2758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=2758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}