{"id":2559,"date":"2016-08-05T12:29:36","date_gmt":"2016-08-05T15:29:36","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=2559"},"modified":"2016-08-05T12:29:36","modified_gmt":"2016-08-05T15:29:36","slug":"reforma-da-previdencia-cria-divisao-no-governo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/reforma-da-previdencia-cria-divisao-no-governo\/","title":{"rendered":"Reforma da Previd\u00eancia cria divis\u00e3o no governo"},"content":{"rendered":"<p><span style=\"font-size: medium\"><em>Unifica\u00e7\u00e3o dos sistemas previdenci\u00e1rios de servidores civis, militares e trabalhadores da iniciativa privada provoca choque entre a Casa Civil e o Minist\u00e9rio da Defesa. For\u00e7as Armadas querem manter regime pr\u00f3prio que garante benef\u00edcios \u00e0 carreira. Para especialista, pens\u00e3o de militares \u00e9 pouco discutida. Deficit atuarial da categoria era de R$ 1,3 trilh\u00e3o. Jungmann alega que membros da caserna n\u00e3o t\u00eam direitos garantidos aos civis<\/em> <\/span><\/p>\n<p><strong><span style=\"font-size: medium\">CELIA PERRONE<\/span><\/strong><\/p>\n<p><span style=\"font-size: medium\">O governo come\u00e7ou a rachar em rela\u00e7\u00e3o \u00e0 reforma da Previd\u00eancia antes mesmo de o projeto ficar pronto. O ministro da Defesa, Raul Jungmann, e o da Casa Civil, Eliseu Padilha, divergem em rela\u00e7\u00e3o \u00e0 proposta de unificar os sistemas previdenci\u00e1rios de trabalhadores da iniciativa privada, servidores e militares. Jungmann \u00e9 contra a unifica\u00e7\u00e3o. \u201cOs integrantes da carreira militar s\u00e3o obrigados a renunciar a uma s\u00e9rie de direitos que s\u00e3o garantidos aos servidores civis\u201d, tem dito ele em reuni\u00f5es em que o assunto vem \u00e0 baila. Para Padilha, n\u00e3o pode haver distin\u00e7\u00e3o e \u00e9 preciso que todos deem sua cota de sacrif\u00edcio e abram m\u00e3o de privil\u00e9gios. <\/span><\/p>\n<p><span style=\"font-size: medium\">Ex-ministro da Previd\u00eancia no governo Fernando Henrique Cardoso, Jos\u00e9 Cechin considera natural que setores da sociedade lutem para preservar benef\u00edcios, mas diz que cabe ao governo decidir. \u201cA carreira militar \u00e9 altamente hierarquizada, com afunilamento progressivo, e tem de ser assim. Isso a faz diferente das outras, mas n\u00e3o justifica que ela tenha privil\u00e9gios em rela\u00e7\u00e3o \u00e0s demais\u201d, ressaltou. <\/span><\/p>\n<p><span style=\"font-size: medium\">Cechin explicou que, ap\u00f3s exercer por 10 anos a mesma fun\u00e7\u00e3o, o militar \u00e9 obrigatoriamente reformado. \u201cEsse \u00e9 um dado t\u00edpico dos militares no mundo inteiro. No entanto, n\u00e3o necessariamente ele deve ser promovido e levar o \u00faltimo sal\u00e1rio integral para o resto da vida. Deve receber o valor mensal correspondente ao que contribuiu. H\u00e1 que se reconhecer o esfor\u00e7o contributivo de cada um\u201d, defendeu. <\/span><\/p>\n<p><span style=\"font-size: medium\">O professor da Escola Brasileira de Administra\u00e7\u00e3o P\u00fablica e de Empresas da Funda\u00e7\u00e3o Getulio Vargas (Ebape\/ FGV) Istvan Karoly Kasznar salienta que a Constitui\u00e7\u00e3o estabelece que todos s\u00e3o iguais perante a lei. Portanto, ela \u00e9 desrespeitada quando se proporciona aposentadoria integral para funcion\u00e1rios p\u00fablicos civis e militares, e o mesmo n\u00e3o \u00e9 concedido a trabalhadores da iniciativa privada. Ele concorda, contudo, que a categoria militar tem certas peculiaridades que devem ser contempladas na legisla\u00e7\u00e3o. <\/span><\/p>\n<p><strong>Guerra<\/strong><\/p>\n<p>\u201c<span style=\"font-size: medium\">A lei deve ter a flexibilidade de prever que militares e civis sejam tratados igualmente em tempos de paz e de modo diferenciado em \u00e9pocas de periculosidade, como uma guerra. A \u00faltima vez que o Brasil mandou homens para um conflito foi na Segunda Guerra Mundial. J\u00e1 se v\u00e3o mais de 70 anos\u201d, argumentou Kasznar. \u201cTamb\u00e9m temos que olhar os riscos que policiais militares correm em cidades como S\u00e3o Paulo e Rio de Janeiro. S\u00f3 neste ano 70 policiais civis e militares morreram no Rio. A aposentadoria especial e pens\u00f5es para mulheres e filhos desses policiais, nesses casos, \u00e9 essencial\u201d, frisou. <\/span><\/p>\n<p><span style=\"font-size: medium\">O professor Jos\u00e9 Roberto da Sav\u00f3ia, da Universidade de S\u00e3o Paulo (USP), que foi secret\u00e1rio de Previd\u00eancia Social de 2001 a 2003, ressaltou que o sistema de previd\u00eancia dos militares \u00e9 tratado como um n\u00e3o assunto pelo governo. \u201cFalta transpar\u00eancia. A pens\u00e3o dos militares n\u00e3o \u00e9 tema de an\u00e1lises. No balan\u00e7o da Uni\u00e3o n\u00e3o aparece o regime militar, mas precisamos mudar esses par\u00e2metros\u201d, afirmou. \u201cO per\u00edodo mais curto de atividade talvez seja o ponto mais cr\u00edtico para a constru\u00e7\u00e3o de uma proposta mas, contornando isso, podemos, sim, fazer a unifica\u00e7\u00e3o dos sistemas. As regras de proporcionalidade caberiam na aposentadoria do militar. O que n\u00e3o d\u00e1 mais \u00e9 carregar o deficit atuarial dessa categoria que atingiu a astron\u00f4mica cifra de R$ 1,3 trilh\u00e3o em 2014\u201d, disse.<\/span><\/p>\n<p><strong><span style=\"font-size: medium\">Preocupa\u00e7\u00e3o <\/span><\/strong><\/p>\n<p><span style=\"font-size: medium\">A reforma do sistema previdenci\u00e1rio tem causado inquieta\u00e7\u00e3o no<\/span> <span style=\"font-size: medium\">Minist\u00e9rio da Defesa. Na pasta, o assunto \u00e9 acompanhado e discutido em reuni\u00f5es com a participa\u00e7\u00e3o do secret\u00e1rio-geral do minist\u00e9rio, Joaquim Silva e Luna e<\/span> <span style=\"font-size: medium\">representantes da Marinha, do Ex\u00e9rcito e da Aeron\u00e1utica. Jungmann observa que as discuss\u00f5es ainda s\u00e3o preliminares. Portanto, ser\u00e1 poss\u00edvel chegar a um projeto de consenso, e que o que for decidido ser\u00e1 acatado<\/span>. \u201cMas acho justo um tratamento diferenciado para os militares\u201d, frisa.<\/p>\n<p><span style=\"font-size: medium\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unifica\u00e7\u00e3o dos sistemas previdenci\u00e1rios de servidores civis, militares e trabalhadores da iniciativa privada provoca choque entre a Casa Civil e o Minist\u00e9rio da Defesa. For\u00e7as Armadas querem manter regime pr\u00f3prio que garante benef\u00edcios \u00e0 carreira. Para especialista, pens\u00e3o de militares \u00e9 pouco discutida. Deficit atuarial da categoria era de R$ 1,3 trilh\u00e3o. Jungmann alega que membros da caserna n\u00e3o t\u00eam [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[766,1035,3192,3096,98,855,51,3193,3194,549,1295,3191,58,1779,159],"class_list":["post-2559","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-casa-civil","tag-civis","tag-divisao","tag-forcas-armadas","tag-governo","tag-jungmann","tag-militares","tag-ministerio-defesa","tag-padilha","tag-previdencia","tag-privada","tag-refporma","tag-servidores","tag-sistemas","tag-unificacao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=2559"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2559\/revisions"}],"predecessor-version":[{"id":2560,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/2559\/revisions\/2560"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=2559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=2559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=2559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}