{"id":20981,"date":"2021-10-25T12:16:17","date_gmt":"2021-10-25T15:16:17","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=20981"},"modified":"2021-10-25T12:16:17","modified_gmt":"2021-10-25T15:16:17","slug":"cartorios-do-brasil-passam-a-receber-denuncias-contra-violencia-domestica","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/cartorios-do-brasil-passam-a-receber-denuncias-contra-violencia-domestica\/","title":{"rendered":"Cart\u00f3rios do Brasil passam a receber den\u00fancias contra viol\u00eancia dom\u00e9stica"},"content":{"rendered":"<p><em><strong>A partir de hoje, Campanha nacional Sinal Vermelho conta com os mais de 13 mil Cart\u00f3rios brasileiros para prestar aux\u00edlio discreto e sigiloso \u00e0s mulheres em situa\u00e7\u00e3o de vulnerabilidade.\u00a0Segundo a AMB, mais de 17 milh\u00f5es de mulheres sofreram viol\u00eancia f\u00edsica, psicol\u00f3gica ou sexual entre agosto de 2020 e julho de 2021, n\u00famero que representa 24,4% da popula\u00e7\u00e3o feminina com mais de 16 anos no Brasil<\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19976 alignleft\" src=\"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2021\/07\/SINAL-VERMELHO.jpeg\" alt=\"\" width=\"480\" height=\"384\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2021\/07\/SINAL-VERMELHO.jpeg 480w, https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2021\/07\/SINAL-VERMELHO-300x240.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2021\/07\/SINAL-VERMELHO-230x184.jpeg 230w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Os mais de 13 mil Cart\u00f3rios brasileiros agora s\u00e3o pontos de apoio \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica. A partir desta segunda-feira (25\/10), todas as unidades do pa\u00eds integram a campanha Sinal Vermelho, que tem como objetivo incentivar e facilitar den\u00fancias de qualquer tipo de abuso dentro do ambiente dom\u00e9stico e que, por meio de um s\u00edmbolo \u201cX\u201d desenhado na palma da m\u00e3o, poder\u00e3o, de maneira discreta, sinalizar ao colaborador a situa\u00e7\u00e3o de vulnerabilidade, que ent\u00e3o acionar\u00e1 a Pol\u00edcia.<\/p>\n<p>A a\u00e7\u00e3o nacional permanente integra a Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg\/BR), entidade que representa todos os Cart\u00f3rios do pa\u00eds, a uma iniciativa nacional da Associa\u00e7\u00e3o dos Magistrados Brasileiros (AMB) e do Conselho Nacional de Justi\u00e7a (CNJ), j\u00e1 transformada em Lei Federal n\u00ba 14.188, de 28 de julho de 2021 -, como uma das medidas de enfrentamento da viol\u00eancia dom\u00e9stica e familiar contra a mulher previstas na Lei n\u00ba 11.340, de 7 de agosto de 2006 (Lei Maria da Penha), e no Decreto-Lei n\u00ba 2.848, de 7 de dezembro de 1940 (C\u00f3digo Penal).<\/p>\n<p>Para integrar os Cart\u00f3rios \u00e0 iniciativa, a Anoreg\/BR produziu e disponibilizou uma s\u00e9rie de materiais \u00e0s unidades de todo o pa\u00eds, como v\u00eddeos, cartilha, cartazes e materiais para as redes sociais, de forma a preparar os funcion\u00e1rios para oferecer aux\u00edlio \u2013 abrigando a mulher em uma sala da unidade \u2013 e acionar as autoridades. Caso a v\u00edtima n\u00e3o queira ou n\u00e3o possa ter aux\u00edlio no momento, os profissionais dever\u00e3o anotar seus dados pessoais \u2013 nome, CPF, RG e telefone \u2013 e comunicar posteriormente as autoridades respons\u00e1veis.<\/p>\n<p>\u201cOs Cart\u00f3rios foram considerados servi\u00e7os essenciais durante todo esse per\u00edodo de pandemia, seja pelos atos de cidadania que praticam, seja pela seguran\u00e7a jur\u00eddica que emprestam aos atos pessoais e patrimoniais das pessoas, de forma que usar sua presen\u00e7a em todo o territ\u00f3rio nacional como forma de atuar na prote\u00e7\u00e3o das mulheres, ainda mais fragilizadas neste momento, \u00e9 um papel que n\u00e3o devemos nos furtar\u201d, destaca o presidente da Anoreg\/BR, Claudio Mar\u00e7al Freire.<\/p>\n<p>N\u00fameros divulgados pela AMB apontam que mais de 17 milh\u00f5es de mulheres sofreram viol\u00eancia f\u00edsica, psicol\u00f3gica ou sexual entre agosto de 2020 e julho de 2021, n\u00famero que representa 24,4% da popula\u00e7\u00e3o feminina com mais de 16 anos que reside no Brasil. J\u00e1 as chamadas para o n\u00famero 180, servi\u00e7o que registra e encaminha den\u00fancias de viol\u00eancia contra a mulher aos \u00f3rg\u00e3os competentes, tiveram aumento de 34% em compara\u00e7\u00e3o ao mesmo per\u00edodo do ano passado, segundo balan\u00e7o do governo federal.<\/p>\n<p><strong>Anoreg\/BR<\/strong><\/p>\n<p>Fundada no dia 4 de maio de 1984, com sede na cidade de Bras\u00edlia (DF), a Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg\/BR) \u00e9 a \u00fanica entidade da classe com legitimidade, reconhecida pelos poderes constitu\u00eddos, para representar os titulares de servi\u00e7os notariais e de registro do Brasil em qualquer inst\u00e2ncia ou Tribunal, operando em harmonia e coopera\u00e7\u00e3o direta com outras associa\u00e7\u00f5es cong\u00eaneres, principalmente com os Institutos Membros e Sindicatos, representativos das especialidades. \u00c9 regida pelo C\u00f3digo Civil brasileiro, pelas demais disposi\u00e7\u00f5es legais aplic\u00e1veis e pelo Estatuto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de hoje, Campanha nacional Sinal Vermelho conta com os mais de 13 mil Cart\u00f3rios brasileiros para prestar aux\u00edlio discreto e sigiloso \u00e0s mulheres em situa\u00e7\u00e3o de vulnerabilidade.\u00a0Segundo a AMB, mais de 17 milh\u00f5es de mulheres sofreram viol\u00eancia f\u00edsica, psicol\u00f3gica ou sexual entre agosto de 2020 e julho de 2021, n\u00famero que representa 24,4% da popula\u00e7\u00e3o feminina com mais [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[13623,19429,1550,164,19430,142,439,9294,11429,11545,27,5252,1263,19433,1415,545,6435,3476,19431,11623,9667,19432],"class_list":["post-20981","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-amp","tag-anoreg","tag-auxilio","tag-brasil","tag-campanha-sinal-vermelho","tag-cartorios","tag-cidadania","tag-codigo-penal","tag-discreto","tag-feminina","tag-fisica","tag-lei-maria-da-penha","tag-mulheres","tag-palma-da-mao","tag-politica","tag-populacao","tag-psicologica","tag-sexual","tag-sigiloso","tag-violencia-domestica","tag-vulnerabilidade","tag-x"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/20981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=20981"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/20981\/revisions"}],"predecessor-version":[{"id":20982,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/20981\/revisions\/20982"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=20981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=20981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=20981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}