{"id":18248,"date":"2020-11-09T11:05:55","date_gmt":"2020-11-09T14:05:55","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=18248"},"modified":"2020-11-09T11:07:11","modified_gmt":"2020-11-09T14:07:11","slug":"a-quem-interessa-a-falencia-da-geap","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/a-quem-interessa-a-falencia-da-geap\/","title":{"rendered":"A quem interessa a fal\u00eancia da Geap"},"content":{"rendered":"<p><em><strong>Na nota com o t\u00edtulo &#8220;A quem interessa a fal\u00eancia da Geap&#8221;, a Anasps informa que a not\u00edcia veiculada pela Geap, maior operadora de plano de sa\u00fade do funcionalismo, de que a Associa\u00e7\u00e3o teria perdido uma a\u00e7\u00e3o na Justi\u00e7a, n\u00e3o \u00e9 verdadeira. &#8220;Primeiro, a senten\u00e7a ainda permite recurso. Vamos fazer. Segundo a ANASPS n\u00e3o est\u00e1 jogando batalha naval, logo n\u00e3o perde. Apenas direitos s\u00e3o expropriados. Terceiro, se alguma coisa n\u00e3o vai bem ou se as normas e regras estatut\u00e1rias n\u00e3o s\u00e3o respeitadas, quem perde s\u00e3o os participantes e a pr\u00f3pria GEAP. Esse \u00e9 o caso&#8221;, destaca.<\/strong><\/em><\/p>\n<p>A entidade refor\u00e7a, ainda, que se a operadora que\u00a0falar de ganhar e perder, deveria divulgar v\u00e1rios dados, tais como: &#8220;1. Por que a Diretoria Executiva n\u00e3o traz a p\u00fablico quantos idosos perderam seu plano de sa\u00fade da GEAP nos \u00faltimos 05 anos?\u00a02. Por que a Diretoria Executiva n\u00e3o divulga os n\u00fameros dos reajustes dos planos nos \u00faltimos 05 anos? Ser\u00e1 que os reajustes foram iguais a infla\u00e7\u00e3o ou aos reajustes salariais pagos aos servidores pelo Governo? Quantos idosos perderam seu plano de sa\u00fade pelos reajustes abusivos?\u00a03. Por que a Diretoria Executiva n\u00e3o divulga seus sal\u00e1rios mensalmente na capa do site? Afinal de contas, os recursos que s\u00e3o repassados para a GEAP pelos patrocinadores s\u00e3o p\u00fablicos? Que a contribui\u00e7\u00e3o anual dos benefici\u00e1rios ultrapassa R$ 5 bilh\u00f5es de reais? Quanto aos idosos que perderam seu dinheiro que foi usado para pagar sal\u00e1rios de Diretores que n\u00e3o respeitam seus direitos&#8221;.<\/p>\n<p>Veja a nota:<\/p>\n<p>&#8220;A vida de milhares de idosos n\u00e3o \u00e9 um jogo de ganhar e perder<\/p>\n<p>Este ano a GEAP ter\u00e1 elei\u00e7\u00f5es para o CONAD e CONFIS para escolha de representantes eleitos pelos participantes. Ser\u00e3o eleitos 5 conselheiros titulares e 5 suplentes. Os conselhos t\u00eam a atribui\u00e7\u00e3o de decidir os rumos da gest\u00e3o (CONAD) e a atuar na fiscaliza\u00e7\u00e3o dos gastos (CONFIS) da Diretoria Executiva da GEAP. O momento \u00e9 muito importante e, diferentemente de toda a hist\u00f3ria da GEAP, a atual Diretoria Executiva tem tentado interferir ilegalmente nas elei\u00e7\u00f5es. A ANASPS, que representa milhares de participantes, vem atuando com lupa para impedir que ocorram fraudes e desmandos nas elei\u00e7\u00f5es. Para isso, temos ajuizado a\u00e7\u00f5es judiciais para garantir paridade, lisura e transpar\u00eancia nas elei\u00e7\u00f5es. Isso, \u00e9 claro, tem incomodado a Diretoria Executiva da GEAP.<\/p>\n<p>\u00c9 muito triste quando a vida de milhares de idosos \u00e9 tratada como uma partida de batalha naval. Uma brincadeira de crian\u00e7as. Chega a ser humilhante constatar que militares que juraram zelar pela seguran\u00e7a, integridade e felicidade de seu pa\u00eds possam ter esquecido de seu papel.<\/p>\n<p>Ser\u00e1 que tais pessoas olham para seus pr\u00f3prios pais e av\u00f3s? Ser\u00e1 que n\u00e3o se imaginam como uma pessoa idosa no futuro?<\/p>\n<p>Pois bem, essa \u00e9 a reflex\u00e3o que queremos deixar aos nossos leitores.<\/p>\n<p>Nessa semana foi veiculada not\u00edcia no site da Geap, com o seguinte t\u00edtulo: \u201cANASPS PERDE A\u00c7\u00c3O NA JUSTI\u00c7A CONTRA GEAP, mais uma vez\u201d.<\/p>\n<p>PASMEM, assinada pela Diretoria Executiva da GEAP.<\/p>\n<p>A chamada da mat\u00e9ria caracteriza bem a postura e demonstra a verdadeira inten\u00e7\u00e3o da atual gest\u00e3o.<\/p>\n<p>A Diretoria que deveria estar preocupada com o bem estar dos participantes da GEAP, zomba deles. Tripudia, humilha e ofende. N\u00e3o tem qualquer respeito pelos milhares de idosos da GEAP que s\u00e3o associados da ANASPS.<\/p>\n<p>Evidente que a Diretoria n\u00e3o est\u00e1 preparada para ocupar a fun\u00e7\u00e3o de gerir um dos maiores planos de sa\u00fade do pa\u00eds, cujo custeio \u00e9 realizado quase que exclusivamente pelos participantes (idosos na sua maioria).<\/p>\n<p>Ao contr\u00e1rio do projeto original de cria\u00e7\u00e3o da GEAP, a atual Diretoria tem trabalhado incansavelmente para expulsar os idosos do plano de sa\u00fade. Idosos que contribu\u00edram a vida toda para a GEAP.<\/p>\n<p>Muitos j\u00e1 contribu\u00edam quando os atuais Diretores ainda n\u00e3o tinham autonomia e precisavam usar fraldas. Naquele tempo, entretanto, o que faziam nas fraldas n\u00e3o prejudicava milhares de vidas de idosos&#8230;. muitos poderiam ser seus pr\u00f3prios pais e av\u00f3s.<\/p>\n<p>A ANASPS, no caso, como uma m\u00e3e zelosa e cuidadosa, tem atuado na troca de fraldas para garantir a prote\u00e7\u00e3o de seus associados e idosos, assim como uma m\u00e3e que prima pela higiene e sa\u00fade de seus filhos.<\/p>\n<p>Feito o introito, \u00e9 preciso informar que a lament\u00e1vel not\u00edcia n\u00e3o \u00e9 ver\u00eddica.<\/p>\n<p>Primeiro, a senten\u00e7a ainda permite recurso. Vamos fazer. Segundo a ANASPS n\u00e3o est\u00e1 jogando batalha naval, logo n\u00e3o perde. Apenas direitos s\u00e3o expropriados. Terceiro, se alguma coisa n\u00e3o vai bem ou se as normas e regras estatut\u00e1rias n\u00e3o s\u00e3o respeitadas, quem perde s\u00e3o os participantes e a pr\u00f3pria GEAP. Esse \u00e9 o caso.<\/p>\n<p>Mas se a GEAP quer falar de ganhar e perder, podemos convidar a GEAP a fazer not\u00edcia com os dados da pr\u00f3pria Diretoria Executiva. Vamos l\u00e1:<\/p>\n<p>1. Por que a Diretoria Executiva n\u00e3o traz a p\u00fablico quantos idosos perderam seu plano de sa\u00fade da GEAP nos \u00faltimos 05 anos?<\/p>\n<p>2. Por que a Diretoria Executiva n\u00e3o divulga os n\u00fameros dos reajustes dos planos nos \u00faltimos 05 anos? Ser\u00e1 que os reajustes foram iguais a infla\u00e7\u00e3o ou aos reajustes salariais pagos aos servidores pelo Governo? Quantos idosos perderam seu plano de sa\u00fade pelos reajustes abusivos?<\/p>\n<p>3. Por que a Diretoria Executiva n\u00e3o divulga seus sal\u00e1rios mensalmente na capa do site? Afinal de contas, os recursos que s\u00e3o repassados para a GEAP pelos patrocinadores s\u00e3o p\u00fablicos? Que a contribui\u00e7\u00e3o anual dos benefici\u00e1rios ultrapassa R$ 5 bilh\u00f5es de reais? Quanto aos idosos que perderam seu dinheiro que foi usado para pagar sal\u00e1rios de Diretores que n\u00e3o respeitam seus direitos.<\/p>\n<p>4. Ser\u00e1 que a Diretoria da GEAP perdeu a l\u00edngua para essas perguntas? Ser\u00e1 que perdeu a coragem de apresentar os n\u00fameros verdadeiros?<\/p>\n<p>5. Ser\u00e1 que a Diretoria da GEAP poderia publicar quantas vezes o voto de minerva do Conselho da GEAP foi utilizado para decidir contra a vontade da Diretoria? Nunca. Quem ser\u00e1 que perde com essas decis\u00f5es?<\/p>\n<p>Se quis\u00e9ssemos explorar os resultados dessa brincadeira de batalha naval, quem ser\u00e1 que realmente perdeu? Fa\u00e7a voc\u00ea mesmo as suas an\u00e1lises.<\/p>\n<p>A ANASPS, no seu papel de associa\u00e7\u00e3o, representando milhares de participantes da GEAP tem atuado de forma aguerrida pela defesa e prote\u00e7\u00e3o dos direitos dos seus associados.<\/p>\n<p>Temos defendido judicialmente que os reajustes sejam compat\u00edveis com a infla\u00e7\u00e3o ou, no m\u00ednimo, com os \u00edndices dos planos coletivos autorizados pela ANS.<\/p>\n<p>Temos defendido judicialmente que as regras estatut\u00e1rias sejam respeitadas e que todos os participantes possam participar das elei\u00e7\u00f5es para os conselhos de administra\u00e7\u00e3o e fiscal, sem distin\u00e7\u00e3o. Idosos n\u00e3o podem perder o direito de representa\u00e7\u00e3o.<\/p>\n<p>Temos defendido judicialmente a paridade na representa\u00e7\u00e3o nos \u00f3rg\u00e3os colegiados e comiss\u00f5es eleitorais, de forma a garantir isonomia e transpar\u00eancia aos processos de escolhas de representantes. Idosos n\u00e3o podem perder o direito de decidir.<\/p>\n<p>Temos defendido judicialmente o direito ao parcelamento de valores de contrapartidas, uma vez que os idosos tem perdido sua capacidade de renda e aumentado sua necessidade de atendimento m\u00e9dico-hospitalar.<\/p>\n<p>Temos defendido o direito de milhares de participantes que vem sendo lesados e tendo suas vidas estilha\u00e7adas com o processo de exclus\u00e3o do plano de sa\u00fade da GEAP, depois de d\u00e9cadas contribuindo.<\/p>\n<p>A Diretoria Executiva da GEAP hoje est\u00e1 preocupada apenas em tornar o plano de sa\u00fade solvente, esquecendo-se de que s\u00e3o milhares de fam\u00edlias que est\u00e3o perdendo sua prote\u00e7\u00e3o.<\/p>\n<p>No caso da not\u00edcia veiculada pela GEAP, a a\u00e7\u00e3o proposta pela ANASPS objetiva garantir o direito de ampla representa\u00e7\u00e3o na Comiss\u00e3o Eleitoral que ir\u00e1 regular as elei\u00e7\u00f5es. A Diretoria da GEAP colocou apenas pessoas diretamente ligadas a ela na comiss\u00e3o. Com esse crit\u00e9rio, quem ganha e quem perde? Onde est\u00e1 o representante dos participantes?<\/p>\n<p>Outro ponto discutido pela ANASPS diz respeito a mudan\u00e7a das regras e do sistema eleitoral promovido por aquela comiss\u00e3o eleitoral que tem apenas representantes da Diretoria da GEAP. Por que mudaram as regras? Qual a finalidade? Quem realmente ganha e quem perde?<\/p>\n<p>Tamb\u00e9m foram questionados em ju\u00edzo as expuls\u00f5es dos conselheiros eleitos pelos participantes. Isso mesmo, a Diretoria Executiva da GEAP expulsou os representantes eleitos dos Conselhos para dirigir a GEAP apenas com os seus amigos de jogo \u201cbatalha naval\u201d.<\/p>\n<p>Por fim, a ANASPS tem lutado contra as abusivas e reiteradas altera\u00e7\u00f5es estatut\u00e1rias que tem sido feitas com a utiliza\u00e7\u00e3o do voto de minerva. O que \u00e9 isso? Pois \u00e9, isso \u00e9 uma decis\u00e3o obtida com o voto do amigo da corte, o Presidente do Conselho de Administra\u00e7\u00e3o. Sempre que h\u00e1 empate, o voto do amigo da corte \u00e9 quem decide. Quem ser\u00e1 que perde quando o voto do amigo da corte \u00e9 utilizado?<\/p>\n<p>A atua\u00e7\u00e3o da ANASPS tem sido voltada exclusivamente para proteger todos os benefici\u00e1rios da GEAP, n\u00e3o s\u00f3 os s\u00f3cios, como insinuado. Se n\u00e3o fosse verdade, porque haveria tanto \u00f3dio na Diretoria da GEAP?<\/p>\n<p>Queremos proteger nossa GEAP da fal\u00eancia total, t\u00ednhamos 700 mil benefici\u00e1rios, na administra\u00e7\u00e3o atual estamos com menos de 360 mil, havendo uma redu\u00e7\u00e3o di\u00e1ria no n\u00famero de participantes. Nossa rede de atendimento hoje, em rela\u00e7\u00e3o com outras operadoras, \u00e9 uma piada.<\/p>\n<p>O Conselho aprova tudo com voto de minerva, por isso a preocupa\u00e7\u00e3o da atual dire\u00e7\u00e3o em vencer as elei\u00e7\u00f5es e colocar l\u00e1 somente quem vote com eles. Se os indicados n\u00e3o votam com eles, s\u00e3o substitu\u00eddos.<\/p>\n<p>N\u00e3o compactuamos com aumento abusivo e atualmente os eleitos votaram contra um aumento que, em alguns casos, chegou a 45 %, ao passo que os servidores n\u00e3o t\u00eam e n\u00e3o ter\u00e3o nenhum aumento em seus sal\u00e1rios.<\/p>\n<p>A ANASPS continuar\u00e1 nessa luta incans\u00e1vel de defesa de seus direitos e n\u00e3o poupar\u00e1 esfor\u00e7os e recursos dispon\u00edveis para proteger seus associados em todas as inst\u00e2ncias, inclusive no Judici\u00e1rio. Esse \u00e9 nosso dever e nossa miss\u00e3o.<\/p>\n<p>A ANASPS tem sido incans\u00e1vel para promover a inclus\u00e3o dos seus s\u00f3cios. De oferecer cada dia mais servi\u00e7os e vantagens, diferentemente da Diretoria da GEAP.<\/p>\n<p>A ANASPS tem constru\u00eddo uma hist\u00f3ria de sucesso, com a\u00e7\u00f5es concretas, cuja solidez se verifica com a disponibiliza\u00e7\u00e3o de uma faculdade gratuita para s\u00f3cios, um clube de servi\u00e7os gratuito para s\u00f3cios com milhares de vantagens e, agora, acrescentamos um plano odontol\u00f3gico gratuito para s\u00f3cios.<\/p>\n<p>Como \u00faltima compara\u00e7\u00e3o, perguntamos: O que a GEAP oferece hoje para os benefici\u00e1rios? At\u00e9 mesmo o plano odontol\u00f3gico da GEAP \u00e9 pago, maquiado com nome de coparticipa\u00e7\u00e3o. Quem ser\u00e1 que realmente est\u00e1 perdendo?<\/p>\n<p>Queremos aqui deixar uma mensagem para \u201celes\u201d que pensam que venceram. A luta apenas come\u00e7ou. A GEAP existe h\u00e1 d\u00e9cadas e com a defesa da ANASPS a GEAP vai continuar.<\/p>\n<p>Somos brasileiros e n\u00e3o desistimos nunca.<\/p>\n<p>\u201cQuando algu\u00e9m sonha, temos apenas um sonho, quando muitos sonham juntos, a realidade come\u00e7a\u201d.<\/p>\n<p>Acreditamos na Justi\u00e7a. \u00c9 com ela que vamos reconquistar nossos direitos!!!<\/p>\n<p>Diretoria Executiva da ANASPS&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na nota com o t\u00edtulo &#8220;A quem interessa a fal\u00eancia da Geap&#8221;, a Anasps informa que a not\u00edcia veiculada pela Geap, maior operadora de plano de sa\u00fade do funcionalismo, de que a Associa\u00e7\u00e3o teria perdido uma a\u00e7\u00e3o na Justi\u00e7a, n\u00e3o \u00e9 verdadeira. &#8220;Primeiro, a senten\u00e7a ainda permite recurso. Vamos fazer. Segundo a ANASPS n\u00e3o est\u00e1 jogando batalha naval, logo n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[1214,337,982,345,980,131,2021,1164,76,443,260,2317,690,30,58],"class_list":["post-18248","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-abusivos","tag-anasps","tag-ans","tag-aposentados","tag-beneficiarios","tag-contribuicao","tag-eleicoes","tag-funcionalismo","tag-geap","tag-idosos","tag-justica","tag-plano-de-saude","tag-reajustes","tag-salarios","tag-servidores"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/18248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=18248"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/18248\/revisions"}],"predecessor-version":[{"id":18251,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/18248\/revisions\/18251"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=18248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=18248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=18248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}