{"id":16502,"date":"2020-06-08T18:19:53","date_gmt":"2020-06-08T21:19:53","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=16502"},"modified":"2020-06-08T18:19:53","modified_gmt":"2020-06-08T21:19:53","slug":"marcha-virtual-pela-vida","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/marcha-virtual-pela-vida\/","title":{"rendered":"Marcha Virtual pela Vida"},"content":{"rendered":"<p><em><strong>Mais de 300 organiza\u00e7\u00f5es apoiam o evento, cuja programa\u00e7\u00e3o consiste em debates &#8211; espalhados pelas m\u00eddias das entidades -, amanh\u00e3, 9 de junho, com um tuita\u00e7o, \u00e0s 12 horas, um painel unificado, \u00e0s 13 horas, e um ato pol\u00edtico, \u00e0s 16 horas, que endere\u00e7ar\u00e1 o documento motriz da Frente a parlamentares<\/strong><\/em><\/p>\n<p>A Frente pela Vida, movimento que re\u00fane entidades de diversos setores da sociedade civil, realizar\u00e1 amanh\u00e3, 9 de junho, a <a href=\"https:\/\/marchavirtualpelavida.org.br\/\">#MarchaPelaVida<\/a>. O objetivo \u00e9 ocupar as redes, ao longo do dia,com atividades que reforcem a import\u00e2ncia de defender a ci\u00eancia, o SUS, a solidariedade e a democracia: valores fundamentais para garantir a vida e a sa\u00fade de todos os brasileiros e enfrentar a pandemia de coronav\u00edrus.<\/p>\n<p>A Associa\u00e7\u00e3o Brasileira de Sa\u00fade Coletiva (Abrasco) \u00e9 uma das organizadoras, e receber\u00e1 o semin\u00e1rio da Rede em Pesquisa \u00e0 Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade (Rede APS\/Abrasco) Experi\u00eancias de fortalecimento da Estrat\u00e9gia Sa\u00fade da Fam\u00edlia para o enfrentamento da Covid-19: o que podemos aprender?, na TV Abrasco, canal do Youtube, \u00e0s 9h. O encontro virtual pretende analisar experi\u00eancias locais de reestrutura\u00e7\u00e3o da Aten\u00e7\u00e3o B\u00e1sica e iniciativas inovadoras na ESF, no que tange a pandemia, al\u00e9m de debater as fragilidades identificadas.<\/p>\n<p>Apoio<br \/>\nOs participantes da Marcha Virtual pela Vida tamb\u00e9m poder\u00e3o demonstrar seu apoio \u00e0 manifesta\u00e7\u00e3o por meio do aplicativo Manif.app, uma ferramenta que permite que pessoas protestem virtualmente, em tempo real, obedecendo as recomenda\u00e7\u00f5es da OMS de distanciamento social para evitar a dissemina\u00e7\u00e3o da Covid-19. Importantes cientistas, gestores p\u00fablicos, ativistas, parlamentares e artistas endossam o movimento &#8211; como Jurema Werneck, Greg\u00f3rio Duvivier, Sidarta Ribeiro, Silvio Tendler, Frei Betto, Jandira Feghali e os ex-ministros da sa\u00fade Alexandre Padilha e Jos\u00e9 Gomes Tempor\u00e3o.<\/p>\n<p>Os depoimentos est\u00e3o reunidos no site elaborado para o evento, assim como a programa\u00e7\u00e3o completa, a declara\u00e7\u00e3o das entidades, not\u00edcias e materiais de divulga\u00e7\u00e3o. Acesse e veja como se juntar \u00e0 #MarchaPelaVida: www.marchavirtualpelavida.org.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 300 organiza\u00e7\u00f5es apoiam o evento, cuja programa\u00e7\u00e3o consiste em debates &#8211; espalhados pelas m\u00eddias das entidades -, amanh\u00e3, 9 de junho, com um tuita\u00e7o, \u00e0s 12 horas, um painel unificado, \u00e0s 13 horas, e um ato pol\u00edtico, \u00e0s 16 horas, que endere\u00e7ar\u00e1 o documento motriz da Frente a parlamentares A Frente pela Vida, movimento que re\u00fane entidades de [&hellip;]<\/p>\n","protected":false},"author":89,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[15104,463,21,5332,16896,4053,1242,17657,4165,275,17255,187,1427,3236,616,2833,2000,15101,1808,372],"class_list":["post-16502","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-abrasco","tag-atividades","tag-ato","tag-ciencia","tag-coronavirus","tag-democracia","tag-familia","tag-marcha-virtual-pela-vida","tag-organizacoes","tag-painel","tag-pandemia","tag-pesquisa","tag-politico","tag-redes","tag-saude","tag-solidariedade","tag-sus","tag-tuitaco","tag-valores","tag-vida"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/16502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=16502"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/16502\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=16502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=16502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=16502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}