{"id":14928,"date":"2020-01-14T16:06:53","date_gmt":"2020-01-14T19:06:53","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=14928"},"modified":"2020-01-14T16:08:34","modified_gmt":"2020-01-14T19:08:34","slug":"mpf-fara-audiencia-publica-para-discutir-a-demora-do-inss-no-atendimento-de-solicitacoes-de-beneficio","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/mpf-fara-audiencia-publica-para-discutir-a-demora-do-inss-no-atendimento-de-solicitacoes-de-beneficio\/","title":{"rendered":"MPF far\u00e1 audi\u00eancia p\u00fablica para discutir a demora do INSS no atendimento de solicita\u00e7\u00f5es de benef\u00edcio"},"content":{"rendered":"<p><em>O objetivo \u00e9 ouvir especialistas e trazer os segurados que v\u00eam procurando o MPF para conseguir uma resposta da Presid\u00eancia do INSS, al\u00e9m de garantir o regular atendimento pela autarquia. A legisla\u00e7\u00e3o imp\u00f5e ao Instituto Nacional do Seguro Social prazos certos para a an\u00e1lise de pedidos de concess\u00e3o de benef\u00edcios previdenci\u00e1rios<\/em><\/p>\n<p>O Minist\u00e9rio P\u00fablico Federal (MPF) far\u00e1, no dia 11 de fevereiro, \u00e0s 10 horas, audi\u00eancia p\u00fablica &#8220;Demora no INSS: Por qu\u00ea?&#8221; para debater a demora na an\u00e1lise de pedidos de concess\u00e3o de benef\u00edcios pelo INSS na Baixada Fluminense. Ser\u00e1 no audit\u00f3rio da Procuradoria da Rep\u00fablica em S\u00e3o Jo\u00e3o de Meriti, na Avenida Autom\u00f3vel Clube, n\u00ba 2435 \u2013 Vilar dos Teles. O debate ser\u00e1 conduzido pelo procurador da Rep\u00fablica Julio Jos\u00e9 Araujo Junior. Compor\u00e3o a mesa o presidente da autarquia, Renato Rodrigues Vieira, o Superintendente Regional \u2013 Sudeste II, Paulo Eduardo Cirino, e o Gerente Executivo em Duque de Caxias, Marcos de Oliveira Fernandes.<\/p>\n<p>Para participar da audi\u00eancia, basta fazer inscri\u00e7\u00e3o pr\u00e9via por meio do e-mail prrj-sjm-gaboficio3@mpf.mp.br ou do telefone (21) 2753-7926, de acordo com a capacidade f\u00edsica do local. Na inscri\u00e7\u00e3o \u00e9 necess\u00e1rio informar nome completo, documento de identidade, entidade ou \u00f3rg\u00e3o p\u00fablico eventualmente vinculados e se deseja manifestar-se oralmente nos debate. Participantes n\u00e3o inscritos e manifesta\u00e7\u00f5es n\u00e3o informadas anteriormente poder\u00e3o ser aceitos, de acordo com a disponibilidade de vagas e tempo dos trabalhos.<\/p>\n<p><strong>Entenda o caso<\/strong><\/p>\n<p>Em agosto do ano passado, o Minist\u00e9rio P\u00fablico Federal (MPF) instaurou inqu\u00e9rito civil p\u00fablico (n\u00ba 1.30.017.000352\/2019-18) para apurar a demora na an\u00e1lise de pedidos de concess\u00e3o de benef\u00edcio nas ag\u00eancias de Previd\u00eancia Social na Baixada Fluminense (RJ). O \u00f3rg\u00e3o vem recebendo diversas den\u00fancias de segurados que n\u00e3o recebem resposta sobre os seus pedidos h\u00e1 mais de um ano. Al\u00e9m disso, diversos mandados de seguran\u00e7a v\u00eam sendo impetrados para discutir a quest\u00e3o.<\/p>\n<p>Segundo o procurador da Rep\u00fablica Julio Jos\u00e9 Araujo Junior, a situa\u00e7\u00e3o anormal encontrada levou \u00e0 necessidade de dar uma solu\u00e7\u00e3o coletiva ao caso, buscando uma mudan\u00e7a nas rotinas da autarquia e uma melhora na presta\u00e7\u00e3o de servi\u00e7o p\u00fablico. &#8220;\u00c9 necess\u00e1rio que o INSS atenda com celeridade tais pedidos, em aten\u00e7\u00e3o \u00e0 dura\u00e7\u00e3o razo\u00e1vel do processo&#8221;, afirmou. Al\u00e9m disso, tamb\u00e9m foi ressaltado que a legisla\u00e7\u00e3o imp\u00f5e ao Instituto Nacional do Seguro Social prazos certos para a an\u00e1lise de pedidos de concess\u00e3o de benef\u00edcios previdenci\u00e1rios.<\/p>\n<p>Passados cinco meses, os problemas persistem. As reclama\u00e7\u00f5es continuam vindo, sem qualquer resposta do INSS acerca das solicita\u00e7\u00f5es de benef\u00edcios como aux\u00edlio-doen\u00e7a, aposentadoria por invalidez, benef\u00edcios de presta\u00e7\u00e3o continuada, pens\u00e3o por morte entre outros. Al\u00e9m da falta de resposta, a an\u00e1lise n\u00e3o respeita a dura\u00e7\u00e3o razo\u00e1vel do processo.<\/p>\n<p><a href=\"http:\/\/www.mpf.mp.br\/rj\/sala-de-imprensa\/docs\/prm-s-j-meriti\/edital-de-convocacao\">Veja o edital de convoca\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O objetivo \u00e9 ouvir especialistas e trazer os segurados que v\u00eam procurando o MPF para conseguir uma resposta da Presid\u00eancia do INSS, al\u00e9m de garantir o regular atendimento pela autarquia. A legisla\u00e7\u00e3o imp\u00f5e ao Instituto Nacional do Seguro Social prazos certos para a an\u00e1lise de pedidos de concess\u00e3o de benef\u00edcios previdenci\u00e1rios O Minist\u00e9rio P\u00fablico Federal (MPF) far\u00e1, no dia 11 [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[551,1220,980,852,16744,457,16745,1291,11,2092,16746,9214,2469,522],"class_list":["post-14928","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-atendimento","tag-audiencia-publica","tag-beneficiarios","tag-beneficios","tag-demroa","tag-denuncias","tag-esposta","tag-inscricao","tag-inss","tag-legislacao","tag-mandos-de-seguranca","tag-mpfrj","tag-pedidos","tag-segurados"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/14928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=14928"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/14928\/revisions"}],"predecessor-version":[{"id":14932,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/14928\/revisions\/14932"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=14928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=14928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=14928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}