{"id":13221,"date":"2019-07-19T11:35:28","date_gmt":"2019-07-19T14:35:28","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=13221"},"modified":"2019-07-19T11:38:05","modified_gmt":"2019-07-19T14:38:05","slug":"morre-o-economista-walter-barelli","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/morre-o-economista-walter-barelli\/","title":{"rendered":"Morre o economista Walter Barelli"},"content":{"rendered":"<p><em>Faleceu na noite de quinta-feira (18), em S\u00e3o Paulo, o economista Walter Barelli, aos 80 anos (completaria 81, no pr\u00f3ximo dia 25). Ele foi diretor-t\u00e9cnico do Departamento Intersindical de Estat\u00edstica e Estudos Socioecon\u00f4micos (Dieese) por 22 anos, professor, ex-ministro do Trabalho e ex-deputado federal.\u00a0Ele ser\u00e1 enterrado no cemit\u00e9rio Geths\u00eamani Anhanguera. O vel\u00f3rio acontecer\u00e1 nesta tarde (19), na cripta da Catedral da S\u00e9<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-13224\" src=\"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2019\/07\/Walter-Barelli.jpg\" alt=\"\" width=\"349\" height=\"500\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2019\/07\/Walter-Barelli.jpg 349w, https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2019\/07\/Walter-Barelli-209x300.jpg 209w, https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2019\/07\/Walter-Barelli-244x350.jpg 244w, https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-content\/uploads\/sites\/10\/2019\/07\/Walter-Barelli-230x330.jpg 230w\" sizes=\"auto, (max-width: 349px) 100vw, 349px\" \/><\/p>\n<p>Ele estava em coma h\u00e1 tr\u00eas meses, ap\u00f3s um acidente na escadaria do Instituto Tomie Ohtake, em S\u00e3o Paulo. Na quela, ele bateu com a cabe\u00e7a. Estava internado no hospital S\u00edrio Liban\u00eas e morreu de fal\u00eancia de m\u00faltiplos \u00f3rg\u00e3os, ao lado da fam\u00edlia. Nascido em S\u00e3o Paulo, Barelli ganhou notoriedade ao desmontar a farsa dos c\u00e1lculos sobre \u00edndices da infla\u00e7\u00e3o durante a ditadura militar. Ele foi incans\u00e1vel na luta, ao lado dos sindicatos, contra o mecanismo de \u201carrocho salarial\u201d, que achatava os rendimentos de trabalhadores.<\/p>\n<p>Foi casado com Lourdes Barelli. Vi\u00favo, deixa os filhos Suzana, Pedro e Paulo Barelli, e cinco netos.\u00a0Filho de um mec\u00e2nico de manuten\u00e7\u00e3o e de uma tecel\u00e3, militante na universidade, banc\u00e1rio, corintiano, economista, ministro e secret\u00e1rio do Trabalho, deputado federal e professor.\u00a0Barelli pensou em estudar Administra\u00e7\u00e3o, mas o sal\u00e1rio de funcion\u00e1rio do Banco do Brasil n\u00e3o era suficiente para pagar a mensalidade.<\/p>\n<p>Fez vestibular e foi um dos primeiros no classifica\u00e7\u00e3o da Faculdade de Economia da Universidade de S\u00e3o Paulo (USP). Se formou em em 1964 (mas n\u00e3o teve formatura, por causa do golpe militar). Nesse per\u00edodo, militou na Juventude Universit\u00e1ria Cat\u00f3lica (JUC), que ajudou nas suas reflex\u00f5es sobre os problemas brasileiros. Integrou tamb\u00e9m a organiza\u00e7\u00e3o pol\u00edtica A\u00e7\u00e3o Popular.<\/p>\n<p>O economista entrou no Dieese em um per\u00edodo de persegui\u00e7\u00e3o ao movimento sindical, que sustentava o instituto, desativado em um primeiro momento e rearticulado aos poucos, sem deixar de sofrer tentativas de fechamento por falta de recursos. Ganhou notoriedade externa em 1977, depois que um relat\u00f3rio do Banco Mundial mostrou manipula\u00e7\u00e3o nos dados oficiais de infla\u00e7\u00e3o no Brasil em 1973 \u2013 a estimativa mais pr\u00f3xima da realidade era a do Dieese.<\/p>\n<p>O epis\u00f3dio das perdas inflacion\u00e1rias de 1973 deu impulso \u00e0s campanhas salariais a partir de 1977 e 1978.\u00a0\u00a0Barelli chegou a ser preso em 1979, primeiro ano do governo Jo\u00e3o Figueiredo, o \u00faltimo dos presidentes-generais.\u00a0O economista deixou o Dieese no in\u00edcio de 1990. Foi dar aulas na Universidade Estadual de Campinas (Unicamp). Ao mesmo tempo, colaborou, durante quase dois anos, como coordenador da \u00e1rea econ\u00f4mica do chamado \u201cgoverno paralelo\u201d criado por Lula ap\u00f3s as elei\u00e7\u00f5es presidenciais de 1989, quando perdeu no segundo turno para Fernando Collor.<\/p>\n<p>Em 1992, ap\u00f3s o impeachment de Collor, assumiu o vice Itamar Franco, que levou Barelli para o Minist\u00e9rio do Trabalho.\u00a0Em S\u00e3o Paulo, foi por duas gest\u00f5es secret\u00e1rio estadual de Emprego e Rela\u00e7\u00f5es do Trabalho, de 1995 a 2002, nos governos de M\u00e1rio Covas, que morreu em 2001 e foi substitu\u00eddo pelo vice, Geraldo Alckmin. Tamb\u00e9m exerceu parcialmente mandato de deputado federal, entre 2005 e 2007, pelo PSDB, cuja filia\u00e7\u00e3o manteve.<\/p>\n<p>Entre outras, publicou as seguintes obras: Pesquisa de cargos e fun\u00e7\u00f5es (1974), Dez anos de pol\u00edtica salarial (em coautoria com C\u00e9sar Concone, 1975), Distribui\u00e7\u00e3o funcional dos bancos comerciais (1979), Crise econ\u00f4mica de alimenta\u00e7\u00e3o do trabalhador (1984), Le c\u00f4ut social de la modernisation conservatrice (1990), O futuro do sindicalismo (1992) e O Futuro do Emprego (2002).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faleceu na noite de quinta-feira (18), em S\u00e3o Paulo, o economista Walter Barelli, aos 80 anos (completaria 81, no pr\u00f3ximo dia 25). Ele foi diretor-t\u00e9cnico do Departamento Intersindical de Estat\u00edstica e Estudos Socioecon\u00f4micos (Dieese) por 22 anos, professor, ex-ministro do Trabalho e ex-deputado federal.\u00a0Ele ser\u00e1 enterrado no cemit\u00e9rio Geths\u00eamani Anhanguera. O vel\u00f3rio acontecer\u00e1 nesta tarde (19), na cripta da Catedral [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[10814,2267,4141,15722,2026,1039,6287,15727,2626,98,240,15725,1863,7851,15724,2841,35,15721,15726,5264,5909,643,15723,2982,4630],"class_list":["post-13221","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-acao-popular","tag-acidente","tag-bancario","tag-coma","tag-dieese","tag-ditadura","tag-economista","tag-escritor","tag-filhos","tag-governo","tag-inflacao","tag-juc","tag-mao","tag-mecanico","tag-militante","tag-ministerio-do-trabalho","tag-ministro","tag-morre","tag-movimento-sindical","tag-netos","tag-pai","tag-salario","tag-tecela","tag-usp","tag-walter-barelli"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/13221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=13221"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/13221\/revisions"}],"predecessor-version":[{"id":13225,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/13221\/revisions\/13225"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=13221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=13221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=13221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}