{"id":11989,"date":"2019-02-21T12:52:48","date_gmt":"2019-02-21T15:52:48","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=11989"},"modified":"2019-02-21T12:52:48","modified_gmt":"2019-02-21T15:52:48","slug":"salariometro-janeiro-foi-um-mes-dificil-para-fechamento-de-negociacoes-salariais","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/salariometro-janeiro-foi-um-mes-dificil-para-fechamento-de-negociacoes-salariais\/","title":{"rendered":"Salari\u00f4metro &#8211; Janeiro foi um m\u00eas dif\u00edcil para fechamento de negocia\u00e7\u00f5es salariais"},"content":{"rendered":"<p><em>De acordo com o Boletim Salari\u00f4metro, da Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (Fipe), a dificuldade \u00e9 maior em 2019 do que foi em 2018. O piso salarial mediano sofre o efeito sazonal de janeiro e cai para R$ 1.097 (10% acima do sal\u00e1rio m\u00ednimo)<\/em><\/p>\n<div>Pelo quinto m\u00eas consecutivo, em janeiro, o reajuste mediano fica em 4%. E pelo segundo m\u00eas consecutivo, houve ganho real no reajuste mediano, segundo dados do Salari\u00f4metro, boletim coordenado pelo economista H\u00e9lio Zylberstajn. A proje\u00e7\u00e3o do INPC acumulado, disse, d\u00e1 espa\u00e7o a continuidade do ganho real nos pr\u00f3ximos meses. Ele apontou como destaque, esse m\u00eas, o adicional de hora extra, que passou a ter mais import\u00e2ncia nas discuss\u00f5es entre empregados e patr\u00f5es.<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o Boletim Salari\u00f4metro, da Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (Fipe), a dificuldade \u00e9 maior em 2019 do que foi em 2018. O piso salarial mediano sofre o efeito sazonal de janeiro e cai para R$ 1.097 (10% acima do sal\u00e1rio m\u00ednimo) Pelo quinto m\u00eas consecutivo, em janeiro, o reajuste mediano fica em 4%. E pelo segundo m\u00eas [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2719],"tags":[2046,12747,4471,4002,10352,14764,4000,14763,14163],"class_list":["post-11989","post","type-post","status-publish","format-standard","hentry","category-servidor","tag-adicional","tag-boletim-salariometro","tag-fechamento","tag-fipe","tag-ganho-real","tag-hora-extra","tag-inpc","tag-negociacoes-salariais","tag-sazonal"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/11989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=11989"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/11989\/revisions"}],"predecessor-version":[{"id":11990,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/11989\/revisions\/11990"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=11989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=11989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=11989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}