{"id":1181,"date":"2016-03-04T14:21:55","date_gmt":"2016-03-04T17:21:55","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/?p=1181"},"modified":"2016-03-04T14:21:55","modified_gmt":"2016-03-04T17:21:55","slug":"pl-17752015-pode-elevar-gastos-do-governo-em-mais-de-r-2-bilhoes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/pl-17752015-pode-elevar-gastos-do-governo-em-mais-de-r-2-bilhoes\/","title":{"rendered":"PL 1775\/2015 PODE ELEVAR GASTOS DO GOVERNO EM MAIS DE R$ 2 BILH\u00d5ES"},"content":{"rendered":"<p><em>O PL 1775\/15 coloca em risco a seguran\u00e7a das elei\u00e7\u00f5es, dados pessoais dos cidad\u00e3os e gera gastos abusivos, denuncia a Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg\/BR). Para a entidade, o CPF, n\u00famero de contribuinte do cidad\u00e3o, emitido gratuitamente pelos cart\u00f3rios, pode ser o documento \u00fanico de identifica\u00e7\u00e3o, evitando um gasto estimado de mais de R$ 2 bilh\u00f5es a cada dois anos<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A C\u00e2mara dos Deputados pretende votar em regime de urg\u00eancia o Projeto de Lei n\u00ba 1775\/2015, que disp\u00f5e sobre o Registro Civil Nacional (RCN). Por meio de requerimentos de deputados ligados ao presidente da Casa, os parlamentares pretendem vot\u00e1-lo ainda nesta semana. A Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg\/BR) defende que o CPF, n\u00famero de contribuinte do cidad\u00e3o junto \u00e0 Receita Federal,\u00a0 emitido gratuitamente pelos cart\u00f3rios de Registro Civil de Pessoas Naturais, pode ser usado como documento \u00fanico de identifica\u00e7\u00e3o, evitando um gasto estimado de mais de R$ 2 bilh\u00f5es a cada dois anos.<\/p>\n<p>No entender da Anoreg, o projeto apresenta, em seus 12 artigos, uma s\u00e9rie de caracter\u00edsticas que especialistas consideram inconstitucionais, al\u00e9m de colocar em risco a integridade, a disponibilidade, a autenticidade e a confidencialidade da base de dados privados dos cidad\u00e3os. Outra quest\u00e3o importante \u00e9 que os cart\u00f3rios de registro civil, que est\u00e3o presentes em todos os munic\u00edpios brasileiros, j\u00e1 colocaram \u00e0 disposi\u00e7\u00e3o do governo federal a sua base de dados de nascimentos, casamentos e \u00f3bitos, para os necess\u00e1rios controles de benef\u00edcios sociais e previdenci\u00e1rios. Al\u00e9m disso, se prontificaram a fazer o cadastramento biom\u00e9trico sem qualquer custo.<\/p>\n<p>O\u00a0 PL 1775\/15, enfatiza a entidade, ainda prev\u00ea que o Tribunal Superior Eleitoral (TSE) poder\u00e1 firmar acordo, conv\u00eanio ou outro instrumento cong\u00eanere com\u00a0entidades governamentais ou privadas. O pr\u00f3prio escopo do projeto diz que \u201ch\u00e1 o interesse de diversas entidades p\u00fablicas e privadas na participa\u00e7\u00e3o do projeto, inclusive com recursos financeiros&#8221;. Esse ponto evidencia que o TSE poder\u00e1 comercializar os dados pessoais do seu cadastro para a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), bancos e outras entidades do sistema financeiro, denuncia a Anoreg.<\/p>\n<p>A Anoreg lembra, tamb\u00e9m, que, em agosto de 2013, um esc\u00e2ndalo marcou a revela\u00e7\u00e3o de que a Justi\u00e7a Eleitoral havia repassado os dados de 141 milh\u00f5es de brasileiros para a Serasa. O acordo, feito sem o conhecimento dos cidad\u00e3os, sofreu forte resist\u00eancia da sociedade e acabou sendo suspenso pelo Tribunal ap\u00f3s cr\u00edticas que, dentre outros aspectos, afirmavam ser inconstitucional o fornecimento de dados privados de cidad\u00e3os sem ordem judicial. Na mesma \u00e9poca, veio \u00e0 tona outro esc\u00e2ndalo, pois se comprovou que os dados repassados \u00e0 Serasa, fruto da parceria com o TSE, haviam vazado na internet, onde estavam sendo comercializados por entidades privadas.<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A Anoreg BR, que \u00e9 favor\u00e1vel \u00e0 ado\u00e7\u00e3o de um n\u00famero \u00fanico de identifica\u00e7\u00e3o do cidad\u00e3o, defende que o Cadastro Nacional de Pessoa F\u00edsica (CPF), que tamb\u00e9m \u00e9 emitido pelos cart\u00f3rios de Registro Civil de Pessoas Naturais, deveria ser utilizado para esse fim, uma vez que ele j\u00e1 conta com um documento chave seguro, acess\u00edvel e adaptado a toda a base de dados social e econ\u00f4mica brasileira. Al\u00e9m disso, a Anoreg BR concorda com a utiliza\u00e7\u00e3o da biometria (foto e impress\u00e3o digital) associada ao registro, mas acredita \u00e9 fundamental envolver neste processo as institui\u00e7\u00f5es que j\u00e1 possuem dados das pessoas f\u00edsicas, tais como registradores, Receita Federal, entre outros, a fim de evitar novos e desnecess\u00e1rios gastos para o governo.<\/p>\n<p>Segundo o presidente\u00a0 da Anoreg\/BR, Rog\u00e9rio Portugal Bacelar, o projeto tamb\u00e9m cita a cria\u00e7\u00e3o do Comit\u00ea do RCN, formado por tr\u00eas representantes indicados pelo Poder Executivo federal e tr\u00eas representantes indicados pelo Tribunal Superior Eleitoral, mas n\u00e3o deixa claro como ser\u00e1 essa escolha.<\/p>\n<p>\u201cO projeto coloca em d\u00favida a separa\u00e7\u00e3o e a independ\u00eancia dos Poderes da Rep\u00fablica, prevista na Constitui\u00e7\u00e3o Federal, na medida em que\u00a0 possibilita que se fa\u00e7a um indevido controle eleitoral por parte do Poder Executivo que ter\u00e1 acesso ao Registro Civil Nacional\u201d, enfatiza Rog\u00e9rio.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Sobre a Anoreg- BR<\/em><\/p>\n<p>A Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg-BR) congrega mais de 15 mil cart\u00f3rios distribu\u00eddos em todos os estados, munic\u00edpios e na maioria dos distritos brasileiros, os quais empregam direta e indiretamente mais de 500 mil pessoas. Entre os objetivos da atividade extrajudicial destacam-se a garantia de autenticidade, seguran\u00e7a e efic\u00e1cia a todos os atos jur\u00eddicos. A entidade nacional tem legitimidade, pelos poderes constitu\u00eddos, para representar todas as especialidades em qualquer inst\u00e2ncia ou tribunal, operando em harmonia e coopera\u00e7\u00e3o direta com outras associa\u00e7\u00f5es cong\u00eaneres. Acesse: www.anoreg.org.br.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O PL 1775\/15 coloca em risco a seguran\u00e7a das elei\u00e7\u00f5es, dados pessoais dos cidad\u00e3os e gera gastos abusivos, denuncia a Associa\u00e7\u00e3o dos Not\u00e1rios e Registradores do Brasil (Anoreg\/BR). Para a entidade, o CPF, n\u00famero de contribuinte do cidad\u00e3o, emitido gratuitamente pelos cart\u00f3rios, pode ser o documento \u00fanico de identifica\u00e7\u00e3o, evitando um gasto estimado de mais de R$ 2 bilh\u00f5es a [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1214,1215,1213,144,804,1211,1169,98,1209,1210,1212,208,1216],"class_list":["post-1181","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-abusivos","tag-anoregbr","tag-cidadaos","tag-cpf","tag-documento","tag-elevar","tag-gastos","tag-governo","tag-pl-177515","tag-pode","tag-risco","tag-seguranca","tag-unico"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/comments?post=1181"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/1181\/revisions"}],"predecessor-version":[{"id":1182,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/posts\/1181\/revisions\/1182"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/categories?post=1181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/servidor\/wp-json\/wp\/v2\/tags?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}