{"id":8043,"date":"2018-10-07T10:04:56","date_gmt":"2018-10-07T13:04:56","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=8043"},"modified":"2018-10-06T19:20:30","modified_gmt":"2018-10-06T22:20:30","slug":"humberto-carrao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/humberto-carrao\/","title":{"rendered":"Humberto Carr\u00e3o comemora entrar em Sob press\u00e3o"},"content":{"rendered":"<h3>Segunda temporada de <em>Sob press\u00e3o<\/em> volta a discutir o sistema de sa\u00fade p\u00fablica e traz a corrup\u00e7\u00e3o como tema. Humberto Carr\u00e3o refor\u00e7a o elenco!<\/h3>\n<p>A cr\u00edtica e o entretenimento est\u00e3o lado a lado mais uma vez, com a estreia da segunda temporada do seriado <em>Sob press\u00e3o<\/em><a href=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/critica-sob-pressao-e-er-brasileira\/\"><strong>(leia aqui a nossa cr\u00edtica da primeira temporada)<\/strong><\/a>. Com supervis\u00e3o de texto de Jorge Furtado e dire\u00e7\u00e3o de Andrucha Waddington, a atra\u00e7\u00e3o chega \u00e0 Globo nesta ter\u00e7a-feira, depois de <em>Segundo sol<\/em>.<\/p>\n<p>O foco de <em>Sob press\u00e3o<\/em> continua sendo a luta dos m\u00e9dicos Carolina (Marjorie Estiano) e Evandro (J\u00falio Andrade) para levar sa\u00fade de qualidade \u00e0 rede p\u00fablica, mesmo sem contar com investimentos grandes e aparelhagem de qualidade. Na segunda temporada, a dire\u00e7\u00e3o do hospital passa a ser ocupada por Renata (Fernanda Torres), o que abre caminho para a discuss\u00e3o sobre corrup\u00e7\u00e3o e desvio de verba.<\/p>\n<p>Quem tamb\u00e9m estreia nesta temporada \u00e9 Humberto Carr\u00e3o, que viver\u00e1 o arrogante cirurgi\u00e3o ortopedista Henrique. \u201c\u00c9 muito interessante entrar numa s\u00e9rie que j\u00e1 tem a equipe t\u00e3o entrosada. Sob press\u00e3o tem uma import\u00e2ncia muito grande por discutir o sistema de sa\u00fade p\u00fablica no pa\u00eds. O Henrique participar\u00e1 da discuss\u00e3o sobre para onde vai o recurso p\u00fablico por causa da corrup\u00e7\u00e3o\u201d, afirma Humberto, em entrevista ao <strong>Correio<\/strong>.<\/p>\n<p>Mais acostumado a fazer novelas do que s\u00e9ries, Humberto comenta que no formato mais fechado \u00e9 poss\u00edvel compor o personagem com mais clareza. \u201cFazer novela \u00e9 um exerc\u00edcio dif\u00edcil. \u00c9 uma surpresa a cada bloco de cap\u00edtulos que a gente recebe. Os personagens podem ir mudando de acordo com o que o p\u00fablico pensa. Eu passei duas vezes pela experi\u00eancia de o vil\u00e3o que eu fazia virar mocinho. Na s\u00e9rie, tem um limite estabelecido, o que \u00e9 muito bom para o ator\u201d, compara Humberto, que esteve em novelas como <em>A lei do amor<\/em> (2016) e <em>Gera\u00e7\u00e3o Brasil<\/em> (2014).<\/p>\n<p><em>Sob press\u00e3o<\/em> \u00e9 um sucesso t\u00e3o grande que, antes de a segunda temporada estrear, a terceira est\u00e1 sendo gravada. Mas Humberto n\u00e3o estar\u00e1 na pr\u00f3xima leva de epis\u00f3dios porque vai se dedicar ao roteiro de um longa-metragem que ele est\u00e1 escrevendo e a um curta que ele quer dirigir.<\/p>\n<h2>Humberto Carr\u00e3o \u00e9 apaixonado por cinema<\/h2>\n<p>O cinema \u00e9 uma grande paix\u00e3o de Humberto, que j\u00e1 dirigiu dois curtas e atuou em outros tantos, como <em>Para\u00edso perdido<\/em> (2018) e <em>Aquarius<\/em> (2016). \u201cEstudei cinema na minha faculdade. Minha vontade de escrever e dirigir \u00e9 t\u00e3o grande quanto a de atuar. Tem assuntos de que eu quero falar e levar \u00e0s telas\u201d, afirma.<\/p>\n<figure id=\"attachment_8045\" aria-describedby=\"caption-attachment-8045\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8045\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido.jpg\" alt=\"Ao lado de Jaloo, Humberto Carr\u00e3o teve cenas sensuais em Para\u00edso perdido\" width=\"1200\" height=\"650\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/paraiso-perdido-230x125.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-8045\" class=\"wp-caption-text\">Ao lado de Jaloo, Humberto Carr\u00e3o teve cenas sensuais em Para\u00edso perdido<\/figcaption><\/figure>\n<p>Al\u00e9m de ator e diretor, Humberto \u00e9 tamb\u00e9m apresentador do programa Pausa pro caf\u00e9, no Canal Brasil, dedicado a curtas-metragens. \u201cO curta \u00e9 fundamental para o cinema, para a forma\u00e7\u00e3o cultural. A gente vive um momento que a Ancine lan\u00e7a um edital de pontua\u00e7\u00e3o que \u00e9 muito estranho porque n\u00e3o leva a qualidade art\u00edstica como crit\u00e9rio, tem a ver com o mercado, com a audi\u00eancia. O edital ignora o curta-metragista, que n\u00e3o recebe nem um ponto. A impress\u00e3o que d\u00e1 \u00e9 que eles querem matar o cinema\u201d, lamenta Carr\u00e3o.<\/p>\n<p>Para ele, um dos locais de discuss\u00e3o para que isso n\u00e3o aconte\u00e7a s\u00e3o os festivais. H\u00e1 menos de um m\u00eas, Humberto esteve na capital para ser jurado do Festival de Bras\u00edlia do Cinema Brasileiro. Na oportunidade, o ator voltou a Bras\u00edlia, onde j\u00e1 tinha vindo duas vezes, mas nunca por tanto tempo. \u201cBras\u00edlia \u00e9 uma loucura. \u00c9 a nossa capital. Passar pelo Pal\u00e1cio do Planalto, pelo Congresso Nacional, pela Esplanada dos Minist\u00e9rios \u00e9 uma sensa\u00e7\u00e3o muito boa. D\u00e1 um \u2018uau\u2019, sabe? Saber que \u00e9 ali que se decidem v\u00e1rias coisas do Brasil inteiro\u201d, conta Humberto, ressaltando que voltar\u00e1 sempre que poss\u00edvel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segunda temporada de Sob press\u00e3o volta a discutir o sistema de sa\u00fade p\u00fablica e traz a corrup\u00e7\u00e3o como tema. Humberto Carr\u00e3o refor\u00e7a o elenco!<\/p>\n","protected":false},"author":57,"featured_media":8044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[22,919],"class_list":["post-8043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-series","tag-globo","tag-sob-pressao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=8043"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8043\/revisions"}],"predecessor-version":[{"id":8046,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8043\/revisions\/8046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/8044"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=8043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=8043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=8043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}