{"id":8021,"date":"2018-10-07T09:00:34","date_gmt":"2018-10-07T12:00:34","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=8021"},"modified":"2018-10-05T15:48:08","modified_gmt":"2018-10-05T18:48:08","slug":"programacao-especial-mes-das-criancas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/programacao-especial-mes-das-criancas\/","title":{"rendered":"Confira programa\u00e7\u00e3o especial para celebrar o m\u00eas das crian\u00e7as"},"content":{"rendered":"<h3>Programa\u00e7\u00e3o da tev\u00ea fechada e do streaming aproveita o m\u00eas das crian\u00e7as para focar no p\u00fablico infantil em outubro<\/h3>\n<p>O m\u00eas de outubro chegou e, com ele, uma s\u00e9rie de lan\u00e7amentos dedicados ao p\u00fablico infantojuvenil como forma de celebrar o Dia das Crian\u00e7as, comemorado no dia 12. Entre as novidades est\u00e3o tr\u00eas produ\u00e7\u00f5es nacionais, os desenhos<em> Os Chocolix<\/em> e <em>Clube da Anittinha<\/em> e a s\u00e9rie live-action <em>Escola de g\u00eanios<\/em>. Mas tamb\u00e9m h\u00e1 anima\u00e7\u00f5es vindas de fora, como <em>Dragon Ball Super<\/em>, <em>Fancy Nancy Clancy<\/em> e <em>O chefinho \u2014 De volta aos neg\u00f3cios<\/em>.<\/p>\n<p>Lan\u00e7ado no fim de setembro, o desenho <em>Os Chocolix<\/em> \u00e9 exibido no canal Nickelodeon toda ter\u00e7a e quinta-feira, \u00e0s 11h, e foi criado pela peruana radicada no Brasil Jacqueline Shor. A ideia da produ\u00e7\u00e3o surgiu durante uma situa\u00e7\u00e3o de bullying que Jacqueline presenciou. Ela primeiro transformou a hist\u00f3ria em um conto que deu origem a um livro, at\u00e9 que se tornou na anima\u00e7\u00e3o<em> Os Chocolix<\/em>.<\/p>\n<p>\u201cSou uma pessoa que detesta bullying. Depois de um epis\u00f3dio espec\u00edfico, decidi que deveria fazer alguma coisa. Queria, sobretudo, trabalhar contra o bullying com foco nas crian\u00e7as. \u00c9 algo muito importante para a autoestima delas\u201d, afirma Jacqueline Shor em entrevista ao<strong> Correio<\/strong>.<\/p>\n<figure id=\"attachment_8022\" aria-describedby=\"caption-attachment-8022\" style=\"width: 1035px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8022\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_.png\" alt=\"Cr\u00e9dito: Nickelodeon\/Divulga\u00e7\u00e3o\" width=\"1035\" height=\"571\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_.png 1035w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_-300x166.png 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_-768x424.png 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_-1024x565.png 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_-550x303.png 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/Os-Chocolix_-230x127.png 230w\" sizes=\"auto, (max-width: 1035px) 100vw, 1035px\" \/><figcaption id=\"caption-attachment-8022\" class=\"wp-caption-text\">Cr\u00e9dito: Nickelodeon\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Com esse tema em foco, ela criou uma hist\u00f3ria que acompanha uma fam\u00edlia de chocolate, formada por Dona Branca, DonCacau e os filhos Chocomark, Chocholyne, al\u00e9m do mascote Docecookie. \u201cO pai \u00e9 um chocolate escuro, a m\u00e3e um chocolate branco e as crian\u00e7as s\u00e3o de chocolate ao leite. J\u00e1 mostramos a diversidade, ent\u00e3o \u00e9 uma anima\u00e7\u00e3o com situa\u00e7\u00f5es com as quais as crian\u00e7as se assemelham e tudo isso de uma maneira l\u00fadica.\u201d<\/p>\n<p>Na s\u00e9rie, a fam\u00edlia se muda para Chocol\u00e2ndia e precisa aprender a lidar com as inseguran\u00e7as dessa nova fase de vida. Em cada epis\u00f3dio, um novo personagem se torna destaque. \u201cAcho que \u00e9 uma trama importante por esse momento que o mundo est\u00e1 vivendo de globaliza\u00e7\u00e3o, de diversidade. O Brasil est\u00e1 acolhendo v\u00e1rios refugiados. Ent\u00e3o, por meio das minhas hist\u00f3rias, posso transmitir a mensagem de que o diferente \u00e9 legal\u201d, completa. Uma segunda temporada est\u00e1 em fase de produ\u00e7\u00e3o, e Jacqueline Shor garante que j\u00e1 tem hist\u00f3ria para mais outras duas sequ\u00eancias.<\/p>\n<p><strong>Poderosinha<\/strong><\/p>\n<p>A cantora Anitta \u00e9 hoje uma das maiores estrelas do Brasil e h\u00e1 algum tempo ela se dedica tamb\u00e9m ao p\u00fablico infantil. Todo come\u00e7ou com o <em>Show das poderosinhas<\/em>, apresenta\u00e7\u00e3o feita em formato de matin\u00ea especialmente para as crian\u00e7as, at\u00e9 o lan\u00e7amento do primeiro desenho animado, o <em>Clube da Anittinha<\/em>, voltado para os pequenos.<\/p>\n<figure id=\"attachment_8023\" aria-describedby=\"caption-attachment-8023\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8023\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha.jpg\" alt=\"Cr\u00e9dito: Gloob\/Divulga\u00e7\u00e3o\" width=\"1200\" height=\"650\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/clube-da-anittinha-230x125.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-8023\" class=\"wp-caption-text\">Cr\u00e9dito: Gloob\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Lan\u00e7ado no \u00faltimo dia 3 nos canais Gloobinho, com exibi\u00e7\u00e3o \u00e0s 18h30, e Gloob, \u00e0s 17h30, o <em>Clube da Anittinha<\/em> acompanha uma vers\u00e3o mirim de Anitta, dublada por ela mesma, em uma s\u00e9rie de aventuras ao lado dos amigos Rositcha, Renuvem, Mauro Mar, Marshmelle, Gatrick, Juju Coral e Estrellar \u2014 todos personagens criados inspirados em familiares, amigos e at\u00e9 cachorros da carioca.<\/p>\n<p>A primeira temporada \u00e9 formada por 10 epis\u00f3dios e tem roteiro e anima\u00e7\u00f5es da Birdo Studio com colabora\u00e7\u00e3o da escritora Jana\u00edna Totikaka e do humorista Victor Sarro.<\/p>\n<p><strong>Live-action<\/strong><\/p>\n<p>Dispon\u00edvel no servi\u00e7o on-demand dos canais Globosat, a s\u00e9rie <em>Escola de espi\u00f5es<\/em> \u00e9 uma live-action nacional voltada para o espectador infantojuvenil. A trama traz a hist\u00f3ria de Isaac, um estudante de 12 anos, que \u00e9 convidado para estudar na Escola de G\u00eanios por conta de suas habilidades especiais em matem\u00e1tica.<\/p>\n<figure id=\"attachment_8025\" aria-describedby=\"caption-attachment-8025\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8025\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1.jpg\" alt=\"Cr\u00e9dito: Gloob\/Divulga\u00e7\u00e3o\" width=\"1200\" height=\"650\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/10\/escola-de-g\u00eanios-1-230x125.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-8025\" class=\"wp-caption-text\">Cr\u00e9dito: Gloob\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Ele aceita a transfer\u00eancia com o intuito de ajudar a irm\u00e3 Maju, de 9 anos, que ficou tetrapl\u00e9gica ap\u00f3s um acidente. No entanto, Isaac vai passar por algumas situa\u00e7\u00f5es chatas na nova escola, j\u00e1 que a presen\u00e7a dele desagradou \u00e0 estudante Tesla, uma jovem de 11 anos extremamente competitiva por ter nascido numa fam\u00edlia de superdotados, que n\u00e3o quer que o novato chegue at\u00e9 o Torneio Regional de Rob\u00f3tica.<\/p>\n<p>A produ\u00e7\u00e3o estreia na televis\u00e3o em 15 de outubro, \u00e0s 19h30, no Gloob. Os 26 epis\u00f3dios da primeira temporada j\u00e1 est\u00e3o dispon\u00edveis para assinantes no Globosat Play.<\/p>\n<p><strong>Do cinema para a tev\u00ea<\/strong><\/p>\n<p>No ano passado, estreou nos cinemas a anima\u00e7\u00e3o<em> O poderoso chefinho<\/em>. O desenho de Tom McGrath mostra um beb\u00ea falante, que, na verdade, tem uma miss\u00e3o secreta de impedir uma cat\u00e1strofe no mundo dos beb\u00eas. A hist\u00f3ria fez tanto sucesso que ganhou uma vers\u00e3o seriada produzida pela Netflix.<\/p>\n<p>A segunda temporada de <em>Chefinho \u2014 De volta aos neg\u00f3cios<\/em> estreia em 12 de outubro na plataforma. Os novos epis\u00f3dios mostram o poderoso chefinho trazendo o irm\u00e3o mais velho Tim para o escrit\u00f3rio para ensin\u00e1-lo a arte dos neg\u00f3cios. Os epis\u00f3dios da primeira temporada j\u00e1 est\u00e3o dispon\u00edveis na Netflix.<\/p>\n<p><strong>Muitas aventuras<\/strong><\/p>\n<p>Desenho animado de sucesso nos anos 1990, <em>Dragon Ball<\/em> ganhou uma nova franquia, intitulada Dragon Ball Super, que estreou no dia 1\u00ba na programa\u00e7\u00e3o do Cartoon Network, com novos epis\u00f3dios de segunda a sexta, \u00e0s 15h30.<\/p>\n<p>Supervisionada pelo criador original Akira Toriyama, Dragon Ball Super mostra mais uma aventura de Goku e seus amigos para salvar o universo das for\u00e7as do mal. Dessa vez, o her\u00f3i decide coletar as Esferas do Drag\u00e3o para reviver o Rei Kai.<\/p>\n<p>A partir de 22 de outubro, o canal Disney Jr. passa a exibir na faixa das 19h15 a anima\u00e7\u00e3o <em>Fancy Nancy Clancy<\/em>. A anima\u00e7\u00e3o retrata a hist\u00f3ria de Nancy, uma menina de 6 anos que \u00e9 fascinada por tudo que \u00e9 elegante e sofisticado. O diferencial do desenho \u00e9 ensinar palavras em franc\u00eas para os pequenos telespectadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa\u00e7\u00e3o da tev\u00ea fechada e do streaming aproveita o m\u00eas das crian\u00e7as para focar no p\u00fablico infantil em outubro<\/p>\n","protected":false},"author":58,"featured_media":8024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,16],"tags":[2168,2171,2169,2172,2170,2167],"class_list":["post-8021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programas","category-series","tag-clube-da-anittinha","tag-dia-das-criancas","tag-dragon-ball-super","tag-escola-de-genios","tag-mes-das-criancas","tag-os-chocolix"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=8021"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8021\/revisions"}],"predecessor-version":[{"id":8026,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/8021\/revisions\/8026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/8024"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=8021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=8021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=8021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}