{"id":7668,"date":"2018-09-03T14:27:35","date_gmt":"2018-09-03T17:27:35","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=7668"},"modified":"2018-09-03T13:41:37","modified_gmt":"2018-09-03T16:41:37","slug":"mateus-solano-o-ze-bonitinho","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/mateus-solano-o-ze-bonitinho\/","title":{"rendered":"Mateus Solano: &#8220;O Z\u00e9 Bonitinho \u00e9 um personagem muito complexo&#8221;"},"content":{"rendered":"<h3><em>Escolinha do Professor Raimundo<\/em> chega \u00e0 quarta temporada no Viva. Confira o que Mateus Solano, o Z\u00e9 Bonitinho, falou sobre a sequ\u00eancia!<\/h3>\n<p>&#8220;N\u00e3o existe um Z\u00e9 Bonitinho, existe o Z\u00e9 Bonitinho, e ele pode ser feito por qualquer um de n\u00f3s, basta amar e gostar de fazer&#8221;. \u00c9 assim que o ator brasiliense, radicado no Rio de Janeiro, Mateus Solano explica o processo de composi\u00e7\u00e3o do cl\u00e1ssico personagem da <em><a href=\"http:\/\/df.divirtasemais.com.br\/app\/noticia\/tv\/2015\/11\/22\/noticia_tv,155649\/escolinha-do-professor-raimundo-tera-remake-vivido-pelo-filho-do-humor.shtml\">Escolinha do Professor Raimundo<\/a><\/em>, que ele volta a encenar na telinha a partir desta segunda-feira (3\/9) quando a quarta temporada do humor\u00edstico estreia, \u00e0s 22h45, no canal Viva.<\/p>\n<p>Esse \u00e9 a quarta temporada de Mateus Solano \u00e0 frente do personagem que ficou eternizado na pele do ator Jorge Loredo, que morreu em mar\u00e7o de 2015, antes da estreia da nova vers\u00e3o da Escolinha na televis\u00e3o. No entanto, o mais inusitado \u00e9 que Solano tinha sido escalado para viver outro personagem, seu Ptolomeu, papel que depois ficou com Otaviano Costa, que, inclusive, est\u00e1 de volta na nova temporada ap\u00f3s um tempo longe do humor\u00edstico. Z\u00e9 Bonitinho seria vivido por Rodrigo Lombardi, que n\u00e3o p\u00f4de assumir o compromisso.<\/p>\n<figure id=\"attachment_7671\" aria-describedby=\"caption-attachment-7671\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7671\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho.jpg\" alt=\"Coletiva da Escolinha do professor Raimundo. Cr\u00e9dito: Canal Viva\/Divulga\u00e7\u00e3o\" width=\"1200\" height=\"650\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/zebonitinho-230x125.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-7671\" class=\"wp-caption-text\">Coletiva da Escolinha do professor Raimundo. Cr\u00e9dito: Canal Viva\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>&#8220;A\u00ed pensou-se em me dar o Z\u00e9 Bonitinho. Eu fiquei muito entusiasmado, porque o Z\u00e9 Bonitinho \u00e9 um personagem muito complexo e um desafio muito grande, ao mesmo tempo que era um personagem que eu adorava. Em duas semanas estudei muito para pegar o m\u00e1ximo de tiques, o trabalho de composi\u00e7\u00e3o do Z\u00e9. E a\u00ed foi muito doido. S\u00e3o quatro temporadas, mas at\u00e9 hoje, olhar pra frente para o professor Raimundo \u00e9 muito estranho. \u00c9 coisa de maluco, desde a primeira temporada tem essa aprova\u00e7\u00e3o t\u00e3o grande do p\u00fablico, \u00e9 realmente insano&#8221;, classifica o ator.<\/p>\n<h2>Quarta temporada de <em>Escolinha do Professor Raimundo<\/em><\/h2>\n<p>Sucesso entre o p\u00fablico, a nova <em>Escolinha<\/em> retorna \u00e0 programa\u00e7\u00e3o em sua quarta temporada com algumas novidades: a presen\u00e7a de personagens ilustres do humor\u00edstico. Eust\u00e1quio ser\u00e1 encenado por \u00c9rico Br\u00e1s, enquanto Patropi chega ao programa com interpreta\u00e7\u00e3o de Marco Luque, que deixa o papel de Nerso da Capitinga, agora vivido por Gui Santana.<\/p>\n<p>&#8220;O \u00c9rico est\u00e1 genial, a mudan\u00e7a do Luque foi um acerto e o Gui tamb\u00e9m foi muito bem-vindo. Ele trouxe nuances ao Nerso. Para mim, o mais emocionante foi ver o \u00c9rico Bras fazendo o seu Eust\u00e1quio entrando de peixinho para ver a calcinha da Dona Bela. Eu quase chorei porque eu lembrei muito do Grande Otelo, quando ele fazia o Eust\u00e1quio&#8221;, lembra Solano.<\/p>\n<figure id=\"attachment_7673\" aria-describedby=\"caption-attachment-7673\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7673\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1.jpg\" alt=\"Coletiva Escolinha do Professor Raimundo. Cr\u00e9dito: Canal Viva\/Divulga\u00e7\u00e3o\" width=\"1200\" height=\"650\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1.jpg 1200w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/09\/escolinha-1-230x125.jpg 230w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-7673\" class=\"wp-caption-text\">Coletiva Escolinha do Professor Raimundo. Cr\u00e9dito: Canal Viva\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Sobre os sets filmagens, Mateus Solano compartilha que \u00e9 um ambiente de muita risada e tamb\u00e9m muita emo\u00e7\u00e3o ao lado dos companheiros de elenco Bruno Mazzeo (Raimundo Nonato),\u00a0Betty Gofman (Dona Bela), Marcelo Adnet (Rolando Lero), L\u00facio Mauro Filho (Aldemar Vig\u00e1rio), Fabiana Karla (Dona Cacilda), Marcius Melhem (Seu Boneco), Marco Ricca (Pedro Pedreira), Ot\u00e1vio Muller (Baltazar da Rocha), Marcos Caruso (Seu Peru), Evandro Mesquita (Armando Volta), Dani Calabresa (Dona Catifunda), Angelo Antonio (Joselino Barbacena), Maria Clara Gueiros (C\u00e2ndida), Rodrigo Sant&#8217;Anna (Seu Batista), Ellen Roche (Dona Capitu) e Fernanda de Freitas (Marina da Gl\u00f3ria). &#8220;A gente acha gra\u00e7a, se emociona, faz bagun\u00e7a, leva bronca. Fizemos muita bagun\u00e7a, \u00e9 um servi\u00e7o completo&#8221;, diz entre risos.<\/p>\n<p><strong><em>Escolinha do Professor Raimundo<\/em> &#8211; Quarta temporada<\/strong><br \/>\nEstreia em 3 de setembro, \u00e0s 22h45, no canal Viva. Exibi\u00e7\u00e3o de segunda a sexta, \u00e0s 22h45. Reprises: de segunda a sexta, \u00e0s 19h15 e s\u00e1bado, \u00e0s 19h30, 20h20, 21h10, 22h e 22h50.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escolinha do Professor Raimundo chega \u00e0 quarta temporada no Viva. Confira o que Mateus Solano, o Z\u00e9 Bonitinho, falou sobre a sequ\u00eancia! &#8220;N\u00e3o existe um Z\u00e9 Bonitinho, existe o Z\u00e9 Bonitinho, e ele pode ser feito por qualquer um de n\u00f3s, basta amar e gostar de fazer&#8221;. \u00c9 assim que o ator brasiliense, radicado no Rio de Janeiro, Mateus Solano [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":7670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[1148,652,731,648,2082],"class_list":["post-7668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-series","tag-escolinha-do-professor-raimundo","tag-mateus-solano","tag-quarta-temporada","tag-viva","tag-ze-bonitinho"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/7668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=7668"}],"version-history":[{"count":6,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/7668\/revisions"}],"predecessor-version":[{"id":7677,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/7668\/revisions\/7677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/7670"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=7668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=7668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=7668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}