{"id":5594,"date":"2018-03-11T14:13:02","date_gmt":"2018-03-11T17:13:02","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=5594"},"modified":"2018-03-11T14:13:02","modified_gmt":"2018-03-11T17:13:02","slug":"ex-masterchef-jiang-tera-quadro","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/ex-masterchef-jiang-tera-quadro\/","title":{"rendered":"Quem quer \u2018cebora\u2019? Ex-MasterChef Jiang Pu ter\u00e1 quadro fixo em novo programa da Band"},"content":{"rendered":"<h3>Uma das participantes mais carism\u00e1ticas do MasterChef Brasil, a chinesa Jiang Pu vai comandar um quadro do novo<em> Cozinha do Bork<\/em>, de Daniel Bork. Vai ter \u2018cebora\u2019!<\/h3>\n<p>Estreia nesta segunda-feira, nas manh\u00e3s da Band, o programa <em>Cozinha do Bork<\/em>. A partir das 8h50, de segunda a sexta, Daniel Bork vai dar receitas f\u00e1ceis, pr\u00e1ticas e baratas. A ideia \u00e9 seguir o estilo que Daniel consagrou no <em>Dia a dia<\/em>, tamb\u00e9m da Band. Isso quer dizer que os preparos escolhidos ser\u00e3o ensinados passo a passo, sempre com linguagem simples e em clima bem informal.<\/p>\n<p>\u201cMinha expectativa \u00e9 que as pessoas gostem muito porque estamos usando a experi\u00eancia para avan\u00e7ar no conte\u00fado. Al\u00e9m disso, de olho nas mensagens dos telespectadores, a Luitha Miraglia vai me ajudar a responder as d\u00favidas sobre culin\u00e1ria, o que aumenta a nossa conex\u00e3o com o p\u00fablico\u201d, diz o apresentador no material de divulga\u00e7\u00e3o da atra\u00e7\u00e3o.<\/p>\n<figure id=\"attachment_5595\" aria-describedby=\"caption-attachment-5595\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5595\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-1024x555.jpg\" alt=\"O estilo de Daniel Bork, marcado pela informalidade, ser\u00e1 mantido no novo programa\" width=\"1024\" height=\"555\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork-230x125.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2018\/03\/daniel_bork.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-5595\" class=\"wp-caption-text\">O estilo de Daniel Bork, marcado pela informalidade, ser\u00e1 mantido no novo programa<\/figcaption><\/figure>\n<p>Por mais que Daniel e Luitha sejam carism\u00e1ticos \u30fc e s\u00e3o! \u30fc , \u00e9 sobre a outra participante de <em>Cozinha do Bork<\/em> que est\u00e3o os holofotes. A ex-competidora do <strong><a href=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/brasiliense-no-masterchef\/\"><em>MasterChef<\/em><\/a><\/strong> Jiang Pu est\u00e1 de volta, para a felicidade geral da na\u00e7\u00e3o que adora o reality show. A chinesa que nos conquistou na segunda temporada do MasterChef e chegou \u00e0 semifinal vai dar dicas de culin\u00e1ria ao lado de Bork. Pelo menos desta vez a comunica\u00e7\u00e3o entre eles deve ser mais f\u00e1cil do que a de Jiang com o jurado Erick Jacquin. At\u00e9 hoje tenho minhas d\u00favidas se ela e o franc\u00eas se entendiam sempre.<\/p>\n<p>A participa\u00e7\u00e3o de Jiang ser\u00e1 em v\u00e1rios momentos de Cozinha do Bork. Entre os quadros fixos da atra\u00e7\u00e3o matutina est\u00e3o Fog\u00e3o e sa\u00fade, dedicado a comidas mais leves; Pre\u00e7o justo, quando o chef ensina a fazer receitas gastando pouco; Fa\u00e7a e venda, voltado para quem quer ganhar dinheiro com produ\u00e7\u00e3o pr\u00f3pria; Fica a dica, com segredos valiosos sendo revelados; Prato do dia; e Receita minuto, formado de um passo a passo s\u00f3 com imagens.<\/p>\n<p>Lembre momentos maravilhosos de Jiang no <em>MasterChef<\/em>!<\/p>\n<p><iframe loading=\"lazy\" width=\"1440\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/MZVUX9soUJg?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das participantes mais carism\u00e1ticas do MasterChef Brasil, a chinesa Jiang Pu vai comandar um quadro do novo Cozinha do Bork, de Daniel Bork. Vai ter \u2018cebora\u2019!<\/p>\n","protected":false},"author":57,"featured_media":5596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[49,1575,1574,47,50],"class_list":["post-5594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-band","tag-cozinha-do-bork","tag-daniel-bork","tag-gastronomia","tag-masterchef"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/5594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=5594"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/5594\/revisions"}],"predecessor-version":[{"id":5598,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/5594\/revisions\/5598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/5596"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=5594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=5594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=5594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}