{"id":24021,"date":"2024-01-09T15:00:37","date_gmt":"2024-01-09T18:00:37","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=24021"},"modified":"2024-01-09T00:42:49","modified_gmt":"2024-01-09T03:42:49","slug":"my-life-with-the-walter-boys","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/my-life-with-the-walter-boys\/","title":{"rendered":"Sossegada e nost\u00e1lgica, \u2018My life with the Walter boys\u2019 \u00e9 o que precisamos para 2024"},"content":{"rendered":"<h2><strong>Novidade da Netflix, produ\u00e7\u00e3o teen<em> My life with the Walter boys<\/em> apresenta os bons tempos de uma TV livre de grandes ang\u00fastias e amea\u00e7as zumbis (ou de drag\u00f5es)<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">Sob o prisma de produ\u00e7\u00f5es como <em>Silo, Succession<\/em> e <em>The last of us<\/em>, as produ\u00e7\u00f5es classe A da TV em 2023 apostaram alto em manter os nervos dos telespectadores \u00e0 flor da pele. Entre epis\u00f3dios cercados de muita tens\u00e3o e ang\u00fastia, poucas produ\u00e7\u00f5es puderam ser chamadas de \u201cleves\u201d no \u00faltimo ano. N\u00e3o se trata de um crime, pelo contr\u00e1rio. \u00c9 uma forma justa de prender milhares de f\u00e3s ao redor do mundo, mas vale lembrar que a outra ponta do extremo, contudo, n\u00e3o foi esquecida. \u00c9 o que prova <em>My life with the Walter boys<\/em>.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A nova produ\u00e7\u00e3o da Netflix \u2014 que teve estreia em meados do \u00faltimo m\u00eas dezembro \u2014 foi uma pedida cir\u00fargica para o \u201cwinter break\u201d do hemisf\u00e9rio Norte, ou as f\u00e9rias de ver\u00e3o em terras tupiniquins. Com um tom interiorano nost\u00e1lgico \u00e0 l\u00e1 <em>One Tree Hill<\/em> e <em>Dawson&#8217;s creek<\/em>, <em>My life with the Walter boys<\/em> \u00e9 sossegada, com boas doses de clich\u00ea e um drama bem regulado.\u00a0<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"My Life With the Walter Boys | Official Trailer | Netflix\" width=\"1440\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/pHIXtOrHF80?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"font-weight: 400\">A s\u00e9rie em 10 epis\u00f3dios teve como showrunner Melanie Halsall (que carrega no curr\u00edculo a produ\u00e7\u00e3o de projetos pequenos e essencialmente infanto-juvenis, como <em>Dead gorgeous<\/em> e <em>Itch<\/em>) e faz a adapta\u00e7\u00e3o do livro de mesmo nome de Ali Novak. A hist\u00f3ria gira em torno de Jackie (Nikki Rodriguez), uma jovem de 16 anos, moradora de Nova York, que acaba de perder os pais e a irm\u00e3 em um acidente de carro.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Agora completamente sozinha, a garota tem de \u201cenfrentar\u201d a vontade da falecida m\u00e3e de ficar sob os cuidados de Katherine (Sarah Rafferty) e morar ao lado dos novos 10 \u201cirm\u00e3os\u201d.<\/span><\/p>\n<h3><strong>Amores e dramas: a receita de uma boa s\u00e9rie teen<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Ao longo dos anos, Katherine e marido George (Marc Blucas) criaram uma grande fam\u00edlia, cheia de filhos. Um dos trunfos de <em>My life with the Walter boys<\/em> \u00e9 saber desenvolver a hist\u00f3ria de Jackie ao redor de tanta gente. N\u00e3o me entenda mal, \u00e9 claro que os 10 irm\u00e3os n\u00e3o s\u00e3o igualmente coadjuvantes da s\u00e9rie, mas sabem entrar e sair na medida do aceit\u00e1vel para que o enredo n\u00e3o se torne enfadonho.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O destaque mesmo fica com os irm\u00e3os mais velhos \u2014 mas n\u00e3o primog\u00eanitos \u2014 Cole (Noah LaLonde) e Alex (Ashby Gentry). Os dois se \u201capaixonam\u201d (na medida da paix\u00e3o que jovens de 16 anos podem ter) por Jackie, e a menina da cidade, que agora mora no interior, tamb\u00e9m passa a nutrir sentimentos por ambos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A sinopse pode at\u00e9 lembrar <em>The summer I turned pretty\/O ver\u00e3o que mudou minha vida<\/em>, mas vale pontuar que o tom da produ\u00e7\u00e3o da Netflix desce alguns degraus no drama (e no excesso de m\u00fasicas da Taylor Swift) em compara\u00e7\u00e3o com a aposta da Prime Video. Na pr\u00e1tica, Jackie tem uma personalidade mais adulta e respons\u00e1vel, assim como Alex, o que deixa a narrativa menos procedual \u2014 ou seja, sem epis\u00f3dios com hist\u00f3rias independentes \u2014 e, em consequ\u00eancia, menos ca\u00f3tica.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vale pontuar que a perfei\u00e7\u00e3o televisiva passa longe de <em>My life with the Walter boys<\/em>. As atua\u00e7\u00f5es, em maioria, s\u00e3o principiantes e os recursos t\u00e9cnicos s\u00e3o limitados. Pesa a favor da produ\u00e7\u00e3o, contudo, uma hist\u00f3ria bem contada.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novidade da Netflix, produ\u00e7\u00e3o teen My life with the Walter boys apresenta os bons tempos de uma TV livre de grandes ang\u00fastias e amea\u00e7as zumbis (ou de drag\u00f5es) Sob o prisma de produ\u00e7\u00f5es como Silo, Succession e The last of us, as produ\u00e7\u00f5es classe A da TV em 2023 apostaram alto em manter os nervos dos telespectadores \u00e0 flor da [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":24022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/24021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=24021"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/24021\/revisions"}],"predecessor-version":[{"id":24025,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/24021\/revisions\/24025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/24022"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=24021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=24021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=24021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}