{"id":16029,"date":"2020-11-14T06:18:17","date_gmt":"2020-11-14T09:18:17","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/?p=16029"},"modified":"2020-11-14T08:17:00","modified_gmt":"2020-11-14T11:17:00","slug":"quarta-temporada-de-the-crown-e-dominado-por-mulheres-fortes-leia-a-critica","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/quarta-temporada-de-the-crown-e-dominado-por-mulheres-fortes-leia-a-critica\/","title":{"rendered":"Quarta temporada de The crown \u00e9 dominada por mulheres fortes. Leia a cr\u00edtica!"},"content":{"rendered":"<h3>Rainha Elizabeth, Margareth Thatcher e principalmente a princesa Diana dominam a cena na quarta temporada de <em>The crown<\/em>. Confira a nossa opini\u00e3o sobre a sequ\u00eancia<\/h3>\n<p>N\u00e3o resta d\u00favida: as mulheres d\u00e3o as cartas e s\u00e3o as poderosas na quarta temporada da s\u00e9rie <em>The crown<\/em>, que a Netflix estreia neste domingo (15\/11). O<strong> Pr\u00f3ximo Cap\u00edtulo<\/strong> assistiu aos 10 epis\u00f3dios e te conta do que achou da sequ\u00eancia da s\u00e9rie que mostra os bastidores da fam\u00edlia real brit\u00e2nica.<\/p>\n<p>Desde o cartaz, as atrizes Emma Corrin (princesa Diana), Olivia Colman (rainha Elizabeth II) e Gillian Anderson (Margareth Thatcher) dominam a cena. E n\u00e3o \u00e9 s\u00f3 pelo talento das int\u00e9rpretes \u30fc as tr\u00eas muito bem nos pap\u00e9is\u00a0\u30fc, mas sim pelo temperamento forte de cada uma delas.<\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-16030\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-1024x416.jpg\" alt=\"\" width=\"1024\" height=\"416\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-1024x416.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-300x122.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-768x312.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-800x325.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-550x224.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz-230x94.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_cartaz.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>A a\u00e7\u00e3o come\u00e7a no fim da d\u00e9cada de 1970 e segue por 25 anos, aproximadamente. Nas primeiras cenas, Margareth Thatcher faz hist\u00f3ria ao se tornar primeira-ministra, cargo nunca ocupado por uma mulher antes. Os encontros entre ela e a rainha s\u00e3o deliciosos. O texto inspirado e cheio de ironias e do humor ingl\u00eas se destaca, al\u00e9m, \u00e9 claro, da performance das atrizes. A caracteriza\u00e7\u00e3o de uma irreconhec\u00edvel Gillian Anderson chama a aten\u00e7\u00e3o.<\/p>\n<p>Mas \u00e9 a partir do momento que Diana entra em cena que a quarta temporada mostra que tem uma protagonista. \u00c9 imposs\u00edvel tirar os olhos da jovem menina que entra para a fam\u00edlia real sem ter a m\u00ednima ideia do que est\u00e1 fazendo e se torna uma mulher amargurada dentro de casa e encantadora dos pal\u00e1cios para fora. Impressiona que Emma Corrin leve para a tela todo o carisma da Lady Di da vida real. N\u00e3o \u00e9 f\u00e1cil tirar os olhos dela.<\/p>\n<p>Por meio de Lady Di entramos a fundo num castelo povoado por pessoas importantes e reconhecidas servidas por centenas de empregados onde os moradores s\u00e3o solit\u00e1rios. A infelicidade de Diana a transforma numa daquelas hero\u00ednas pelas quais adoramos torcer \u30fc adiciona-se a\u00ed o fato de estarmos falando de uma personagem que existiu. O drama dos transtornos alimentares enfrentado por Diana ganha aten\u00e7\u00e3o especial no roteiro. Ali\u00e1s, interessante o aviso colocado pela Netflix no in\u00edcio do epis\u00f3dio em que isso fica mais expl\u00edcito de que as cenas s\u00e3o fortes e podem servir como \u201cgatilho\u201d para algumas pessoas mais sens\u00edveis ao tema.<\/p>\n<p>\u00c0 medida em que Diana vai se firmando como a grande hero\u00edna de <em>The crown<\/em>, o pr\u00edncipe Charles (Josh O\u2019Connor) cumpre trajet\u00f3ria oposta e se torna o vil\u00e3o da hist\u00f3ria. Somos levados a odiar o pr\u00edncipe de Gales desde o in\u00edcio da temporada, quando Elizabeth est\u00e1 preocupada porque, aos 30 anos, o rapaz n\u00e3o assume um relacionamento s\u00e9rio, divertindo-se com v\u00e1rias mulheres, algumas delas casadas. A verdade \u00e9 que o amor dele pela comprometida Camilla Parker-Bowles (Emerald Fennell) j\u00e1 transparece. Por isso, cenas como quando ele insiste para que Diana saia para se divertir com Camilla durante a primeira viagem oficial dele acabam despertando antipatia no p\u00fablico.<\/p>\n<figure id=\"attachment_16031\" aria-describedby=\"caption-attachment-16031\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-16031\" src=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-1024x555.jpg\" alt=\"Pr\u00edncipe Charles na s\u00e9rie The crown\" width=\"1024\" height=\"555\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-1024x555.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-300x163.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-768x416.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-800x433.jpg 800w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-550x298.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles-230x125.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-content\/uploads\/sites\/27\/2020\/11\/crown_charles.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption id=\"caption-attachment-16031\" class=\"wp-caption-text\">Charles desperta antipatia no p\u00fablico de The crown<\/figcaption><\/figure>\n<p>O roteiro de <em>The crown<\/em> n\u00e3o \u00e9 feito s\u00f3 da vida pessoal da realeza. <a href=\"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/quarta-temporada-de-the-crown-comeca-dando-agradavel-aula-de-politica\/\"><strong>A pol\u00edtica est\u00e1 presente e deixa espa\u00e7o para que Gillian Anderson e Olivia Colman tenham mais destaque nessas sequ\u00eancias<\/strong><\/a>. Seja na guerra das Malvinas, seja na composi\u00e7\u00e3o do minist\u00e9rio, ou ainda no combate ao Ir\u00e3 \u30fc as diferen\u00e7as entre Elizabeth e Margareth Thatcher se tornam cada vez mais evidente e mais insustent\u00e1vel. S\u00f3 que a majestade n\u00e3o deixa isso transparecer e \u30fc para nosso deleite \u30fc abusa das ironias e sutilezas.<\/p>\n<p>Como n\u00e3o pode deixar de ser numa produ\u00e7\u00e3o de \u00e9poca, a gente assiste a tudo de olho na dire\u00e7\u00e3o de arte e nos figurinos. E quem acompanha a fam\u00edlia real pode suspirar aliviado com as recria\u00e7\u00f5es especialmente do figurino de Lady Di, incluindo o lend\u00e1rio vestido do casamento, e os indefect\u00edveis tailleurs de Thatcher.<\/p>\n<p>O por\u00e9m da temporada \u00e9 que ela se arrasta um pouco \u30fc desculpa para apreciarmos a bela fotografia das casas de campo da realeza? \u30fc , tendo algumas cenas dispens\u00e1veis ou seguindo um ritmo lento. Nada que comprometa o resultado final da s\u00e9rie que deve ter suas atrizes figurinhas f\u00e1ceis nas premia\u00e7\u00f5es da temporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elizabeth II, Margareth Thatcher e principalmente Diana dominam a cena na quarta temporada de The crown. Confira a nossa opini\u00e3o sobre a sequ\u00eancia<\/p>\n","protected":false},"author":57,"featured_media":16032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[8,5,914],"class_list":["post-16029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-series","tag-critica","tag-netflix","tag-the-crown"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/16029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/comments?post=16029"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/16029\/revisions"}],"predecessor-version":[{"id":16050,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/posts\/16029\/revisions\/16050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media\/16032"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/media?parent=16029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/categories?post=16029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/proximocapitulo\/wp-json\/wp\/v2\/tags?post=16029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}