{"id":8461,"date":"2019-07-03T10:43:23","date_gmt":"2019-07-03T13:43:23","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=8461"},"modified":"2019-07-04T10:45:32","modified_gmt":"2019-07-04T13:45:32","slug":"curso-para-oficiais-do-itamaraty-pergunta-o-que-fazer-em-caso-de-uma-invasao-alienigena","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/curso-para-oficiais-do-itamaraty-pergunta-o-que-fazer-em-caso-de-uma-invasao-alienigena\/","title":{"rendered":"Curso para oficiais do Itamaraty pergunta o que fazer em caso de uma invas\u00e3o alien\u00edgena"},"content":{"rendered":"<p>Uma hip\u00f3tese, no m\u00ednimo curiosa, foi levantada em um dos exerc\u00edcios de fixa\u00e7\u00e3o de um curso interno para promo\u00e7\u00e3o na carreira de oficial de chancelaria, do Minist\u00e9rio de Rela\u00e7\u00f5es Exteriores (MRE). Em uma aula de gest\u00e3o patrimonial, foi perguntado aos servidores qual deveria ser a prioridade em caso de uma invas\u00e3o alien\u00edgena! E mais, a gal\u00e1xia desses poss\u00edveis alien\u00edgenas ainda \u00e9 especificada!\u00a0???<\/p>\n<p>Segundo a assessoria do Itamaraty, tratou-se de recurso ret\u00f3rico, que se usa nesse tipo de prova. No contexto fica claro que \u00e9 um cen\u00e1rio hipot\u00e9tico usado em sala de aula, n\u00e3o \u00e9 uma avalia\u00e7\u00e3o real de risco dessa natureza. O objetivo era fixar uma quest\u00e3o fundamental que, em caso de emerg\u00eancia (e, neste caso, uma emerg\u00eancia assustadora!) a prioridade \u00e9 ajudar as pessoas e n\u00e3o os bens materiais.<\/p>\n<figure id=\"attachment_8462\" aria-describedby=\"caption-attachment-8462\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8462\" src=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11.jpeg\" alt=\"\" width=\"740\" height=\"412\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11.jpeg 1000w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11-300x167.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11-768x428.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11-350x195.jpeg 350w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11-550x306.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-content\/uploads\/sites\/14\/2019\/07\/whatsapp-image-2019-07-02-at-23.06.11-230x128.jpeg 230w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><figcaption id=\"caption-attachment-8462\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>Confira a nota do Itamaraty em sua \u00edntegra:<\/strong><\/p>\n<p><em>O excerto citado faz parte de material did\u00e1tico dispon\u00edvel na rede interna do Itamaraty e destinado a preparar servidores para as promo\u00e7\u00f5es na carreira de Oficial de Chancelaria.<\/em><\/p>\n<p><em>O texto faz uso de um recurso ret\u00f3rico para fins exclusivamente did\u00e1ticos.<\/em><\/p>\n<p><em>O trecho consta da apostila de &#8220;Gest\u00e3o Patrimonial&#8221;, na qual, em seu m\u00f3dulo dois, o tema \u00e9 &#8220;Princ\u00edpio Zero&#8221;, sendo o corol\u00e1rio desse princ\u00edpio &#8220;se a situa\u00e7\u00e3o de fato inspira p\u00e2nico, ent\u00e3o o problema n\u00e3o \u00e9 de gest\u00e3o patrimonial. Terremotos, inc\u00eandios, guerras, invas\u00f5es alien\u00edgenas, etc.: preocupe-se com as pessoas, n\u00e3o com os bens (existem tamb\u00e9m preocupa\u00e7\u00f5es relacionadas a documentos e seguran\u00e7a de informa\u00e7\u00f5es, mas que tamb\u00e9m est\u00e3o fora da al\u00e7ada da gest\u00e3o patrimonial).&#8221;<\/em><\/p>\n<p><em>O item em quest\u00e3o trata de t\u00f3pico dedicado a exerc\u00edcios de fixa\u00e7\u00e3o. O que se espera dessa li\u00e7\u00e3o de preserva\u00e7\u00e3o de patrim\u00f4nio \u00e9 que o estudante saiba responder que, em casos de risco \u00e0 vida, o patrim\u00f4nio deve ficar em segundo plano.<\/p>\n<p><\/em><\/p>\n<p>Sobre a quest\u00e3o em si, o professor Jefferson Alves de Ur\u00e2nia, que ministra a disciplina de atualidades e realidade do DF no IMP Concursos, acredita que n\u00e3o merece pol\u00eamica e que vale lembrar que \u00e9 um exerc\u00edcio de fixa\u00e7\u00e3o aplicado pelo Itamaraty. \u201cA quest\u00e3o enumera uma serie de cat\u00e1strofe simult\u00e2nea inimagin\u00e1veis, terremoto, tsunami e explos\u00e3o de bomba at\u00f4mica, a cita\u00e7\u00e3o de uma invas\u00e3o alien\u00edgena s\u00f3 deixa a afirma\u00e7\u00e3o com um ar de cat\u00e1strofe total. Vejo o item como uma forma de preparar o futuro profissional de como agir em casos extremos; qual deve ser a prioridade a ser seguida\u201d, diz.<\/p>\n<h3>Sons de p\u00e1ssaros<\/h3>\n<p>N\u00e3o \u00e9 a primeira vez que provas de \u00f3rg\u00e3os p\u00fablicos apresentam conte\u00fados exc\u00eantricos. A prova de ingl\u00eas para a carreira diplom\u00e1tica de 2013 exigia a tradu\u00e7\u00e3o do ingl\u00eas para o portugu\u00eas de um texto que mencionava diversos tipos de sons emitidos por p\u00e1ssaros. Para resolver a quest\u00e3o, o candidato deveria saber as palavras em portugu\u00eas correspondentes aos termos &#8220;cackle&#8221;, &#8220;croak&#8221;, &#8220;whistle&#8221; e &#8220;squawk&#8221;. De acordo com o dicion\u00e1rio Michaelis, as tradu\u00e7\u00f5es mais pr\u00f3ximas desses termos s\u00e3o, respectivamente, &#8220;cacarejar&#8221;, &#8220;coaxar&#8221;, &#8220;assobiar&#8221; e &#8220;grasnar&#8221;.<\/p>\n<h3>Zorra, novelas e duplas sertanejas<\/h3>\n<p>Em 2012, o caderno de provas de atualidades do concurso p\u00fablico da Prefeitura de Cambem, no norte do Paran\u00e1, trouxe quest\u00f5es inusitadas. Um dos itens questionou: &#8220;A frase que deixou a personagem Val\u00e9ria famosa no programa Zorra Total \u00e9: &#8220;Ai, que louca que sou!&#8221;, &#8220;Ai, como sou mordida!&#8221;, &#8220;Ai, que loucura!&#8221;, &#8220;Ai, como sou maluca!&#8221; ou &#8220;Ai, como eu sou bandida!&#8221;?<\/p>\n<p>No mesmo caderno de provas, chamaram aten\u00e7\u00e3o quest\u00f5es sobre o nome da m\u00fasica do cantor Michel Tel\u00f3 que o craque do Real Madrid Cristiano Ronaldo escolheu para fazer uma coreografia de comemora\u00e7\u00e3o de gol. \u201cAi se eu te aperto\u201d; \u201cAi como sou esperto\u201d; \u201cAi del\u00edcia&#8221;; \u201cAi se eu te pego\u201d; \u201cDel\u00edcia, del\u00edcia assim voc\u00ea me mata&#8221;, eram as poss\u00edveis respostas.<\/p>\n<p>A cantora Paula Fernandes tamb\u00e9m foi conte\u00fado da sele\u00e7\u00e3o que questionou qual novela ela j\u00e1 havia participado na Rede Globo antes de se tornar famosa. Al\u00e9m dela, outros sertanejos tamb\u00e9m foram citados em perguntas como: &#8220;Assinale qual dupla sertaneja que anunciou seu fim durante o show, mas depois alegou ser um mal-entendido&#8221;. As alternativas para as respostas eram: Bruno e Marrone, Jorge e Mateus, Fernando e Sorocaba, Zez\u00e9 di Camargo e Luciano ou Jo\u00e3o Bosco e Vin\u00edcius.<\/p>\n<p>O professor do IMP lembra que em concursos que cobram a \u00e1rea de atualidades j\u00e1 foram vistas quest\u00f5es que fogem a regra do razo\u00e1vel, como por exemplo: Qual era o nome do livro da Bruna surfistinha? Qual o nome de uma atriz que interpretava determinado papel numa certa novela? Nome do vencedor do BBB de determinada edi\u00e7\u00e3o? Por\u00e9m, para o professor, essas quest\u00f5es s\u00e3o mais comuns em certames realizados por bancas menores.<\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma hip\u00f3tese, no m\u00ednimo curiosa, foi levantada em um dos exerc\u00edcios de fixa\u00e7\u00e3o de um curso interno para promo\u00e7\u00e3o na carreira de oficial de chancelaria, do Minist\u00e9rio de Rela\u00e7\u00f5es Exteriores (MRE). Em uma aula de gest\u00e3o patrimonial, foi perguntado aos servidores qual deveria ser a prioridade em caso de uma invas\u00e3o alien\u00edgena! E mais, a gal\u00e1xia desses poss\u00edveis alien\u00edgenas ainda [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":8465,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177],"tags":[771,573,761,460,770],"class_list":["post-8461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governo-federal","tag-alienigena","tag-itamaraty","tag-ministerio-das-relacoes-exteriores","tag-mre","tag-oficial-de-chancelaria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=8461"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8461\/revisions"}],"predecessor-version":[{"id":8476,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8461\/revisions\/8476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/8465"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=8461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=8461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=8461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}