{"id":8252,"date":"2019-05-16T13:36:11","date_gmt":"2019-05-16T16:36:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=8252"},"modified":"2019-05-16T13:36:11","modified_gmt":"2019-05-16T16:36:11","slug":"ibge-deve-dividir-vagas-do-censo-em-dois-editais-o-primeiro-esta-previsto-para-agosto","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/ibge-deve-dividir-vagas-do-censo-em-dois-editais-o-primeiro-esta-previsto-para-agosto\/","title":{"rendered":"IBGE deve dividir vagas do Censo em dois editais, o primeiro est\u00e1 previsto para agosto"},"content":{"rendered":"<p>A expectativa \u00e9 grande entre os concurseiros ap\u00f3s o an\u00fancio da abertura de 234.416 vagas para o Censo Demogr\u00e1fico de 2020, feito pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). De acordo com a assessoria do \u00f3rg\u00e3o, dever\u00e3o ser publicados dois editais, sendo um espec\u00edfico para recenseadores, a princ\u00edpio. A previs\u00e3o \u00e9 que o primeiro edital seja divulgado em agosto, ou seja, tr\u00eas meses antes do prazo limite, de novembro, estipulado na autoriza\u00e7\u00e3o de 6 de maio.<\/p>\n<p>Os profissionais ser\u00e3o contratados por tempo determinado, por meio de processo seletivo simplificado, e poder\u00e3o ser contratados a partir de janeiro de 2020.<\/p>\n<p>Do total de vagas, 196 mil ser\u00e3o para recenseador que coleta as informa\u00e7\u00f5es junto \u00e0 popula\u00e7\u00e3o. Outro cargo com grande n\u00famero de vagas \u00e9 o de agente censit\u00e1rio supervisor (23.578). Ser\u00e3o contratados tamb\u00e9m supervisores, coordenadores censit\u00e1rios e agentes censit\u00e1rios operacionais (<a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2019\/05\/06\/noticiasinterna,39524\/ibge-recebe-autorizacao-para-abrir-edital-com-234-416-vagas-para-censo.shtml\"><strong>confira a distribui\u00e7\u00e3o de vagas aqui<\/strong><\/a>). O prazo de dura\u00e7\u00e3o dos contratos dever\u00e1 ser de at\u00e9 um ano, com possibilidade de prorroga\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h3>Mais vagas no IBGE<\/h3>\n<p>Na semana passada, o Minist\u00e9rio da Economia publicou no Di\u00e1rio Oficial da Uni\u00e3o, outra autoriza\u00e7\u00e3o para que o IBGE abra nova sele\u00e7\u00e3o p\u00fablica simplificada. Ser\u00e3o oferecidas 400 novas oportunidades tempor\u00e1rias para o posto de analistas censit\u00e1rios. Segundo a portaria, os novos funcion\u00e1rios poder\u00e3o ser contratados a partir de setembro deste ano, para atuarem nas etapas de planejamento, acompanhamento e suporte especializado, relativas ao Censo Demogr\u00e1fico 2020. <a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2019\/04\/30\/noticiasinterna,39507\/ministerio-da-economia-autoriza-nova-selecao-com-400-vagas-para-o-ibge.shtml\"><strong>Saiba mais aqui!\u00a0<\/strong><\/a><\/p>\n<p>Em mar\u00e7o outra sele\u00e7\u00e3o para o instituto foi anunciada, desta vez com 209 vagas. Esse edital est\u00e1 mais encaminhado e j\u00e1 tem banca organizadora escolhida. O Instituto Brasileiro de Apoio e Desenvolvimento Executivo (Ibade) ser\u00e1 o respons\u00e1vel pela sele\u00e7\u00e3o de novos 209 funcion\u00e1rios tempor\u00e1rios do \u00f3rg\u00e3o. Segundo a assessoria do \u00f3rg\u00e3o, a expectativa \u00e9 de que o edital seja publicado at\u00e9 15 de maio. Os candidatos aprovados ser\u00e3o contratados para atuar no Censo Experimental de 2019. <a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2019\/04\/26\/noticiasinterna,39497\/ibge-escolhe-banca-organizadora-para-nova-selecao-publica.shtml\"><strong>Saiba mais aqui!\u00a0<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A expectativa \u00e9 grande entre os concurseiros ap\u00f3s o an\u00fancio da abertura de 234.416 vagas para o Censo Demogr\u00e1fico de 2020, feito pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). De acordo com a assessoria do \u00f3rg\u00e3o, dever\u00e3o ser publicados dois editais, sendo um espec\u00edfico para recenseadores, a princ\u00edpio. A previs\u00e3o \u00e9 que o primeiro edital seja divulgado em agosto, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":8253,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177],"tags":[714,146],"class_list":["post-8252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governo-federal","tag-censo-2020","tag-ibge"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=8252"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8252\/revisions"}],"predecessor-version":[{"id":8254,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8252\/revisions\/8254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/8253"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=8252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=8252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=8252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}