{"id":8142,"date":"2019-04-11T17:13:09","date_gmt":"2019-04-11T20:13:09","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=8142"},"modified":"2019-04-11T17:13:09","modified_gmt":"2019-04-11T20:13:09","slug":"onyx-anuncia-contratacao-de-1-000-policiais-federais-para-pacote-anticrime-de-moro","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/onyx-anuncia-contratacao-de-1-000-policiais-federais-para-pacote-anticrime-de-moro\/","title":{"rendered":"Onyx anuncia contrata\u00e7\u00e3o de 1.000 policiais federais para pacote anticrime de Moro"},"content":{"rendered":"<p><em>Rodolfo Costa<\/em> &#8211; Durante participa\u00e7\u00e3o de solenidade para marcar os 100 primeiros dias de governo, no Pal\u00e1cio do Planalto, o ministro-chefe da Casa Civil, Onyx Lorenzoni, anunciou que vai convocar 1.000 candidatos aprovados no concurso da Pol\u00edcia Federal, de 2018, para compor o pacote anticrime do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;O Brasil tem reacendido a esperan\u00e7a de que o pa\u00eds dar\u00e1 certo e o trabalho do grupo de ministros vai reafirmar isso. O presidente disse que vamos combater a criminalidade, corrup\u00e7\u00e3o. Instalei pacote anticrime extraordin\u00e1rio do ministro S\u00e9rgio Moro e est\u00e1 ajustado ao aproveitamento de 1.000 novos policiais federais aprovados em concurso p\u00fablico e que est\u00e3o em fase de reformar a nossa PF no que diz respeito ao combate, crime organizado e corrup\u00e7\u00e3o. Portanto, o Brasil que vimos hoje apenas no seu alvorecer j\u00e1 \u00e9 o novo pa\u00eds, porque tem um governo decente, um presidente honesto e um corpo de ministro que s\u00f3 tem um sonho: servir todo dia de forma mais humilde, eficiente e eficaz,&#8221; afirmou Onyx.<\/p>\n<p>&nbsp;<\/p>\n<p>Ao todo, o concurso ofereceu 500 vagas, sendo 150 para delegado, 60 para perito criminal, 180 agente, 80 para escriv\u00e3o e 30 para papiloscopista. Os sal\u00e1rios iniciais variam entre R$ 11.983,26 e R$ 22.672,48, para jornadas de trabalho de 40 horas semanais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodolfo Costa &#8211; Durante participa\u00e7\u00e3o de solenidade para marcar os 100 primeiros dias de governo, no Pal\u00e1cio do Planalto, o ministro-chefe da Casa Civil, Onyx Lorenzoni, anunciou que vai convocar 1.000 candidatos aprovados no concurso da Pol\u00edcia Federal, de 2018, para compor o pacote anticrime do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro. &nbsp; &#8220;O Brasil tem reacendido a [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":8143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[701,564,348,702],"class_list":["post-8142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","tag-onyx-lorenzoni","tag-pf","tag-policia-federal","tag-sergio-moro"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=8142"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8142\/revisions"}],"predecessor-version":[{"id":8144,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/8142\/revisions\/8144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/8143"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=8142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=8142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=8142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}