{"id":7811,"date":"2018-12-13T13:15:45","date_gmt":"2018-12-13T15:15:45","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=7811"},"modified":"2018-12-13T17:38:51","modified_gmt":"2018-12-13T19:38:51","slug":"colnago-sugere-reduzir-numero-de-carreiras-federais-para-menos-de-20","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/colnago-sugere-reduzir-numero-de-carreiras-federais-para-menos-de-20\/","title":{"rendered":"Colnago sugere reduzir n\u00famero de carreiras federais para menos de 20"},"content":{"rendered":"<p><em>Rosana Hessel<\/em> &#8211; O ministro do Planejamento, Esteves Colnago, avalia que a reforma administrativa dar\u00e1 trabalho para o pr\u00f3ximo governo, pois mudar\u00e1 toda a estrutura atual. \u201cA reforma administrativa \u00e9 t\u00e3o dif\u00edcil quanto a reforma da Previd\u00eancia\u201d, resumiu ministro, nesta quinta-feira (13\/12), durante caf\u00e9 da manh\u00e3 com jornalistas. Ele contou que algumas ideias para o modelo foram passadas para a nova equipe econ\u00f4mica e incluem mudan\u00e7as na estrutura de carreiras e nos processos de avalia\u00e7\u00e3o dos servidores.<\/p>\n<p>Segundo o ministro, que far\u00e1 parte da nova equipe econ\u00f4mica, uma das propostas apresentadas por ele ao futuro ministro da Economia, Paulo Guedes, \u00e9 reduzir o n\u00famero de carreiras de 309 para \u201calgo inferior a 20\u201d. \u201cA ideia \u00e9 criar novas carreiras com o sal\u00e1rio de entrada pr\u00f3ximo ao que a iniciativa privada paga, algo em torno de R$ 5 mil\u201d, disse ele, lembrando que, o teto hoje em torno R$ 25 mil, s\u00f3 ser\u00e1 atingido pelos servidores que tiverem os melhores desempenhos. \u201cA ideia \u00e9 que se remunere o bom gestor melhor que os demais. O grosso dos servidores ter\u00e1 um sal\u00e1rio bem mais baixo\u201d, explicou.<\/p>\n<p>Outra proposta \u00e9 instituir processos de avalia\u00e7\u00e3o de desempenho de servidores, como est\u00e1 previsto na Constitui\u00e7\u00e3o. Al\u00e9m disso, a garantia de empregabilidade durante o est\u00e1gio probat\u00f3rio depender\u00e1 de uma avalia\u00e7\u00e3o mais criteriosa.\u201cEstamos pensando em alterar a metodologia durante o est\u00e1gio probat\u00f3rio para que os melhores se destaquem. Esse est\u00e1gio n\u00e3o garante que quem passou no concurso ser\u00e1 servidor p\u00fablico \u201d, explicou ele, propondo mudan\u00e7a no costume atual de que o est\u00e1gio n\u00e3o faz a peneira necess\u00e1ria entre quem passou no concurso e quem pode prestar o servi\u00e7o p\u00fablico com mais qualidade. \u201cO est\u00e1gio perdeu a capacidade de avaliar e a mudan\u00e7a pode incentivar a pessoa a melhorar o desempenho e se engaje melhor. Mas isso s\u00e3o ideias que precisam ser encampadas pelo novo governo\u201d, explicou.<\/p>\n<p>O secret\u00e1rio executivo do Planejamento, Gleisson Rubin, refor\u00e7ou que o processo de digitaliza\u00e7\u00e3o dos servi\u00e7os ser\u00e1 intensificado no pr\u00f3ximo governo. Ele revelou que a digitaliza\u00e7\u00e3o de 30 processos gerou uma economia de R$ 600 milh\u00f5es. \u201cTemos uma jornada de mais de 1.740 processos com potencial de gerar uma economia de centenas de bilh\u00f5es reais para o Brasil\u201d, disse. Segundo Rubin, atualmente, a digitaliza\u00e7\u00e3o est\u00e1 em 100 processos por ano. Se mantivermos esse ritmo, levaremos 10 anos. \u201cNossa expectativa \u00e9 reduzir atingir esse processo em dois a tr\u00eas anos\u201d, afirmou.<\/p>\n<p><a href=\"https:\/\/www.correiobraziliense.com.br\/app\/noticia\/economia\/2018\/12\/13\/internas_economia,725120\/colnago-reforma-administrativa-sera-tao-dificil-quanto-a-da-previden.shtml\">\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rosana Hessel &#8211; O ministro do Planejamento, Esteves Colnago, avalia que a reforma administrativa dar\u00e1 trabalho para o pr\u00f3ximo governo, pois mudar\u00e1 toda a estrutura atual. \u201cA reforma administrativa \u00e9 t\u00e3o dif\u00edcil quanto a reforma da Previd\u00eancia\u201d, resumiu ministro, nesta quinta-feira (13\/12), durante caf\u00e9 da manh\u00e3 com jornalistas. Ele contou que algumas ideias para o modelo foram passadas para a [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":7812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[664,663,214,92],"class_list":["post-7811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","tag-carreiras-federais","tag-colnago","tag-estabilidade","tag-ministerio-do-planejamento"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/7811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=7811"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/7811\/revisions"}],"predecessor-version":[{"id":7816,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/7811\/revisions\/7816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/7812"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=7811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=7811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=7811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}