{"id":5768,"date":"2016-09-15T09:47:55","date_gmt":"2016-09-15T12:47:55","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=5768"},"modified":"2016-09-16T14:56:44","modified_gmt":"2016-09-16T17:56:44","slug":"nao-confirmariam-minha-autodeclaracao-por-ter-nariz-atipico-diz-candidata-diplomata","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/nao-confirmariam-minha-autodeclaracao-por-ter-nariz-atipico-diz-candidata-diplomata\/","title":{"rendered":"Itamaraty aceita 25 recursos de candidatos que se inscreveram por cotas raciais"},"content":{"rendered":"<p><em>Do Correio Braziliense<\/em> &#8211; Como o <strong><a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2016\/09\/14\/noticiasinterna,36512\/25-candidatos-conseguem-reverter-eliminacao-por-cotas-no-itamaraty.shtml\" target=\"_blank\"><em>Correio<\/em><\/a><\/strong> noticiou nesta quarta-feira (14\/9), o Itamaraty aceitou 25 recursos de candidatos que se inscreveram pelas cotas raciais para concorrer no concurso de admiss\u00e3o \u00e0 carreira diplom\u00e1tica. Ao todo, 47 pessoas foram provisoriamente eliminadas pela comiss\u00e3o respons\u00e1vel por verificar a autodeclara\u00e7\u00e3o dos que concorriam por cotas, mas tr\u00eas n\u00e3o entraram com recurso contra a decis\u00e3o.<\/p>\n<p>Entre os que tiveram a autodeclara\u00e7\u00e3o rejeitada na Comiss\u00e3o de Verifica\u00e7\u00e3o, sete haviam sido beneficiados pelo Programa de A\u00e7\u00e3o Afirmativa do Instituto Rio Branco, que concede uma bolsa de R$ 25 mil para custeio de estudos preparat\u00f3rios a pessoas que se declaram negras. O edital para concorrer ao apoio financeiro exigia que os candidatos, ap\u00f3s passarem por uma prova objetiva, se submetessem a entrevista t\u00e9cnica, como etapa de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio. Agora, 60 pessoas seguem no concurso do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores (MRE) para concorrer \u00e0s seis vagas reservadas para cotas raciais.<\/p>\n<p>Os recursos impetrados pelos candidatos foram analisados por uma nova banca composta por membros diferentes da comiss\u00e3o respons\u00e1vel pela primeira verifica\u00e7\u00e3o. Agora, o concurso seguir\u00e1 para a segunda fase. No s\u00e1bado, ser\u00e3o aplicadas provas de l\u00edngua inglesa e hist\u00f3ria do Brasil. A candidata Rebeca Silva Melo, 23 anos, se tranquilizou ao ter o recurso aceito, mas teme as etapas seguintes do concurso. \u201cPerdemos uma semana inteira nesse drama. N\u00e3o consegui estudar e isso n\u00e3o ser\u00e1 restitu\u00eddo. Por ser um concurso competitivo, \u00e9 prejudicial n\u00e3o manter o ritmo de estudo neste momento\u201d, lamentou.<\/p>\n<p><strong>Despreparo <\/strong><br \/>\nPara o diretor executivo da ONG Educafro, Frei David Santos, a quantidade de pessoas reconduzidas \u00e9 um fato inusitado. Na opini\u00e3o dele, existem problemas na prepara\u00e7\u00e3o t\u00e9cnica dos integrantes das bancas. \u201c\u00c9 um absurdo sem tamanho que o mesmo \u00f3rg\u00e3o, o Itamaraty, tenha comiss\u00f5es com vis\u00f5es diferentes. O n\u00famero de recursos aceitos mostra que algo est\u00e1 mal trabalhado\u201d, argumentou.<\/p>\n<p>Ele afirmou que a Educafro continuar\u00e1 acompanhando as pr\u00f3ximas etapas do certame para avaliar a decis\u00e3o da comiss\u00e3o que julgou os recursos. \u201cA primeira banca tinha a preocupa\u00e7\u00e3o de colorir os corredores do Itamaraty com pessoas negras. S\u00f3 saberemos se a comiss\u00e3o respons\u00e1vel pela revis\u00e3o teve o mesmo pensamento quando forem anunciados os seis candidatos para ocuparem as vagas. Se forem todos ou a maioria pardos-brancos, vamos entrar na Justi\u00e7a\u201d, ressaltou.<\/p>\n<p><em>Leia mais:<\/em> <strong><a href=\"http:\/\/concursos.correioweb.com.br\/app\/noticias\/2016\/09\/09\/noticiasinterna,36502\/itamaraty-eliminados-recebiam-r-25-mil-para-concorrer-pelas-cotas-ra.shtml\" target=\"_blank\">Eliminados recebiam R$ 25 mil para concorrer pelas cotas raciais <\/a><\/strong><\/p>\n<p>O Itamaraty n\u00e3o se posicionou sobre a divulga\u00e7\u00e3o do resultado dos recursos. O \u00f3rg\u00e3o federal informou, por nota, que existem diferen\u00e7as de crit\u00e9rios de sele\u00e7\u00e3o de candidatos negros entre o concurso para diplomatas e o Programa de A\u00e7\u00e3o Afirmativa. Eles ressaltam que, na entrevista para concorrer \u00e0s bolsas, \u201ca experi\u00eancia como negro \u00e9 apenas um dos seis crit\u00e9rios analisados\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Correio Braziliense &#8211; Como o Correio noticiou nesta quarta-feira (14\/9), o Itamaraty aceitou 25 recursos de candidatos que se inscreveram pelas cotas raciais para concorrer no concurso de admiss\u00e3o \u00e0 carreira diplom\u00e1tica. Ao todo, 47 pessoas foram provisoriamente eliminadas pela comiss\u00e3o respons\u00e1vel por verificar a autodeclara\u00e7\u00e3o dos que concorriam por cotas, mas tr\u00eas n\u00e3o entraram com recurso contra a [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":5769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[130,23,343,26],"class_list":["post-5768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-cotas-para-negros","tag-cotas-raciais","tag-diplomata","tag-negros"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=5768"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5768\/revisions"}],"predecessor-version":[{"id":5779,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5768\/revisions\/5779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/5769"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=5768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=5768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=5768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}