{"id":5498,"date":"2016-06-09T11:19:13","date_gmt":"2016-06-09T14:19:13","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=5498"},"modified":"2016-06-09T11:19:13","modified_gmt":"2016-06-09T14:19:13","slug":"5498-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/5498-2\/","title":{"rendered":"TST cria concurso nacional para unificar ingresso \u00e0 magistratura trabalhista"},"content":{"rendered":"<p>Quem pretende ingressar na magistratura trabalhista \u00e9 bom ficar atento \u00e0 nova resolu\u00e7\u00e3o do Tribunal Superior do Trabalho (TST), que aprovou a cria\u00e7\u00e3o e regulamenta\u00e7\u00e3o do concurso nacional para ingresso na carreira. Agora, todos os concursos para ju\u00edzes do trabalho substitutos do pa\u00eds dever\u00e3o ser feitos mediante a aplica\u00e7\u00e3o de provas objetivas, discursivas e pr\u00e1tica de senten\u00e7a, sindic\u00e2ncia de vida pregressa, investiga\u00e7\u00e3o social, exame de sanidade f\u00edsica e mental, prova oral e avalia\u00e7\u00e3o de t\u00edtulos.<\/p>\n<p>&nbsp;<\/p>\n<p>A nota de corte da sele\u00e7\u00e3o foi ampliada em cinco vezes o n\u00famero de candidatos inscritos. Al\u00e9m disso, ser\u00e3o reservadas 20% das vagas para negros e 5% para pessoas com defici\u00eancia. Para concorrer, os candidatos ainda ter\u00e3o que ter acumulado pelo menos tr\u00eas anos de atividades jur\u00eddicas.<\/p>\n<p>&nbsp;<\/p>\n<p>A escolha da lota\u00e7\u00e3o ser\u00e1 de prefer\u00eancia do candidato. O prazo de inscri\u00e7\u00e3o estabelecido ser\u00e1 de no m\u00ednimo trinta dias e a dura\u00e7\u00e3o da validade do certame ser\u00e1 de dois anos.<\/p>\n<p>&nbsp;<\/p>\n<p>A sele\u00e7\u00e3o ser\u00e1 realizada pela Escola Nacional de Forma\u00e7\u00e3o e Aperfei\u00e7oamento de Magistrados do Trabalho (Enemat) e organizada por comiss\u00f5es examinadoras compostas por cinco membros dentre juristas, magistrados do trabalho e representante indicado pelo Conselho Federal da Ordem dos Advogados do Brasil, sendo que cada etapa do concurso ter\u00e1 uma comiss\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo a assessoria do TST, cada tribunal regional costuma fazer o seu concurso separado, o que foi aprovado a id\u00e9ia de um concurso nacional, mas por enquanto essa organiza\u00e7\u00e3o n\u00e3o \u00e9 obrigat\u00f3ria. Os tribunais devem continuar fazendo seus concursos separados e essa decis\u00e3o s\u00f3 valer\u00e1 para aqueles que considerarem necess\u00e1ria a participa\u00e7\u00e3o no concurso nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem pretende ingressar na magistratura trabalhista \u00e9 bom ficar atento \u00e0 nova resolu\u00e7\u00e3o do Tribunal Superior do Trabalho (TST), que aprovou a cria\u00e7\u00e3o e regulamenta\u00e7\u00e3o do concurso nacional para ingresso na carreira. Agora, todos os concursos para ju\u00edzes do trabalho substitutos do pa\u00eds dever\u00e3o ser feitos mediante a aplica\u00e7\u00e3o de provas objetivas, discursivas e pr\u00e1tica de senten\u00e7a, sindic\u00e2ncia de vida [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":5499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17,5],"tags":[238,239,237],"class_list":["post-5498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-publicos","category-magistratura","category-tribunal-do-trabalho","tag-concurso-nacional","tag-magistratura-trabalhista","tag-tst"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=5498"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5498\/revisions"}],"predecessor-version":[{"id":5500,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5498\/revisions\/5500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/5499"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=5498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=5498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=5498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}