{"id":5450,"date":"2016-05-23T09:27:28","date_gmt":"2016-05-23T12:27:28","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=5450"},"modified":"2016-05-23T09:27:56","modified_gmt":"2016-05-23T12:27:56","slug":"com-um-agente-para-120-detentos-df-esta-longe-do-ideal-de-um-para-tres-segundo-onu","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/com-um-agente-para-120-detentos-df-esta-longe-do-ideal-de-um-para-tres-segundo-onu\/","title":{"rendered":"Com um agente para 120 detentos, DF est\u00e1 longe do ideal de um para tr\u00eas segundo a ONU"},"content":{"rendered":"<p><em>Do Correio Braziliense<\/em> &#8211; Aprovados no concurso da Subsecretaria do Sistema Penitenci\u00e1rio do Distrito Federal (Sesipe\/DF) para o cargo de agente penitenci\u00e1rio pressionam o governo a fim de serem convocados para a segunda etapa de curso de forma\u00e7\u00e3o. O edital de maio de 2014 previa 200 vagas para provimento imediato (sendo 40 para pessoas com defici\u00eancia) e 900 para cadastro reserva. Al\u00e9m de prova objetiva, os candidatos passaram por teste de aptid\u00e3o f\u00edsica, avalia\u00e7\u00e3o psicol\u00f3gica e aguardam o resultado da etapa de sindic\u00e2ncia de vida pregressa e investiga\u00e7\u00e3o social.<\/p>\n<p>A estudante Ana L\u00facia Cardoso Aires, 32 anos, come\u00e7ou a estudar para concursos p\u00fablicos em 2012. Na \u00e9poca, conciliava os estudos com o trabalho, mas, com os rumores de um edital para a \u00e1rea de seguran\u00e7a p\u00fablica, resolveu deixar o emprego de assistente jur\u00eddica para se dedicar integralmente para o concurso. \u201cGastei em m\u00e9dia R$ 4 mil em cursinhos, estudava das 9h \u00e0s 19h na biblioteca e depois ia para a aula. Tive o apoio dos meus familiares, mas \u00e9 muito complicado depender financeiramente de algu\u00e9m\u201d, lembrou. Ela lamentou que a situa\u00e7\u00e3o esteja se prolongando e teme que o esfor\u00e7o tenha sido em v\u00e3o. \u201cS\u00f3 queremos que o curso de forma\u00e7\u00e3o seja para todos os aprovados\u201d, argumentou.<\/p>\n<p>Segundo Leandro Allan, presidente do Sindicato dos Agentes de Atividades Penitenci\u00e1rias do Distrito Federal (Sindpen-DF), a situa\u00e7\u00e3o do sistema carcer\u00e1rio \u00e9 ca\u00f3tica. Atualmente, s\u00e3o 1,5 mil agentes em seis unidades prisionais. Cerca 400 foram retirados da Pol\u00edcia Civil para refor\u00e7ar a seguran\u00e7a nas penitenci\u00e1rias. \u201cTemos quase 15 mil presos no DF e a capacidade m\u00e1xima \u00e9 de 7 mil. H\u00e1 um agente para 120 detentos por turno. A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas recomenda um para cada tr\u00eas presos\u201d, comparou.<\/p>\n<p><strong>Edital<\/strong><br \/>\nO edital do concurso previa que apenas 200 candidatos fossem convocados para realizar o curso de forma\u00e7\u00e3o. \u201cOs candidatos integrantes do cadastro reserva t\u00eam apenas a expectativa de direito \u00e0 convoca\u00e7\u00e3o\u201d, diz o documento. A assessoria de Rodrigo Rollemberg confirmou que o governador receber\u00e1 os integrantes da comiss\u00e3o de aprovados na pr\u00f3xima semana.<\/p>\n<p>O estudante Filipe Maurer de Barros, 28,\u00a0 \u00e9 do Paran\u00e1, mas aproveitou a oportunidade do concurso no Distrito Federal para tentar realizar o sonho de ser funcion\u00e1rio p\u00fablico. Ele contou que j\u00e1 veio a Bras\u00edlia tr\u00eas vezes e que ainda est\u00e1 pagando as parcelas da \u00faltima viagem. \u201cAo todo, j\u00e1 gastei mais de R$ 3 mil de passagem, hospedagem e alimenta\u00e7\u00e3o. N\u00f3s investimos para sermos bons funcion\u00e1rios e prestarmos um bom servi\u00e7o para a sociedade, queremos respeito\u201d, disse.<br \/>\n<strong>Cadastro reserva<\/strong><br \/>\nO cadastro reserva, banco de candidatos aprovados, mas n\u00e3o classificados, foi considerado inconstitucional pelo juiz do trabalho Paulo Henrique Blair de Oliveira, da 17\u00aa Vara de Bras\u00edlia. O advogado do escrit\u00f3rio Nelson Wilians &amp; Advogados Associados Fernando Modesto explicou que a lei n\u00e3o garante direito de convoca\u00e7\u00e3o para aprovados em cadastro reserva. \u201cQuando o aprovado \u00e9 selecionado em v\u00e1rias etapas fica na expectativa de assumir o cargo, mas, juridicamente, n\u00e3o h\u00e1 obriga\u00e7\u00e3o de convoca\u00e7\u00e3o. Deveria haver legisla\u00e7\u00e3o espec\u00edfica ou acabar de vez com o cadastro reserva\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Correio Braziliense &#8211; Aprovados no concurso da Subsecretaria do Sistema Penitenci\u00e1rio do Distrito Federal (Sesipe\/DF) para o cargo de agente penitenci\u00e1rio pressionam o governo a fim de serem convocados para a segunda etapa de curso de forma\u00e7\u00e3o. O edital de maio de 2014 previa 200 vagas para provimento imediato (sendo 40 para pessoas com defici\u00eancia) e 900 para cadastro [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":5451,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,177,134],"tags":[212,15,211],"class_list":["post-5450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cadastro-reserva","category-governo-federal","category-seguranca","tag-agente-penitenciaro","tag-distrito-federal","tag-sesipe"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=5450"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5450\/revisions"}],"predecessor-version":[{"id":5453,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/5450\/revisions\/5453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/5451"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=5450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=5450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=5450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}