{"id":4789,"date":"2012-12-07T10:34:00","date_gmt":"2012-12-07T12:34:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/cetro_emite_comunicado_sobre_suspensao_de_concurso_da_ana_\/"},"modified":"2016-05-13T19:28:12","modified_gmt":"2016-05-13T22:28:12","slug":"cetro_emite_comunicado_sobre_suspensao_de_concurso_da_ana_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/cetro_emite_comunicado_sobre_suspensao_de_concurso_da_ana_\/","title":{"rendered":"Cetro emite comunicado sobre suspens\u00e3o de concurso da ANA"},"content":{"rendered":"<p>  <b>&nbsp; <\/b>  <b>Lorena Pacheco \u2013 Do CorreioWeb <\/b>  &nbsp;   <b>Para acalmar os participantes do concurso p\u00fablico da Ag\u00eancia Nacional de \u00c1guas (ANA), suspenso temporariamente pelo Tribunal Regional Federal da Primeira Regi\u00e3o (TRF-1), a Cetro Concursos, banca organizadora, publicou <a href=\"http:\/\/www.cetroconcursos.org.br\/arquivos\/anexos\/242e8ffac53400742be011ba6ba3b253.pdf\">comunicado<\/a> informado que est\u00e1 \u201cdando andamento para cumprir a decis\u00e3o em sede de liminar\u201d. &nbsp;A sele\u00e7\u00e3o oferta 45 vagas de t\u00e9cnico administrativo e est\u00e1 parada devido ao questionamento de dois candidatos que tiveram acesso \u00e0 nota dos candidatos, mas n\u00e3o \u00e0s anota\u00e7\u00f5es realizadas pelos avaliadores nas respostas. <\/b>  <b>&nbsp;<\/b>  \u201c\u00c9 uma medida inconstitucional. A banca n\u00e3o poderia deixar de dar publicidade \u00e0 prova, na \u00edntegra\u201d, explicou Lucas Rodrigues, um dos candidatos que entrou com o agravo de instrumento no TRF, com pedido de liminar, para ter o direito de consultar as corre\u00e7\u00f5es e, se necess\u00e1rio, contest\u00e1-las. A prova aconteceu em 11 de novembro. Ao todo, foram contabilizados 27.596 candidatos, o que corresponde a uma concorr\u00eancia acirrada de aproximadamente 613 inscritos para cada chance. De acordo com o edital de abertura, o sal\u00e1rio inicial para o cargo \u00e9 de R$ 4.760,18 referente a uma jornada de trabalho der 40 horas semanais.   &nbsp;  <b>Na decis\u00e3o, o juiz federal Marcelo Dolzany da Costa determinou que a ANA e a Cetro n\u00e3o podem dar continuidade ao processo seletivo antes de reabrir novo prazo para consulta a todos que participaram. <\/b>O juiz lembrou que a Constitui\u00e7\u00e3o d\u00e1 garantias de esclarecimentos de situa\u00e7\u00f5es de interesse pessoal e que \u201co estudante tem o direito l\u00edquido e certo ao recebimento de informa\u00e7\u00f5es referentes a suas notas discriminadas por disciplina e classifica\u00e7\u00e3o final frente aos demais candidatos\u201d.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lorena Pacheco \u2013 Do CorreioWeb &nbsp; Para acalmar os participantes do concurso p\u00fablico da Ag\u00eancia Nacional de \u00c1guas (ANA), suspenso temporariamente pelo Tribunal Regional Federal da Primeira Regi\u00e3o (TRF-1), a Cetro Concursos, banca organizadora, publicou comunicado informado que est\u00e1 \u201cdando andamento para cumprir a decis\u00e3o em sede de liminar\u201d. &nbsp;A sele\u00e7\u00e3o oferta 45 vagas de t\u00e9cnico administrativo e est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4789","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=4789"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4789\/revisions"}],"predecessor-version":[{"id":5367,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4789\/revisions\/5367"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=4789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=4789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=4789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}