{"id":4700,"date":"2012-10-24T15:51:00","date_gmt":"2012-10-24T17:51:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/planejamento_retifica_prazo_para_edital_do_minc_\/"},"modified":"2012-10-24T15:51:00","modified_gmt":"2012-10-24T17:51:00","slug":"planejamento_retifica_prazo_para_edital_do_minc_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/planejamento_retifica_prazo_para_edital_do_minc_\/","title":{"rendered":"Planejamento retifica prazo para edital do MinC"},"content":{"rendered":"<p>  <b>&nbsp;<\/b>  <b><i>Lorena Pacheco \u2013 Do CorreioWeb <\/i><\/b>  &nbsp;  A ministra do Planejamento, Or\u00e7amento e Gest\u00e3o, Miriam Belchior, publicou nesta quarta-feira (24\/10) retifica\u00e7\u00e3o da autoriza\u00e7\u00e3o referente ao pr\u00f3ximo concurso p\u00fablico do Minist\u00e9rio da Cultura (MinC). De acordo com a portaria, o \u00f3rg\u00e3o tem na verdade seis meses para publica\u00e7\u00e3o do novo edital, e n\u00e3o tr\u00eas como foi divulgado em julho.   &nbsp;  Assim, o MinC tem at\u00e9 31 de janeiro de 2013 para lan\u00e7ar o documento normativo da sele\u00e7\u00e3o que pretende ofertar 83 oportunidades para o cargo de t\u00e9cnico de n\u00edvel superior. Acompanhe o Blog Papo de Concurseiro para mais informa\u00e7\u00f5es.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lorena Pacheco \u2013 Do CorreioWeb &nbsp; A ministra do Planejamento, Or\u00e7amento e Gest\u00e3o, Miriam Belchior, publicou nesta quarta-feira (24\/10) retifica\u00e7\u00e3o da autoriza\u00e7\u00e3o referente ao pr\u00f3ximo concurso p\u00fablico do Minist\u00e9rio da Cultura (MinC). De acordo com a portaria, o \u00f3rg\u00e3o tem na verdade seis meses para publica\u00e7\u00e3o do novo edital, e n\u00e3o tr\u00eas como foi divulgado em julho. &nbsp; Assim, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4700","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=4700"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4700\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=4700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=4700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=4700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}