{"id":4680,"date":"2012-10-15T13:22:00","date_gmt":"2012-10-15T16:22:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/cespeunb_organizara_concurso_com_152_vagas_para_anp\/"},"modified":"2012-10-15T13:22:00","modified_gmt":"2012-10-15T16:22:00","slug":"cespeunb_organizara_concurso_com_152_vagas_para_anp","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/cespeunb_organizara_concurso_com_152_vagas_para_anp\/","title":{"rendered":"Cespe\/UnB organizar\u00e1 concurso com 152 vagas para ANP"},"content":{"rendered":"<p>  <b> <\/p>\n<p><\/b><b>Larissa Domingues \u2013 Do CorreioWeb  <\/p>\n<p><\/b><b> <\/p>\n<p><\/b>  \u00c9 oficial: o Centro de Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos da Universidade de Bras\u00edlia (Cespe\/UnB) vai organizar o concurso da <b>Ag\u00eancia Nacional de Petr\u00f3leo (ANP), previsto para sair at\u00e9 23 de outubro. Do n\u00famero total de vagas, 22 ser\u00e3o para analista administrativo, 15 para especialista em geologia e geof\u00edsica e outras 115 para especialista em regula\u00e7\u00e3o. As remunera\u00e7\u00f5es atuais para estes cargos variam de R$ <\/b><b>9.263,20 <\/b><b>a R$ <\/b><b>10.019,20.  <\/p>\n<p><\/b><b> <\/p>\n<p><\/b>  &nbsp;O \u00faltimo certame promovido pela autarquia especial aconteceu em 2008 e ofereceu 325 vagas para n\u00edveis m\u00e9dio e superior &#8211; sendo 243 reservadas a candidatos com gradua\u00e7\u00e3o e 82 a concorrentes com n\u00edvel intermedi\u00e1rio. O sal\u00e1rios, na \u00e9poca, variavam de R$ 2 mil a R$ 6 mil. Os cargos foram de especialista e t\u00e9cnico em regula\u00e7\u00e3o de petr\u00f3leo e derivados, \u00e1lcool, combust\u00edveis e g\u00e1s natural; especialista em geologia e geof\u00edsica do petr\u00f3leo e do g\u00e1s natural; e analista e t\u00e9cnico administrativo.      <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Larissa Domingues \u2013 Do CorreioWeb \u00c9 oficial: o Centro de Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos da Universidade de Bras\u00edlia (Cespe\/UnB) vai organizar o concurso da Ag\u00eancia Nacional de Petr\u00f3leo (ANP), previsto para sair at\u00e9 23 de outubro. Do n\u00famero total de vagas, 22 ser\u00e3o para analista administrativo, 15 para especialista em geologia e geof\u00edsica e outras 115 para especialista [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4680","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=4680"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4680\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=4680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=4680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=4680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}