{"id":4674,"date":"2012-10-11T11:40:00","date_gmt":"2012-10-11T14:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/mpfpe_pede_exclusao_de_clausula_em_edital_da_marinha\/"},"modified":"2012-10-11T11:40:00","modified_gmt":"2012-10-11T14:40:00","slug":"mpfpe_pede_exclusao_de_clausula_em_edital_da_marinha","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/mpfpe_pede_exclusao_de_clausula_em_edital_da_marinha\/","title":{"rendered":"MPF\/PE pede exclus\u00e3o de cl\u00e1usula em edital da Marinha"},"content":{"rendered":"<p>  <b> <\/p>\n<p><\/b><b>Do CorreioWeb<\/b>  &nbsp;  <b>Lan\u00e7ado em 2011, o processo seletivo para admiss\u00e3o no Curso de Forma\u00e7\u00e3o de Aquavi\u00e1rios, promovido pela Marinha, ter\u00e1 cl\u00e1usula de edital de exclu\u00edda. O Minist\u00e9rio P\u00fablico Federal (MPF) em Pernambuco entrou com a\u00e7\u00e3o civil p\u00fablica e condenou a Uni\u00e3o a retirar o requisito de local de resid\u00eancia como crit\u00e9rio de prefer\u00eancia para as vagas ofertadas na sele\u00e7\u00e3o.<\/b>  &nbsp;  Segundo o edital, as chances seriam destinadas preferencialmente aos candidatos residentes na \u00e1rea em jurisdi\u00e7\u00e3o da Capitania dos Portos, no estado de Pernambuco. As vagas s\u00f3 seriam preenchidas por concorrentes de outros locais caso os candidatos antes inscritos n\u00e3o fossem aptos ao ingresso no Curso de Forma\u00e7\u00e3o.  &nbsp;  Antes de entrar com a a\u00e7\u00e3o, o MPF j\u00e1 havia expedido recomenda\u00e7\u00e3o para o crit\u00e9rio publicado fosse exclu\u00eddo. Mas o pedido n\u00e3o causou efeito, permitindo que o edital ferisse o princ\u00edpio de igualdade entre os candidatos.  &nbsp;  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do CorreioWeb &nbsp; Lan\u00e7ado em 2011, o processo seletivo para admiss\u00e3o no Curso de Forma\u00e7\u00e3o de Aquavi\u00e1rios, promovido pela Marinha, ter\u00e1 cl\u00e1usula de edital de exclu\u00edda. O Minist\u00e9rio P\u00fablico Federal (MPF) em Pernambuco entrou com a\u00e7\u00e3o civil p\u00fablica e condenou a Uni\u00e3o a retirar o requisito de local de resid\u00eancia como crit\u00e9rio de prefer\u00eancia para as vagas ofertadas na sele\u00e7\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4674","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=4674"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4674\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=4674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=4674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=4674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}