{"id":4611,"date":"2012-09-18T11:13:00","date_gmt":"2012-09-18T14:13:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/edital_com_55_vagas_para_juiz_do_tjpe_saira_ate_outubro_\/"},"modified":"2012-09-18T11:13:00","modified_gmt":"2012-09-18T14:13:00","slug":"edital_com_55_vagas_para_juiz_do_tjpe_saira_ate_outubro_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/edital_com_55_vagas_para_juiz_do_tjpe_saira_ate_outubro_\/","title":{"rendered":"Edital com 55 vagas para juiz do TJPE sair\u00e1 at\u00e9 outubro"},"content":{"rendered":"<p>  &nbsp;  <b>Do CorreioWeb<\/b>  &nbsp;  <b>Na primeira quinzena de outubro o Tribunal de Justi\u00e7a de Pernambuco (TJPE) dever\u00e1 publicar o edital de abertura de seu novo concurso p\u00fablico voltado para o cargo de juiz substituto. A Funda\u00e7\u00e3o Carlos Chagas (FCC), banca organizadora escolhida pelo tribunal, firmou contrato no valor de R$ 1.249.795,00 para realiza\u00e7\u00e3o do certame. S\u00e3o previstas 55 oportunidades. &nbsp;<\/b>  <b>&nbsp;<\/b>  A expectativa do \u00f3rg\u00e3o \u00e9 que sejam inscritos cerca de cinco mil candidatos.<b> <\/b>Quatro etapas v\u00e3o compor o concurso: provas objetiva e discursiva, prova pr\u00e1tica (senten\u00e7a c\u00edvel e criminal), prova oral, e, ainda, avalia\u00e7\u00e3o de t\u00edtulos, entrevistas, investiga\u00e7\u00e3o social e exames m\u00e9dico e psicot\u00e9cnicos.&nbsp;&nbsp; &nbsp;  &nbsp;  O \u00faltimo concurso do \u00f3rg\u00e3o foi realizado em junho deste ano. Na ocasi\u00e3o, foram abertas 49 vagas, aproximadamente 5,4 mil candidatos participaram.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Do CorreioWeb &nbsp; Na primeira quinzena de outubro o Tribunal de Justi\u00e7a de Pernambuco (TJPE) dever\u00e1 publicar o edital de abertura de seu novo concurso p\u00fablico voltado para o cargo de juiz substituto. A Funda\u00e7\u00e3o Carlos Chagas (FCC), banca organizadora escolhida pelo tribunal, firmou contrato no valor de R$ 1.249.795,00 para realiza\u00e7\u00e3o do certame. S\u00e3o previstas 55 oportunidades. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4611","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=4611"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/4611\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=4611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=4611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=4611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}