{"id":30107,"date":"2023-05-29T11:59:54","date_gmt":"2023-05-29T14:59:54","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=30107"},"modified":"2023-05-29T11:59:54","modified_gmt":"2023-05-29T14:59:54","slug":"com-1-046-cargos-vagos-sindilegis-diz-que-lutara-por-mais-nomeacoes-para-camara","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/com-1-046-cargos-vagos-sindilegis-diz-que-lutara-por-mais-nomeacoes-para-camara\/","title":{"rendered":"Com 1.046 cargos vagos, Sindilegis diz que lutar\u00e1 por mais nomea\u00e7\u00f5es para C\u00e2mara"},"content":{"rendered":"<h2>Na \u00faltima semana, foi autorizada a abertura de um novo concurso da C\u00e2mara, com a oferta de 140 vagas de n\u00edvel superior<\/h2>\n<p>O Sindilegis afirmou, na \u00faltima semana, que continuar\u00e1 lutando pela nomea\u00e7\u00e3o de candidatos em cadastro reserva no <a href=\"https:\/\/www.correiobraziliense.com.br\/economia\/2023\/05\/5097022-camara-dos-deputados-aprova-edital-de-concurso-com-140-vagas-efetivas.html\">concurso da C\u00e2mara dos Deputados.<\/a> Em um <a href=\"https:\/\/sindilegis.org.br\/autorizado-o-aguardado-concurso-da-camara-dos-deputados-140-vagas-imediatas-para-cargos-de-nivel-superior\/\">texto publicado no site institucional<\/a>, a categoria alega que existe uma grande necessidade de reposi\u00e7\u00e3o no quadro de servidores da Casa.<\/p>\n<p>Na \u00faltima semana, foi autorizada a abertura de um novo concurso da C\u00e2mara, com a oferta de 140 oportunidades de n\u00edvel superior, sem men\u00e7\u00e3o a cadastro de reserva. Entretanto, <a href=\"https:\/\/www2.camara.leg.br\/transparencia\/recursos-humanos\/servidores\/quantitativos\/posicao-atual\/Cargos-ocupados-e-vagos-por-categoria-funcional\">o Sindilegis alerta para o d\u00e9ficit de 1.046 servidores<\/a>, um n\u00famero considerado &#8220;alarmante para a continuidade dos servi\u00e7os prestados pela Casa com excel\u00eancia e padr\u00e3o esperados&#8221;.<\/p>\n<p>De acordo com o Sindicato, a preocupa\u00e7\u00e3o foi discutida repetidas vezes com a Dire\u00e7\u00e3o-Geral da C\u00e2mara e a Primeira Secretaria.<\/p>\n<p>\u201cH\u00e1 alguns anos temos pedido e reiterado a necessidades de repor os quadros da Casa, especialmente ap\u00f3s a \u00faltima reforma da previd\u00eancia, que impulsionou muitos colegas a se aposentarem. O n\u00famero de vagas anunciadas ainda est\u00e1 aqu\u00e9m da necessidade, mas lutaremos para ampliar a nomea\u00e7\u00e3o dos aprovados em cadastro reserva, como fizemos no Senado e no TCU,\u201d disse Alison Souza, presidente do Sindilegis.<\/p>\n<p>O \u00faltimo concurso da C\u00e2mara dos Deputados foi realizado em 2014, com a oferta de 113 vagas. No novo concurso autorizado, a previs\u00e3o \u00e9 de que as vagas ofertadas sejam destinadas para as carreiras de:<\/p>\n<ul>\n<li>Assistente social (2 vagas);<\/li>\n<li>Consultor legislativo (34 vagas);<\/li>\n<li>Contador (3 vagas);<\/li>\n<li>Enfermeiro (2 vagas);<\/li>\n<li>Farmac\u00eautico (1 vaga);<\/li>\n<li>Analista de Inform\u00e1tica (30 vagas);<\/li>\n<li>M\u00e9dico (15 vagas);<\/li>\n<li>T\u00e9cnico legislativo (33 vagas); e<\/li>\n<li>T\u00e9cnico em material e patrim\u00f4nio (20 vagas).<\/li>\n<\/ul>\n<p>Em resposta ao <em>Papo de Concurseiro<\/em>, a assessoria da C\u00e2mara dos Deputados afirmou que a &#8220;decis\u00e3o da Mesa Diretora da C\u00e2mara dos Deputados, publicada no dia 24 de maio no Di\u00e1rio Oficial da Casa, autoriza a realiza\u00e7\u00e3o de concurso p\u00fablico para provimento de cargos efetivos da Casa. N\u00e3o h\u00e1 prazo para divulga\u00e7\u00e3o do edital. Outras informa\u00e7\u00f5es sobre o certame ser\u00e3o divulgadas oportunamente&#8221;.<\/p>\n<ul>\n<li><strong>Leia mais:\u00a0<\/strong><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/salarios-do-proximo-concurso-da-camara-podem-ser-de-mais-de-r-25-mil\/\" rel=\"bookmark\">Sal\u00e1rios do pr\u00f3ximo concurso da C\u00e2mara podem ser de mais de R$ 25 mil<\/a><\/li>\n<li><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/assembleia-legislativa-da-bahia-aprova-criacao-da-policia-penal-do-estado\/\" rel=\"bookmark\">Assembleia Legislativa da Bahia aprova cria\u00e7\u00e3o da Pol\u00edcia Penal do estado<\/a><\/li>\n<li><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/caixa-economica-anuncia-contratacao-de-800-concursados-aprovados-em-2014\/\" rel=\"bookmark\">Caixa Econ\u00f4mica anuncia contrata\u00e7\u00e3o de 800 concursados aprovados em 2014<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>*Com informa\u00e7\u00f5es do Sindilegis<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima semana, foi autorizada a abertura de um novo concurso da C\u00e2mara, com a oferta de 140 vagas de n\u00edvel superior O Sindilegis afirmou, na \u00faltima semana, que continuar\u00e1 lutando pela nomea\u00e7\u00e3o de candidatos em cadastro reserva no concurso da C\u00e2mara dos Deputados. Em um texto publicado no site institucional, a categoria alega que existe uma grande necessidade de [&hellip;]<\/p>\n","protected":false},"author":139,"featured_media":27713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,166,467,282,4,441,2869],"tags":[53,74,24,84,187,15,28],"class_list":["post-30107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autorizacao","category-camara-dos-deputados","category-carreira-judiciaria","category-concursos","category-concursos-publicos","category-poder-legislativo","category-servidores-publicos","tag-autorizacao","tag-camara-dos-deputados","tag-concurso","tag-concurso-publico","tag-concursos","tag-distrito-federal","tag-edital"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/30107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=30107"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/30107\/revisions"}],"predecessor-version":[{"id":30115,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/30107\/revisions\/30115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/27713"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=30107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=30107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=30107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}