{"id":29995,"date":"2023-05-13T01:39:43","date_gmt":"2023-05-13T04:39:43","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=29995"},"modified":"2023-05-13T01:39:43","modified_gmt":"2023-05-13T04:39:43","slug":"semana-da-enfermagem-categoria-chama-atencao-pela-diversidade-de-oportunidades","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/semana-da-enfermagem-categoria-chama-atencao-pela-diversidade-de-oportunidades\/","title":{"rendered":"Semana da Enfermagem: categoria chama aten\u00e7\u00e3o pela diversidade de oportunidades"},"content":{"rendered":"<h2>Atualmente, no pa\u00eds existem mais de 2,8 milh\u00f5es de profissionais do setor no pa\u00eds. O setor p\u00fablico, segundo especialista, \u00e9 muito vantajoso. Confira dicas para a aprova\u00e7\u00e3o:<\/h2>\n<p>No Brasil \u2014 al\u00e9m do Dia Internacional da Enfermagem, comemorado mundialmente nesta sexta-feira (12\/6) \u2014\u00a0 no per\u00edodo de 12 a 20 de maio \u00e9 celebrado\u00a0a Semana da Enfermagem. A data institu\u00edda em meados dos anos 40, consiste em uma\u00a0 homenagem a Florence Nigthingale e Ana N\u00e9ri, enfermeiras brasileiras precursora da \u00e1rea no Brasil.<\/p>\n<p>Atualmente, <a href=\"https:\/\/www.gov.br\/planalto\/pt-br\/acompanhe-o-planalto\/noticias\/2023\/05\/presidente-sanciona-lei-que-abre-credito-de-r-7-3-bi-para-o-piso-da-enfermagem\">no pa\u00eds existem mais de 2,8 milh\u00f5es de profissionais do setor no pa\u00eds<\/a>, sendo\u00a0693.400 enfermeiros, 450 mil auxiliares de\u00a0enfermagem\u00a0e 1,66 milh\u00e3o de t\u00e9cnicos de\u00a0enfermagem, os n\u00fameros constam no levantamento mais recente do Conselho Federal de\u00a0Enfermagem (Cofen). Ainda segundo o <a href=\"http:\/\/www.cofen.gov.br\/perfilenfermagem\/index.html\">Cofen, cerca de 59% dos enfermeiros atuam no servi\u00e7o p\u00fablico.<\/a><\/p>\n<p><a href=\"https:\/\/www.correiobraziliense.com.br\/economia\/2023\/05\/5094011-governo-sanciona-fonte-de-recursos-para-piso-salarial-da-enfermagem.html\">O presidente Luiz In\u00e1cio Lula da Silva (PT) sancionou a Lei 14.581\/23 que garante fonte de recursos para o pagamento\u00a0do piso nacional da enfermagem.\u00a0<\/a>A medida foi publicada no Di\u00e1rio Oficial da Uni\u00e3o desta sexta-feira (12\/5).\u00a0Com o novo piso, a previs\u00e3o \u00e9 que enfermeiros recebam pelo menos R$ 4.750 por m\u00eas; t\u00e9cnicos de enfermagem, R$ 3.325; e auxiliares de enfermagem e parteiras, R$ 2.375.<\/p>\n<p>Segundo a coordenadora das carreiras de sa\u00fade do Gran Cursos, Fernanda Barboza,\u00a0\u201co setor p\u00fablico tem muitas vantagens, como melhores sal\u00e1rios, carga hor\u00e1ria reduzida, melhores escalas e melhor qualidade de vida. Al\u00e9m disso, s\u00e3o muitas oportunidades na \u00e1rea da enfermagem al\u00e9m de hospitais e unidades de sa\u00fade&#8221;. Ela tamb\u00e9m destaca a variedade de op\u00e7\u00f5es \u00f3rg\u00e3os de atua\u00e7\u00e3o e muito deles, como os\u00a0 Minist\u00e9rios, ag\u00eancias reguladoras, empresas p\u00fablicas, poder judici\u00e1rio, as carreiras militares e policiais e at\u00e9 a \u00e1rea legislativa n\u00e3o est\u00e3o no &#8220;radar&#8221; dos profissionais da \u00e1rea.<\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/dia-das-maes-mulheres-contam-os-desafios-de-conciliar-os-estudos-com-a-maternidade\/\">Fernanda \u00e9 enfermeira, atuou por mais de 8 anos em hospitais e atualmente \u00e9 analista judici\u00e1rio na especialidade enfermagem, no Tribunal Superior do Trabalho<\/a>. Segundo a mulher, apesar dos maiores sal\u00e1rios se concentrarem nos \u00f3rg\u00e3os n\u00e3o t\u00e3o tradicionais para a \u00e1rea, como nos Tribunais de Justi\u00e7a e Minist\u00e9rios, com sal\u00e1rios que ultrapassam R$ 15 mil, a principal demanda \u00e9 para as secretarias municipais e estaduais de sa\u00fade e hospitais p\u00fablicos.<\/p>\n<p>Barboza pontua algumas orienta\u00e7\u00f5es para os concurseiros que buscam uma vaga em certames para esta \u00e1rea:<\/p>\n<ul>\n<li>\u00a0Decidir come\u00e7ar;<\/li>\n<li>Estudar com material de qualidade;<\/li>\n<li>Estudar por professores refer\u00eancias em aprova\u00e7\u00f5es, que sabem direcionar o que \u00e9 mais importante para estudar.<\/li>\n<li>Planejamento com cronograma din\u00e2mico, estudo ativo com resumos, revis\u00f5es e muitas quest\u00f5es;<\/li>\n<li>A parte mais importante, \u00e9 o equil\u00edbrio emocional para saber a import\u00e2ncia de persistir mesmo com todas as dificuldades impostas (escalas pesadas, trabalho exaustivo para cuidar de pessoas, acumula\u00e7\u00e3o de dois v\u00ednculos, pouco tempo para estudar, plant\u00f5es noturnos, concilia\u00e7\u00e3o entre vida profissional, familiar e estudos, dentre outras. \u00c9 preciso iniciar a jornada com a resili\u00eancia no entendimento de que deve ser vivido o processo, um passo de cada vez, pois a cada tijolo colocado, mas perto voc\u00ea estar\u00e1 da casa constru\u00edda (alcance da nomea\u00e7\u00e3o).<\/li>\n<\/ul>\n<p><em>*Estagi\u00e1ria sob supervis\u00e3o de Ronayre Nunes<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atualmente, no pa\u00eds existem mais de 2,8 milh\u00f5es de profissionais do setor no pa\u00eds. O setor p\u00fablico, segundo especialista, \u00e9 muito vantajoso. Confira dicas para a aprova\u00e7\u00e3o: No Brasil \u2014 al\u00e9m do Dia Internacional da Enfermagem, comemorado mundialmente nesta sexta-feira (12\/6) \u2014\u00a0 no per\u00edodo de 12 a 20 de maio \u00e9 celebrado\u00a0a Semana da Enfermagem. A data institu\u00edda em meados [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":19470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282,4,1],"tags":[4831,3795,4833,4832],"class_list":["post-29995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","category-concursos-publicos","category-sem-categoria","tag-concurso-tecnico-de-enfermagem","tag-enfermagem","tag-piso-nacional-da-enfermagem","tag-semana-da-enfermagem"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/29995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=29995"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/29995\/revisions"}],"predecessor-version":[{"id":30014,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/29995\/revisions\/30014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/19470"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=29995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=29995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=29995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}