{"id":28472,"date":"2022-12-01T10:23:59","date_gmt":"2022-12-01T13:23:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=28472"},"modified":"2022-12-01T10:23:59","modified_gmt":"2022-12-01T13:23:59","slug":"secretaria-de-saude-do-df-preve-novo-concurso-e-contratacao-de-1-535-temporarios-em-2023","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/secretaria-de-saude-do-df-preve-novo-concurso-e-contratacao-de-1-535-temporarios-em-2023\/","title":{"rendered":"Secretaria de Sa\u00fade do DF prev\u00ea novo concurso e contrata\u00e7\u00e3o de 1.535 tempor\u00e1rios em 2023"},"content":{"rendered":"<p><strong>Yasmin Rajab &#8211;<\/strong> Os profissionais da sa\u00fade do Distrito Federal poder\u00e3o conquistar a t\u00e3o sonhada vaga no servi\u00e7o p\u00fablico em 2023. A <a href=\"https:\/\/www.saude.df.gov.br\/web\/guest\/w\/sa%C3%BAde-vai-abrir-mais-1.535-vagas-para-tempor%C3%A1rios\">Secretaria de Sa\u00fade do DF<\/a> est\u00e1 se preparando para uma s\u00e9rie de contrata\u00e7\u00f5es, que incluir\u00e3o novos concursos p\u00fablicos, contrata\u00e7\u00e3o de tempor\u00e1rios e cria\u00e7\u00e3o de novas carreiras.<\/p>\n<p>Segundo o \u00f3rg\u00e3o, uma das prioridades da pasta \u00e9 a realiza\u00e7\u00e3o de um novo certame destinado aos agentes de vigil\u00e2ncia ambiental (AVA) e agentes comunit\u00e1rios em sa\u00fade (ACS), com a abertura de mais de 500 vagas para cada carreira.<\/p>\n<p>Em 2023, a pasta tamb\u00e9m prev\u00ea a realiza\u00e7\u00e3o de concurso para provimento de cargos efetivos para ambas as \u00e1reas. Ser\u00e3o abertas 17 vagas imediatas e 400 de cadastro de reserva para agentes de vigil\u00e2ncia; e 102 oportunidades imediatas e mais 500 de cadastro de reserva para agentes comunit\u00e1rios.<\/p>\n<p>J\u00e1 para o in\u00edcio do pr\u00f3ximo ano, a Secretaria de Sa\u00fade trabalha para finalizar o processo de escolha e contrata\u00e7\u00e3o de mais 300 t\u00e9cnicos em enfermagem, 50 condutores, 80 padioleiros, 70 fisioterapeutas, 50 psic\u00f3logos e 35 assistentes sociais.<\/p>\n<p>As \u00e1reas de analista e t\u00e9cnico em assist\u00eancia p\u00fablica \u00e0 sa\u00fade tamb\u00e9m ser\u00e3o contempladas. Para analista, ser\u00e3o abertas 300 vagas imediatas e mais 1.952 para forma\u00e7\u00e3o de cadastro reserva. J\u00e1 para t\u00e9cnico, ser\u00e3o ofertadas 50 vagas imediatas e outras 1.700 para cadastro de reserva.<\/p>\n<p>Os t\u00e9cnicos de enfermagem da capital tamb\u00e9m poder\u00e3o tentar vaga no servi\u00e7o p\u00fablico. Os servidores da SES est\u00e3o preparando o certame com 200 vagas imediatas e 1 mil para cadastro de reserva. O documento deve ser lan\u00e7ado ainda no primeiro semestre de 2023.<\/p>\n<p>A atual gest\u00e3o da Secretaria de Sa\u00fade tamb\u00e9m trabalha para a aprova\u00e7\u00e3o de projeto de lei, na C\u00e2mara Legislativa do DF, que cria quatro categoria dentro da carreira de especialista em sa\u00fade p\u00fablica: qu\u00edmico, educador f\u00edsico, direito e legisla\u00e7\u00e3o e m\u00e9dico veterin\u00e1rio. A proposta \u00e9 preparar um concurso com 322 vagas imediatas e 2.057 de cadastro reserva.<\/p>\n<p><strong>Leia mais:<\/strong>\u00a0<a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/especialistas-comentam-gabarito-e-questoes-da-prova-do-concurso-do-inss\/\" rel=\"bookmark\">Especialistas comentam gabarito e quest\u00f5es da prova do concurso do INSS<\/a><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/fim-do-ensino-medio-pode-ser-bom-periodo-para-comecar-a-estudar-para-concursos-diz-especialista\/\" rel=\"bookmark\">Fim do ensino m\u00e9dio pode ser bom per\u00edodo para come\u00e7ar a estudar para concursos<\/a><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concurso-pcdf-gdf-preve-certame-para-2023-entenda\/\" rel=\"bookmark\">Concurso PCDF: GDF prev\u00ea certame para 2023; entenda<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yasmin Rajab &#8211; Os profissionais da sa\u00fade do Distrito Federal poder\u00e3o conquistar a t\u00e3o sonhada vaga no servi\u00e7o p\u00fablico em 2023. A Secretaria de Sa\u00fade do DF est\u00e1 se preparando para uma s\u00e9rie de contrata\u00e7\u00f5es, que incluir\u00e3o novos concursos p\u00fablicos, contrata\u00e7\u00e3o de tempor\u00e1rios e cria\u00e7\u00e3o de novas carreiras. Segundo o \u00f3rg\u00e3o, uma das prioridades da pasta \u00e9 a realiza\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":139,"featured_media":23325,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,31,1309,282,4,10,225],"tags":[53,342,24,84,187,14,15,28,287],"class_list":["post-28472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autorizacao","category-cadastro-reserva","category-camara-legislativa","category-concursos","category-concursos-publicos","category-distrito-federal","category-saude","tag-autorizacao","tag-brasilia","tag-concurso","tag-concurso-publico","tag-concursos","tag-df","tag-distrito-federal","tag-edital","tag-saude"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=28472"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28472\/revisions"}],"predecessor-version":[{"id":28478,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28472\/revisions\/28478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/23325"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=28472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=28472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=28472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}