{"id":28029,"date":"2022-10-25T16:40:08","date_gmt":"2022-10-25T19:40:08","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=28029"},"modified":"2022-10-25T16:40:08","modified_gmt":"2022-10-25T19:40:08","slug":"acao-do-mp-ce-pede-novo-concurso-para-policia-civil-e-reestruturacao-de-delegacias","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/acao-do-mp-ce-pede-novo-concurso-para-policia-civil-e-reestruturacao-de-delegacias\/","title":{"rendered":"A\u00e7\u00e3o do MP-CE pede novo concurso para Pol\u00edcia Civil e reestrutura\u00e7\u00e3o de delegacias"},"content":{"rendered":"<p><strong>Yasmin Rajab &#8211;<\/strong> Uma a\u00e7\u00e3o ajuizada pelo <a href=\"http:\/\/www.mpce.mp.br\/\">Minist\u00e9rio P\u00fablico do Estado do Cear\u00e1 (MP-CE)<\/a> pede, com urg\u00eancia, um novo concurso p\u00fablico para delegados, escriv\u00e3es e inspetores da <a href=\"https:\/\/www.policiacivil.ce.gov.br\/\">Pol\u00edcia Civil<\/a>. A a\u00e7\u00e3o tamb\u00e9m exige a reestrutura\u00e7\u00e3o das delegacias do estado.<\/p>\n<p>Ajuizada pelos promotores de justi\u00e7a atuantes no Controle Externo da Atividade Policial, a solicita\u00e7\u00e3o tem como objetivo sanar problemas cr\u00f4nicos na estrutura f\u00edsica, de recursos humanos e presta\u00e7\u00e3o de servi\u00e7os nas delegacias de pol\u00edcia.<\/p>\n<p>A decis\u00e3o foi tomada ap\u00f3s apura\u00e7\u00f5es sobre a atual situa\u00e7\u00e3o das delegacias, que constataram fragilidades no reduzido quadro funcional e o descompasso com o crescimento da popula\u00e7\u00e3o local, falta de treinamento continuado para os policiais, comprometimento da atividade da Pol\u00edcia Civil, precariedade f\u00edsica em delegacias e falta de equipamentos fundamentais para o pleno desenvolvimento das atribui\u00e7\u00f5es da institui\u00e7\u00e3o.<\/p>\n<p>O Minist\u00e9rio P\u00fablico requer judicialmente a realiza\u00e7\u00e3o de um novo concurso p\u00fablico e reforma das delegacias de pol\u00edcia, incluindo um novo estacionamento, cofres para guardar entorpecentes, armas e objetos apreendidos e novas portas e janelas com grades.<\/p>\n<p>Tamb\u00e9m \u00e9 solicitado que cada delegacia possua ao menos tr\u00eas impressoras multifuncionais, renova\u00e7\u00e3o e acr\u00e9scimo de viaturas, drones para as delegacias de Fortaleza, al\u00e9m de equipamentos espec\u00edficos para as Delegacias de Combate aos Crimes Tribut\u00e1rios, Meio Ambiente e Acidentes e Delitos de Tr\u00e2nsito.<\/p>\n<p><strong>Leia mais:<\/strong>\u00a0<a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/tcdf-autoriza-prosseguimento-do-concurso-para-a-policia-militar-do-df\/\" rel=\"bookmark\">TCDF autoriza prosseguimento do concurso para a Pol\u00edcia Militar do DF<\/a><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governadora-do-ceara-sanciona-lei-de-estruturacao-da-cagece\/\" rel=\"bookmark\">Governadora do Cear\u00e1 sanciona lei de estrutura\u00e7\u00e3o da Cagece<\/a><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/receita-federal-assina-contrato-com-a-fgv-para-organizacao-de-novo-concurso\/\" rel=\"bookmark\">Receita Federal assina contrato com a FGV para organiza\u00e7\u00e3o de novo concurso<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yasmin Rajab &#8211; Uma a\u00e7\u00e3o ajuizada pelo Minist\u00e9rio P\u00fablico do Estado do Cear\u00e1 (MP-CE) pede, com urg\u00eancia, um novo concurso p\u00fablico para delegados, escriv\u00e3es e inspetores da Pol\u00edcia Civil. A a\u00e7\u00e3o tamb\u00e9m exige a reestrutura\u00e7\u00e3o das delegacias do estado. Ajuizada pelos promotores de justi\u00e7a atuantes no Controle Externo da Atividade Policial, a solicita\u00e7\u00e3o tem como objetivo sanar problemas cr\u00f4nicos na [&hellip;]<\/p>\n","protected":false},"author":139,"featured_media":28030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[532,282,4,66,2856,2869],"tags":[839,24,84,187,107],"class_list":["post-28029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-policial","category-concursos","category-concursos-publicos","category-ministerio-publico","category-policia-civil","category-servidores-publicos","tag-carreira-policial","tag-concurso","tag-concurso-publico","tag-concursos","tag-policia-civil"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=28029"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28029\/revisions"}],"predecessor-version":[{"id":28041,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/28029\/revisions\/28041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/28030"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=28029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=28029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=28029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}