{"id":24896,"date":"2022-05-30T20:35:53","date_gmt":"2022-05-30T23:35:53","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=24896"},"modified":"2022-05-30T20:35:53","modified_gmt":"2022-05-30T23:35:53","slug":"concurso-seduc-go-banca-reguladora-e-definida","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concurso-seduc-go-banca-reguladora-e-definida\/","title":{"rendered":"Concurso Seduc-GO: banca reguladora \u00e9 definida"},"content":{"rendered":"<h2><strong>O novo certame ofertar\u00e1 5.050 vagas para o cargo de Professor \u2014 N\u00edvel III e foi anunciado em abril deste ano<\/strong><\/h2>\n<p><span style=\"font-weight: 400\"><strong>Raphaela Peixoto* \u2014<\/strong> O <a href=\"https:\/\/www.iades.com.br\/\">Instituto Americano de Desenvolvimento (Iades)<\/a> foi contratado para ser a banca reguladora do novo concurso da Secretaria de Estado da Educa\u00e7\u00e3o de Goi\u00e1s (Seduc-GO), que ofertar\u00e1 5.050 vagas para o cargo de Professor \u2014 N\u00edvel III, do quadro permanente do magist\u00e9rio.\u00a0<\/span><span style=\"font-weight: 400\">A decis\u00e3o foi publicada no Di\u00e1rio Oficial de Goi\u00e1s desta segunda-feira (30\/5), por meio do Extrato de Dispensa de Licita\u00e7\u00e3o N\u00ba 019\/2022. De acordo com o documento a contrata\u00e7\u00e3o tem o valor de\u00a0 R$ 1.676.000. Ela tamb\u00e9m \u00e9 fundamentada legalmente pelo artigo 24, inciso XIII da Lei Federal n\u00ba 8.666\/1.993.<\/span><\/p>\n<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concurso-seduc-go-novo-edital-vai-ofertar-mais-de-10-mil-vagas\/\"><span style=\"font-weight: 400\">A confirma\u00e7\u00e3o deste certame ocorreu em abril deste ano, atrav\u00e9s de publica\u00e7\u00e3o do Sindicato dos Trabalhadores de Educa\u00e7\u00e3o de Goi\u00e1s (Sintego) em suas redes sociais<\/span><\/a><span style=\"font-weight: 400\">. Segundo a presidente do sindicato, Bia de Lima,\u00a0 o quadro de professores do estado est\u00e1 bastante defasado: &#8220;A educa\u00e7\u00e3o est\u00e1 precisando renovar e melhorar o seu quadro, j\u00e1 que querendo ou n\u00e3o nossa carreira de fato tem as pessoas se envelhecendo&#8221;. \u00c0 \u00e9poca era previsto a oferta de 10.100 vagas, 50% para contrata\u00e7\u00e3o imediata e o restante para forma\u00e7\u00e3o de cadastro reserva.<\/span><\/p>\n<p><span style=\"font-weight: 400\">J\u00e1 havia uma previs\u00e3o de concurso para a pasta anunciada em 2021, na \u00e9poca a secret\u00e1ria de educa\u00e7\u00e3o do estado, F\u00e1tima Gravioli, e o governador, Ronaldo Caiado havia anunciou em entrevista a r\u00e1dio<em> CBN<\/em>\u00a0\u2014 e n\u00e3o tinha confirmado a quantidade de vagas e o cronograma do certame.<\/span><\/p>\n<h2><strong>\u00daltimo certame\u00a0<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">O \u00faltimo concurso realizado pela Secretaria foi realizado em 2018. Ele ofertou 900 vagas para professores de n\u00edvel 3, nas \u00e1reas de matem\u00e1tica, qu\u00edmica e f\u00edsica, al\u00e9m da forma\u00e7\u00e3o de cadastro reserva com remunera\u00e7\u00e3o inicial que chegava a R$ 3.126,35 e foi organizado pelo Instituto Quadrix.<\/span><span style=\"font-weight: 400\">\u00a0A prova foi aplicada\u00a0 nos seguintes munic\u00edpios goianos: An\u00e1polis\/GO, Aparecida de Goi\u00e2nia\/GO, Bras\u00edlia\/DF, Catal\u00e3o\/GO, Formosa\/GO, Goi\u00e2nia\/GO, Goi\u00e1s\/GO, Ipor\u00e1\/GO, Itumbiara\/GO, Jata\u00ed\/GO, Luzi\u00e2nia\/GO e Porangatu\/GO.<\/span><\/p>\n<p><strong>*Estagi\u00e1ria sob supervis\u00e3o de Ronayre Nunes<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo certame ofertar\u00e1 5.050 vagas para o cargo de Professor \u2014 N\u00edvel III e foi anunciado em abril deste ano Raphaela Peixoto* \u2014 O Instituto Americano de Desenvolvimento (Iades) foi contratado para ser a banca reguladora do novo concurso da Secretaria de Estado da Educa\u00e7\u00e3o de Goi\u00e1s (Seduc-GO), que ofertar\u00e1 5.050 vagas para o cargo de Professor \u2014 N\u00edvel [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":24899,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282,4,887,1],"tags":[3925,84,95,3678],"class_list":["post-24896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","category-concursos-publicos","category-goias","category-sem-categoria","tag-carreira-docente","tag-concurso-publico","tag-educacao","tag-seduc-go"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/24896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=24896"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/24896\/revisions"}],"predecessor-version":[{"id":24902,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/24896\/revisions\/24902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/24899"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=24896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=24896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=24896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}