{"id":2331,"date":"2012-08-31T10:01:00","date_gmt":"2012-08-31T13:01:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo_federal_vai_criar_63_mil_vagas_em_2013\/"},"modified":"2012-08-31T10:01:00","modified_gmt":"2012-08-31T13:01:00","slug":"governo_federal_vai_criar_63_mil_vagas_em_2013","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/governo_federal_vai_criar_63_mil_vagas_em_2013\/","title":{"rendered":"Governo federal vai criar 63 mil vagas em 2013"},"content":{"rendered":"<p>  <b> <\/p>\n<p><\/b><b>Da Ag\u00eancia Brasil<\/b><b> <\/p>\n<p><\/b>  <b>O governo federal prev\u00ea a cria\u00e7\u00e3o de 63 mil vagas para cargos p\u00fablicos em 2013.<\/b> Os novos postos de trabalho est\u00e3o previstos no Projeito de Lei Or\u00e7ament\u00e1ria Anual (Ploa), que foi enviado ontem (30) ao Congresso Nacional. <\/p>\n<p>  <b>Segundo o Minist\u00e9rio do Planejamento, deste total, a previs\u00e3o \u00e9 que 61.682 vagas sejam preenchidas j\u00e1 no ano que vem<\/b>. As vagas devem ser preenchidas por concurso p\u00fablico. No entanto, as contrata\u00e7\u00f5es devem obedecer \u00e0s necessidades de contrata\u00e7\u00e3o dos diversos \u00f3rg\u00e3os e entidades p\u00fablicas. <\/p>\n<p>  <b>Das vagas previstas, 53 mil ser\u00e3o para preencher cargos no Executivo.<\/b> A ministra do Planejamento, Miriam Belchior, informou que cerca de 21 mil novas vagas ser\u00e3o para a \u00e1rea da Educa\u00e7\u00e3o. \u201cS\u00e3o cargos fundamentais para expans\u00e3o da rede de universidades e alcan\u00e7ar a meta de institutos t\u00e9cnicos no pa\u00eds\u201d, disse. <\/p>\n<p>  Os novos concursados v\u00e3o onerar em R$ 3 bilh\u00f5es os gastos do governo com folha de pagamento em 2013. A despesa ser\u00e1 adicionada aos R$ 11,3 bilh\u00f5es concedidos de reajuste salarial a cerca de 1,7 milh\u00f5es de servidores, ativos e inativos, do Executivo. Os tr\u00eas poderes totalizam cerca de 1,9 milh\u00f5es de servidores. A remunera\u00e7\u00e3o est\u00e1 atualmente em R$ 198,9 bilh\u00f5es ao ano.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Ag\u00eancia Brasil O governo federal prev\u00ea a cria\u00e7\u00e3o de 63 mil vagas para cargos p\u00fablicos em 2013. Os novos postos de trabalho est\u00e3o previstos no Projeito de Lei Or\u00e7ament\u00e1ria Anual (Ploa), que foi enviado ontem (30) ao Congresso Nacional. Segundo o Minist\u00e9rio do Planejamento, deste total, a previs\u00e3o \u00e9 que 61.682 vagas sejam preenchidas j\u00e1 no ano que vem. [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2331","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}