{"id":2329,"date":"2012-08-31T09:55:00","date_gmt":"2012-08-31T12:55:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concurso_com_298_vagas_saira_em_breve_para_o_tjam_\/"},"modified":"2012-08-31T09:55:00","modified_gmt":"2012-08-31T12:55:00","slug":"concurso_com_298_vagas_saira_em_breve_para_o_tjam_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/concurso_com_298_vagas_saira_em_breve_para_o_tjam_\/","title":{"rendered":"Concurso com 298 vagas sair\u00e1 em breve para o TJAM"},"content":{"rendered":"<p>  <b>&nbsp;<\/b>  <b>Lorena Pacheco \u2013 Do CorreioWeb <\/b>  &nbsp;  O novo concurso p\u00fablico do Tribunal de Justi\u00e7a do Amazonas (TJAM) j\u00e1 est\u00e1 encaminhado. Segundo informa\u00e7\u00f5es do \u00f3rg\u00e3o, no m\u00e1ximo at\u00e9 janeiro do ano que vem o edital de abertura dever\u00e1 ser lan\u00e7ado com oferta de 298 oportunidades para cargos de n\u00edveis m\u00e9dio e superior. A banca organizadora tamb\u00e9m j\u00e1 foi definida, ser\u00e1 a Funda\u00e7\u00e3o Get\u00falio Vargas (FGV).&nbsp;   &nbsp;  Os cargos s\u00e3o: assistente judici\u00e1rio, suporte t\u00e9cnico, oficial de justi\u00e7a e analista judici\u00e1rio. Os aprovados ser\u00e3o lotados na capital do estado e em mais sete munic\u00edpios: Manacapuru, Careiro, Careiro da V\u00e1rzea, Iranduba, Rio Preto da Eva, Itacoatiara e Presidente Figueiredo. Apenas em Manaus ser\u00e3o disponibilizadas 260 chances, sendo 170 para n\u00edvel m\u00e9dio e 90 para graduados.   &nbsp;  Outro concurso para o tribunal tamb\u00e9m j\u00e1 est\u00e1 confirmado. Desta vez ser\u00e1 para a magistratura, ser\u00e3o 35 vagas. Aguardem mais informa\u00e7\u00f5es. <i><\/i>    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lorena Pacheco \u2013 Do CorreioWeb &nbsp; O novo concurso p\u00fablico do Tribunal de Justi\u00e7a do Amazonas (TJAM) j\u00e1 est\u00e1 encaminhado. Segundo informa\u00e7\u00f5es do \u00f3rg\u00e3o, no m\u00e1ximo at\u00e9 janeiro do ano que vem o edital de abertura dever\u00e1 ser lan\u00e7ado com oferta de 298 oportunidades para cargos de n\u00edveis m\u00e9dio e superior. A banca organizadora tamb\u00e9m j\u00e1 foi definida, ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2329","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=2329"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2329\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=2329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=2329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=2329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}