{"id":2328,"date":"2012-08-30T11:17:00","date_gmt":"2012-08-30T14:17:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/rn_e_pe_poderao_ter_76_novos_cargos_em_ti\/"},"modified":"2012-08-30T11:17:00","modified_gmt":"2012-08-30T14:17:00","slug":"rn_e_pe_poderao_ter_76_novos_cargos_em_ti","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/rn_e_pe_poderao_ter_76_novos_cargos_em_ti\/","title":{"rendered":"RN e PE poder\u00e3o ter 76 novos cargos em TI"},"content":{"rendered":"<p>  &nbsp;  <i>Da Ag\u00eancia C\u00e2mara<\/i>  &nbsp;  <b>A Justi\u00e7a do Trabalho em Pernambuco e no Rio Grande do Norte poder\u00e1 ser autorizada a criar 76 cargos efetivos na \u00e1rea de tecnologia da informa\u00e7\u00e3o.<\/b> Esta possibilidade est\u00e1 sendo aberta com a aprova\u00e7\u00e3o de dois projetos de lei da C\u00e2mara (PLC <a href=\"http:\/\/www.senado.gov.br\/atividade\/materia\/detalhes.asp?p_cod_mate=106111\" target=\"_blank\">52<\/a> e <a href=\"http:\/\/www.senado.gov.br\/atividade\/materia\/detalhes.asp?p_cod_mate=106373\" target=\"_blank\">69<\/a>, de 2012), nesta quarta-feira (29), pela Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Cidadania (CCJ). Ambos seguem para vota\u00e7\u00e3o em regime de urg\u00eancia no Plen\u00e1rio do Senado.  &nbsp;  Relatado pelo senador Armando Monteiro (PTB-PE), o PLC 52\/2012 cria 57 cargos efetivos de analista judici\u00e1rio na \u00e1rea no Tribunal Regional do Trabalho (TRT) da 6\u00aa Regi\u00e3o, sediado em Recife. O parlamentar observou que a medida vem suprir car\u00eancia de servidores que atuam com tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00f5es nesse tribunal, onde h\u00e1 apenas 19 funcion\u00e1rios para atender a uma demanda estimada em 1,9 mil usu\u00e1rios internos destes servi\u00e7os.  &nbsp;  O PLC 69\/2012 tem motiva\u00e7\u00e3o semelhante e prev\u00ea 16 cargos efetivos de analista judici\u00e1rio e 03 de t\u00e9cnico judici\u00e1rio em tecnologia da informa\u00e7\u00e3o para o TRT da 21\u00aa Regi\u00e3o, com sede em Natal. Assim como o PLC 52\/2012, esse projeto segue planejamento tra\u00e7ado pelo Conselho Nacional de Justi\u00e7a (CNJ), destinado a tornar mais \u00e1gil e eficaz o andamento das a\u00e7\u00f5es trabalhistas. O senador Jos\u00e9 Agripino (DEM-RN) foi relator da mat\u00e9ria.   &nbsp;  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Da Ag\u00eancia C\u00e2mara &nbsp; A Justi\u00e7a do Trabalho em Pernambuco e no Rio Grande do Norte poder\u00e1 ser autorizada a criar 76 cargos efetivos na \u00e1rea de tecnologia da informa\u00e7\u00e3o. Esta possibilidade est\u00e1 sendo aberta com a aprova\u00e7\u00e3o de dois projetos de lei da C\u00e2mara (PLC 52 e 69, de 2012), nesta quarta-feira (29), pela Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2328","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=2328"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/2328\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=2328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}