{"id":22702,"date":"2022-01-07T14:21:59","date_gmt":"2022-01-07T17:21:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/?p=22702"},"modified":"2022-01-07T14:21:59","modified_gmt":"2022-01-07T17:21:59","slug":"bolsonaro-sanciona-lei-que-limita-tatuagens-para-ingresso-na-marinha","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/bolsonaro-sanciona-lei-que-limita-tatuagens-para-ingresso-na-marinha\/","title":{"rendered":"Bolsonaro sanciona lei que limita tatuagens para ingresso na Marinha\u00a0"},"content":{"rendered":"<h2><span style=\"font-weight: 400\">A nova lei j\u00e1 est\u00e1 em vigor e, al\u00e9m de estabelecer restri\u00e7\u00f5es ao uso de tatuagens, ainda determina o ajuste a faixa et\u00e1ria de ingresso em corpos e quadros da Marinha<\/span><\/h2>\n<p><span style=\"font-weight: 400\">J\u00e9ssica Andrade &#8211; Os concurseiros interessados em ingressar na Marinha do Brasil devem tomar cuidado na hora de escolher um desenho para eternizar na pele. Nesta quarta-feira (5\/1), o presidente da rep\u00fablica, Jair Bolsonaro, sancionou uma lei de restri\u00e7\u00f5es de tatuagens para ingresso na Marinha.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">A <\/span><a href=\"https:\/\/in.gov.br\/en\/web\/dou\/-\/lei-n-14.296-de-4-de-janeiro-de-2022-372220506#:~:text=Altera%20a%20Lei%20n%C2%BA%2011.279,restri%C3%A7%C3%B5es%20ao%20uso%20de%20tatuagem.\"><span style=\"font-weight: 400\">\u00a0Lei 14.296, de 2022<\/span><\/a><span style=\"font-weight: 400\"> pro\u00edbe a entrada de servidores na institui\u00e7\u00e3o com tatuagens que fa\u00e7am alus\u00e3o a &#8220;ideologia terrorista ou extremista contr\u00e1ria \u00e0s institui\u00e7\u00f5es democr\u00e1ticas&#8221;, ou a viol\u00eancia, criminalidade, ato libidinoso, discrimina\u00e7\u00e3o e preconceito de ra\u00e7a, sexo ou credo. A nova lei tamb\u00e9m pro\u00edbe tatuagens na cabe\u00e7a, no rosto ou na parte da frente do pesco\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Em dezembro, quando o projeto proposto pelo governo ( <\/span><a href=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/150535\"><span style=\"font-weight: 400\">PL 5.010\/2020<\/span><\/a><span style=\"font-weight: 400\">) passou pelo Senado, o relator, Marcos do Val (Podemos-ES), disse que a proibi\u00e7\u00e3o de tatuagens se baseia em decis\u00e3o recente do Supremo Tribunal Federal (STF).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Segundo o senador, o PL 5010\/2020 se enquadra na defini\u00e7\u00e3o do STF de que editais de concursos p\u00fablicos n\u00e3o podem determinar restri\u00e7\u00f5es a pessoas com tatuagens, &#8220;salvo em situa\u00e7\u00f5es excepcionais em raz\u00e3o de conte\u00fado que viole valores&#8221;.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cO que se busca \u00e9 a seguran\u00e7a dos militares e das opera\u00e7\u00f5es, n\u00e3o h\u00e1 qualquer pol\u00eamica no que tange \u00e0 liberdade de express\u00e3o. E al\u00e9m disso os militares devem primar pela boa apresenta\u00e7\u00e3o pessoal\u201d, disse o relator em Plen\u00e1rio.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A nova legisla\u00e7\u00e3o, que altera a Lei n\u00ba 11.279, de 9 de fevereiro de 2006, tamb\u00e9m inclui no Sistema de Ensino Naval (SEN) cursos para pra\u00e7as, de gradua\u00e7\u00e3o, de qualifica\u00e7\u00e3o t\u00e9cnica especial e de aperfei\u00e7oamento avan\u00e7ado.\u00a0 e reduz o limite de idade para ingresso no corpo de sa\u00fade, no corpo de engenheiros e no quadro t\u00e9cnico do corpo auxiliar da Marinha de 36 para 35 anos. A norma prev\u00ea ainda que os cursos e est\u00e1gios a dist\u00e2ncia s\u00e3o equivalentes aos presenciais.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nova lei j\u00e1 est\u00e1 em vigor e, al\u00e9m de estabelecer restri\u00e7\u00f5es ao uso de tatuagens, ainda determina o ajuste a faixa et\u00e1ria de ingresso em corpos e quadros da Marinha J\u00e9ssica Andrade &#8211; Os concurseiros interessados em ingressar na Marinha do Brasil devem tomar cuidado na hora de escolher um desenho para eternizar na pele. Nesta quarta-feira (5\/1), o [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":22703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[282],"tags":[],"class_list":["post-22702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/comments?post=22702"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22702\/revisions"}],"predecessor-version":[{"id":22707,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/posts\/22702\/revisions\/22707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media\/22703"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/media?parent=22702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/categories?post=22702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/papodeconcurseiro\/wp-json\/wp\/v2\/tags?post=22702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}